{"id":767509,"date":"2015-06-11T11:02:54","date_gmt":"2015-06-11T09:02:54","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/das-landwirtschaftsministerium-fordert-eine-untersuchung-der-verschmutzung-der-illatos-road\/"},"modified":"2015-06-11T11:02:54","modified_gmt":"2015-06-11T09:02:54","slug":"das-landwirtschaftsministerium-fordert-eine-untersuchung-der-verschmutzung-der-illatos-road","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/das-landwirtschaftsministerium-fordert-eine-untersuchung-der-verschmutzung-der-illatos-road\/","title":{"rendered":"Das Landwirtschaftsministerium fordert eine Untersuchung der Verschmutzung der Illatos Road"},"content":{"rendered":"<p><strong>Budapest (MTI) \u2013 Das Landwirtschaftsministerium hat eine gr\u00fcndliche Untersuchung der Umweltverschmutzung in einem Depot an der Illatos-Stra\u00dfe im 9. Bezirk von Budapest gefordert, um die Quelle der erstmals im April dieses Jahres gemeldeten Kontamination aufzudecken.<\/strong><\/p>\n<p>Das Ministerium teilte MTI mit, dass mit der Bewertung der Sch\u00e4den und der Kontrolle der Umweltsch\u00e4den erst begonnen werden k\u00f6nne, wenn die gef\u00e4hrlichen Abf\u00e4lle vom Standort entfernt worden seien, und f\u00fcgte hinzu, dass Schlussfolgerungen erst nach Abschluss der Untersuchung gezogen werden k\u00f6nnten.<\/p>\n<p>Das Ministerium sagte, die Umweltverschmutzung k\u00f6nne durch unsachgem\u00e4\u00dfe chemische Verwendung oder illegal gewonnenes Futter durch die 1993 privatisierten ehemaligen staatlichen Chemiefabriken verursacht worden sein.<\/p>\n<p>Das Ministerium stellte fest, dass die 1.005 F\u00e4sser mit den gef\u00e4hrlichsten Abf\u00e4llen bis zum 31. Mai vom Gel\u00e4nde entfernt wurden.<\/p>\n<h6>LMP<\/h6>\n<p>Die gr\u00fcne Opposition LMP sagte, sie werde rechtliche Schritte einleiten, um eine Liste von Umweltrisiken zu erhalten, die der an der Illatos Road \u00e4hnelt. Die Partei sagte, sie wolle auch wissen, welche Art von Schadensbegrenzung durchgef\u00fchrt werde, um die Risiken zu verringern. Der Gesetzgeber Benedek R. Sallai sagte, die Illatos Road sei \u201eaber der Tipp, wenn der Eisberg\u201cund f\u00fcgte hinzu, dass es in Ungarn zahlreiche \u00e4hnliche \u201eTicking-Time-Bomben\u201d gebe.<\/p>\n<h6>Jobbik<\/h6>\n<p>Die radikal-nationalistische Jobbik-Partei sagte, sie werde die Einrichtung eines parlamentarischen Untersuchungsausschusses einleiten, um die Umweltausgaben der Regierung zu untersuchen. Der Gesetzgeber Lajos Kepli sagte, es gebe eine Reihe verschmutzter Standorte wie das Depot Illatos Road in Ungarn, was seiner Meinung nach darauf hindeutet, dass die f\u00fcr die Kontrolle von Umweltsch\u00e4den bereitgestellten \u00f6ffentlichen Mittel nicht ordnungsgem\u00e4\u00df ausgegeben w\u00fcrden.<\/p>\n<p>Im April stellte die Regierung mehr als 1 Milliarde Forint (3,3 Mio. EUR) bereit, um Budapest bei der Organisation der Entsorgung gef\u00e4hrlicher Abf\u00e4lle im Depot zu unterst\u00fctzen.<\/p>\n<p><em>Foto: MTI<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest (MTI) \u2013 Das Landwirtschaftsministerium hat eine gr\u00fcndliche Untersuchung der Umweltverschmutzung in einem Depot an der Illatos-Stra\u00dfe im 9. Bezirk von Budapest gefordert, um die Quelle der erstmals im April dieses Jahres gemeldeten Kontamination aufzudecken. Das Ministerium teilte MTI mit, dass mit der Bewertung der Sch\u00e4den und der Kontrolle der Umweltsch\u00e4den erst begonnen werden k\u00f6nne, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":767510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1107,1489,1236],"class_list":["post-767509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-gesundheit","tag-industrie","tag-polizei"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=767509"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/767510"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=767509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=767509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=767509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}