{"id":767619,"date":"2015-06-06T14:22:58","date_gmt":"2015-06-06T12:22:58","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/wirtschaftsforum-agypten-ungarn-neues-kapitel-in-den-ungarisch-agyptischen-beziehungen-ist-eroffnet\/"},"modified":"2015-06-06T14:22:58","modified_gmt":"2015-06-06T12:22:58","slug":"wirtschaftsforum-agypten-ungarn-neues-kapitel-in-den-ungarisch-agyptischen-beziehungen-ist-eroffnet","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/wirtschaftsforum-agypten-ungarn-neues-kapitel-in-den-ungarisch-agyptischen-beziehungen-ist-eroffnet\/","title":{"rendered":"Wirtschaftsforum \u00c4gypten-Ungarn: Neues Kapitel in den ungarisch-\u00e4gyptischen Beziehungen ist er\u00f6ffnet"},"content":{"rendered":"<p><strong>Budapest (MTI) \u2013 Ein neues Kapitel in den ungarisch-\u00e4gyptischen Beziehungen sei aufgeschlagen, sagte Premierminister Viktor Orban nach Gespr\u00e4chen mit Abdul Fattah al-Sisi, dem \u00e4gyptischen Pr\u00e4sidenten, am Freitag in Budapest.<\/strong><\/p>\n<p>Orban sagte, ein Abkommen, das die beiden Staats- und Regierungschefs gerade unterzeichnet h\u00e4tten, w\u00fcrde den wirtschaftlichen und politischen Beziehungen der beiden L\u00e4nder Dynamik verleihen.<\/p>\n<p>Auf einer gemeinsamen Pressekonferenz sagte Orban, dass das wirtschaftliche Verbindungsnetzwerk zwischen \u00c4gypten und Ungarn alle Arten politischer Regime \u00fcberlebt habe und dass Ungarns Pr\u00e4senz im Land \u201eschon immer stark gewesen sei\u201cf\u00fcgte er hinzu und erw\u00e4hnte insbesondere die milit\u00e4rische Zusammenarbeit.<\/p>\n<p>Einhundert Stipendien seien f\u00fcr \u00e4gyptische Studenten eingerichtet worden, sagte er. Das \u00e4gyptische Fernsehen und Radio h\u00e4tten eine Zusammenarbeit mit ungarischen \u00f6ffentlich-rechtlichen Medien gekn\u00fcpft, f\u00fcgte er hinzu.<\/p>\n<p>Der Premierminister sagte, dass es an vielen Orten in Europa eine Angst vor dem Islam gebe, und sogar eine Abneigung dagegen Ungarn sei kein solches Land, sagte er und f\u00fcgte hinzu, dass in Ungarn der Islam als eine der gro\u00dfen intellektuellen und spirituellen Sch\u00f6pfungen der Menschheit angesehen werde.<\/p>\n<p>\u201cWir m\u00fcssen mit einer Stimme des Respekts \u00fcber den Islam sprechen\u201d, sagte Orban und f\u00fcgte hinzu, dass Ungarn an kulturelle Vielfalt glaube. Gleichzeitig ist es nicht sicher, dass soziale und organisatorische Methoden, die in der westlichen Welt \u00fcbernommen wurden, immer erfolgreich sind und von anderen Zivilisationen \u00fcbernommen werden sollten.<\/p>\n<p>\u201cWir sind keine Lehrer der Demokratie; Entscheidungen m\u00fcssen von jeder Nation getroffen werden, was ihre eigenen Angelegenheiten betrifft\u201d, sagte er und w\u00fcnschte dem \u00e4gyptischen Volk viel Gl\u00fcck, \u201cden eigenen Weg zu gehen\u201d.<\/p>\n<p>\u00c4gypten sei ein besonderes Land, ohne das es weder im arabischen Raum noch in Europa Stabilit\u00e4t gebe, sagte Orban.<\/p>\n<p>Der \u00e4gyptische Pr\u00e4sident habe Ungarn aufgefordert, sich an den Entwicklungen seines Landes zu beteiligen, und es aufgefordert, sich in der Europ\u00e4ischen Union daf\u00fcr einzusetzen, sagte er in einer Erkl\u00e4rungEr forderte eine St\u00e4rkung der Industrie &#8211; und Handelsbeziehungen zwischen ihren L\u00e4ndern.<\/p>\n<p>Pr\u00e4sident al-Sisi nannte die Gespr\u00e4che in Budapest \u201cfruchtbar\u201d und stellte fest, dass die ungarisch-\u00e4gyptischen Beziehungen schon lange nahtlos gewesen seienEr dankte den ungarischen Soldaten f\u00fcr ihren zwanzigj\u00e4hrigen Dienst auf der Sinai-Halbinsel.<\/p>\n<p>Al-Sisi sagte, er und Orban h\u00e4tten sich mit der Position \u00c4gyptens zum Kampf gegen den Terrorismus, zu M\u00f6glichkeiten der Konfliktl\u00f6sung in Libyen und zum Syrien-Irak-Konflikt befasst.<\/p>\n<p>\u201cEinigheit zwischen unseren L\u00e4ndern zeigte sich in unseren Gespr\u00e4chen\u201d, sagte er.<\/p>\n<p>Vor ihrem Treffen unterzeichneten Orban und al-Sisi eine gemeinsame Erkl\u00e4rung und zwei weitere Kooperationspakte waren zuvor von den beiden L\u00e4ndern unterzeichnet worden, au\u00dferdem unterzeichneten sie eine Absichtserkl\u00e4rung f\u00fcr \u00c4gyptens Bestellung von 700 ungarischen Eisenbahnwaggons sowie eine Vereinbarungserkl\u00e4rung \u00fcber die Zusammenarbeit zwischen ihren Innenministerien.<\/p>\n<p>In einer Rede auf einem vom Ungarischen Nationalen Handelshaus sp\u00e4ter am Tag organisierten Wirtschaftsforum sagte Orban, Ungarn sei an einem Erfolg \u00c4gyptens interessiert.<\/p>\n<p>Pr\u00e4sident Al-Sisi sagte dem Forum, dass \u00c4gypten nach vier Jahren der Instabilit\u00e4t den Weg des Wachstums eingeschlagen habeEr bat ungarische Unternehmen und Investoren, zu dem Prozess beizutragen.<\/p>\n<p>Au\u00dfenminister Peter Szijjarto sagte, der institutionelle Hintergrund sei vorhanden, um die ungarisch-\u00e4gyptischen Gesch\u00e4fts &#8211; und Handelsbeziehungen auf eine neue Ebene zu heben Ungarn habe im vergangenen Jahr ein Handelshaus in \u00c4gypten er\u00f6ffnet, in dessen Folge die ungarischen Exporte nach \u00c4gypten im Januar-M\u00e4rz dieses Jahres um 88,3 Prozent sprunghaft angestiegen seien, sagte SzijjartoDer bilaterale Handel zwischen ihren L\u00e4ndern sei im vergangenen Jahr um 67,6 Prozent gestiegen, f\u00fcgte er hinzu.<\/p>\n<p>Ashraf Salman, \u00c4gyptens Investitionsminister, sagte dem Forum, dass sein Land die Wirtschaft auf drei S\u00e4ulen aufbaue und dass \u00c4gypten seine Freihandelsbeziehungen ausbaue und seine Verbraucherm\u00e4rkte wuchsen.<\/p>\n<p><em>Foto: MTI<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest (MTI) \u2013 Ein neues Kapitel in den ungarisch-\u00e4gyptischen Beziehungen sei aufgeschlagen, sagte Premierminister Viktor Orban nach Gespr\u00e4chen mit Abdul Fattah al-Sisi, dem \u00e4gyptischen Pr\u00e4sidenten, am Freitag in Budapest. Orban sagte, ein Abkommen, das die beiden Staats- und Regierungschefs gerade unterzeichnet h\u00e4tten, w\u00fcrde den wirtschaftlichen und politischen Beziehungen der beiden L\u00e4nder Dynamik verleihen. Auf einer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":767620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1155,1128],"class_list":["post-767619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-afrika","tag-viktor-orban"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=767619"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/767620"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=767619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=767619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=767619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}