{"id":767747,"date":"2015-05-30T16:51:04","date_gmt":"2015-05-30T14:51:04","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/die-parteien-reichen-anderungen-zum-haushaltsentwurf-ein\/"},"modified":"2015-05-30T16:51:04","modified_gmt":"2015-05-30T14:51:04","slug":"die-parteien-reichen-anderungen-zum-haushaltsentwurf-ein","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/die-parteien-reichen-anderungen-zum-haushaltsentwurf-ein\/","title":{"rendered":"Die Parteien reichen \u00c4nderungen zum Haushaltsentwurf ein"},"content":{"rendered":"<p><strong>Budapest (MTI) \u2013 Bis zum Freitagstermin wurden mehr als 500 \u00c4nderungsvorschl\u00e4ge zum Haushalt 2016 eingereicht, die meisten davon von Oppositionsparteien.<\/strong><\/p>\n<p>Lajos Kosa (Fidesz) schlug vor, im Zusammenhang mit den Wassersport-Weltmeisterschaften, die Budapest 2017 ausrichtet, 1,5 Milliarden Forint (4,85 Mio. EUR) zur Finanzierung nationaler Sportzentren hinzuzuf\u00fcgen.<\/p>\n<p>Kabinettschef Janos Lazar schlug vor, 300 Millionen Forint mehr f\u00fcr die Ungarische Nationalgalerie und 1 Milliarde Forint mehr f\u00fcr die Budapester Operette und das Musiktheater auszugeben. Er schlug au\u00dferdem vor, die Mittel zugunsten des Projekts Liget Budapest, insbesondere des Museums der Sch\u00f6nen K\u00fcnste, des Ethnologischen Museums und des Technik- und Verkehrsmuseums, neu zu b\u00fcndeln.<\/p>\n<p>Peter Harrach (KDNP) w\u00fcrde 300 Millionen Forint mehr f\u00fcr kirchliche Gesundheitseinrichtungen und 80 Millionen Forint f\u00fcr die Programme des Aron Marton Memorial Year ausgeben.<\/p>\n<p>Die Fidesz-Abgeordneten Robert Balazs Simon und Akos Kara schlugen im Zusammenhang mit dem Europ\u00e4ischen Olympischen Jugendfestival 2017 in der Stadt ein Budget von 4,9 Milliarden Forint f\u00fcr Sportanlagen in Gyor im Nordwesten Ungarns vor.<\/p>\n<p>Die gesamte sozialistische Fraktion stand hinter einem Vorschlag, 285 Milliarden Forint f\u00fcr Lohnerh\u00f6hungen f\u00fcr Sozialarbeiter, darunter Lehrer und Gesundheitspersonal, bereitzustellen.<\/p>\n<p>Ein weiterer von den Sozialisten gef\u00f6rderter Gesetzentwurf w\u00fcrde 64 Milliarden Forint f\u00fcr Lohnerh\u00f6hungen in der Hochschulbildung und die Finanzierung der Ungarischen Akademie der Wissenschaften neu b\u00fcndeln. Gem\u00e4\u00df diesem Gesetzentwurf w\u00fcrden weitere 250 Milliarden Forint in f\u00fcrsorgerische Ausgaben flie\u00dfen, darunter Familienbeihilfen sowie Leistungen bei Invalidit\u00e4t und Rehabilitation.<\/p>\n<p>Ein sozialistischer Gesetzentwurf w\u00fcrde 35 Milliarden f\u00fcr staatlich gef\u00f6rderte Mietwohnungen und 50 Milliarden f\u00fcr den Bau der Autobahn M4 ausgeben.<\/p>\n<p>Unter Hunderten von Gesetzentw\u00fcrfen, die von der radikal-nationalistischen Jobbik-Partei eingereicht wurden, zielte einer darauf ab, 96 Milliarden Forint aus dem Nothaushalt des B\u00fcros des Premierministers zu verschieben, um Wohnbauf\u00f6rderprogramme zu finanzieren. In einem anderen Gesetzentwurf wurde vorgeschlagen, die Lohnausgaben bei der staatlichen Agentur f\u00fcr Schulen (Klik) um 35 Milliarden Forint und an Hochschuleinrichtungen um 20 Milliarden Forint zu erh\u00f6hen.<\/p>\n<p>Ein weiterer von Jobbik gef\u00f6rderter Gesetzentwurf w\u00fcrde 3 Milliarden Forint f\u00fcr die Unterst\u00fctzung von In-vitro-Fertilisationsprogrammen ausgeben.<\/p>\n<p>Die kleine Oppositionspartei LMP schlug vor, die Unterst\u00fctzung f\u00fcr die Hochschulbildung um 15 Milliarden Forint zu erh\u00f6hen und dort zus\u00e4tzlich 10 Milliarden Forint f\u00fcr Gehaltserh\u00f6hungen des Personals zu erhalten. Weitere 12 Milliarden Forint w\u00fcrden in Schulen in benachteiligten Regionen und 2,3 Milliarden Forint in Nationalparks flie\u00dfen, um die landgest\u00fctzten Subventionen zu entsch\u00e4digen, die sie verloren haben, hei\u00dft es in dem von LMP vorgelegten Gesetzentwurf.<\/p>\n<p>Wirtschaftsminister Mihaly Varga legte dem Parlament am 13. Mai den Haushaltsentwurf 2016 vor, in dem er zusagte, im n\u00e4chsten Jahr 170 Milliarden Forint mehr bei den Haushalten zu belassenDer Haushalt sieht Einnahmen von 15.790 Milliarden Forint, Ausgaben von 16.551 Milliarden Forint und ein Defizit von 761,6 Milliarden Forint oder etwa 2 Prozent des BIP vor.<\/p>\n<p><em>Foto: MTI<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest (MTI) \u2013 Bis zum Freitagstermin wurden mehr als 500 \u00c4nderungsvorschl\u00e4ge zum Haushalt 2016 eingereicht, die meisten davon von Oppositionsparteien. Lajos Kosa (Fidesz) schlug vor, im Zusammenhang mit den Wassersport-Weltmeisterschaften, die Budapest 2017 ausrichtet, 1,5 Milliarden Forint (4,85 Mio. EUR) zur Finanzierung nationaler Sportzentren hinzuzuf\u00fcgen. Kabinettschef Janos Lazar schlug vor, 300 Millionen Forint mehr f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":767748,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1104],"class_list":["post-767747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=767747"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/767748"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=767747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=767747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=767747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}