{"id":767845,"date":"2015-05-26T16:00:45","date_gmt":"2015-05-26T14:00:45","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/47-kekszalag-europas-groste-regatta-am-plattensee\/"},"modified":"2015-05-26T16:00:45","modified_gmt":"2015-05-26T14:00:45","slug":"47-kekszalag-europas-groste-regatta-am-plattensee","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/47-kekszalag-europas-groste-regatta-am-plattensee\/","title":{"rendered":"47. K\u00e9kszalag \u2013 Europas gr\u00f6\u00dfte Regatta am Plattensee"},"content":{"rendered":"<p><strong>In weniger als 37 Tagen wird am Plattensee der 47. K\u00e9kszalag (Blaues Band) \u00c1rk\u00e1d Grand Prix organisiert, in diesem Jahr werden vom 2. bis 4. Juli mehr als 600 Segelboote auf Europas gr\u00f6\u00dfter internationaler Langstreckenregatta antreten, berichtete vjm.hu.<\/strong><\/p>\n<p>Die Route des Fernrennens ist: Balatonf\u00fcred (Start) (Balatonkenese si\u00f3fok tithany Strait (Keszthely tithany Strait (Endstation) Die Entfernung (gemessen in beeline) betr\u00e4gt ca. 150 km.<\/p>\n<p>Urspr\u00fcnglich bestand das Ziel des K\u00e9kszalag darin, einen Segelwettbewerb zu starten, an dem alle Bootsklassen teilnehmen k\u00f6nnen, und dabei nicht nur die Arbeit der Konstrukteure, sondern auch das Navigationswissen, die Z\u00e4higkeit und die Eignung der betroffenen Segler zu testen. Mittlerweile ist die Regatta jedoch Europas \u00e4lteste, l\u00e4ngste und gr\u00f6\u00dfte internationale Langstreckenregatta und zieht jedes Jahr immer mehr Teilnehmer und Zuschauer an.<\/p>\n<p>Nach dem Abriss von Beschr\u00e4nkungen, die die Regatta in den letzten Jahrzehnten beeinflusst haben, d\u00fcrfen Segelboote jeder Art am Wettbewerb teilnehmen, was es zu einem offenen Rennen f\u00fcr Teilnehmer macht, die den Anforderungen des Ungarischen Yachtverbandes entsprechen Die Teilnehmer des K\u00e9kszalag sind von Jahr zu Jahr gewachsen und reichen von professionellen Seglern, einschlie\u00dflich Weltmeistern, bis hin zu weniger erfahrenen Seglern, die \u00fcber den See fegen und gegeneinander und gegen die Elemente antreten.<\/p>\n<p>Den aktuellen Rekord des K\u00e9kszalag stellte 2014 der 50 Fu\u00df lange Zwillingsmastkatamaran namens Fifty-Fifty auf, indem er die 150 km lange Strecke in 7 Stunden und 13 Minuten absolvierte, mit Windgeschwindigkeiten von 10 Knoten erreichte der Fifty-Fifty Geschwindigkeiten von 24 Knoten.<\/p>\n<p>Abgesehen von der Konkurrenz auf dem Wasser bietet das Kekszalag Festival auch Programme an, die f\u00fcr die Besucher an Land in Balatonf\u00fcred interessant sein k\u00f6nnen.<\/p>\n<p>Die Preisverleihung soll am 4. Juli um 6 Uhr auf der Kisfaludy-B\u00fchne unter freiem Himmel am Eingang des Balatonf\u00fcred-Hafens stattfinden.<\/p>\n<p><em>basierend auf dem Artikel von vjm.hu<\/em><br \/>\n<em>\u00dcbersetzung von G\u00e1bor Hajnal<\/em><\/p>\n<p><em>Foto: MTI<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In weniger als 37 Tagen wird am Plattensee der 47. K\u00e9kszalag (Blaues Band) \u00c1rk\u00e1d Grand Prix organisiert, in diesem Jahr werden vom 2. bis 4. Juli mehr als 600 Segelboote auf Europas gr\u00f6\u00dfter internationaler Langstreckenregatta antreten, berichtete vjm.hu. Die Route des Fernrennens ist: Balatonf\u00fcred (Start) (Balatonkenese si\u00f3fok tithany Strait (Keszthely tithany Strait (Endstation) Die Entfernung [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":767846,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":""},"categories":[1219],"tags":[1289],"class_list":["post-767845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-balaton"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1219","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=767845"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/767846"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=767845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=767845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=767845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}