{"id":767891,"date":"2015-05-23T16:02:02","date_gmt":"2015-05-23T14:02:02","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/fitch-bekraftigt-ungarns-junk-rating-und-erhoht-die-aussichten-auf-positiv\/"},"modified":"2015-05-23T16:02:02","modified_gmt":"2015-05-23T14:02:02","slug":"fitch-bekraftigt-ungarns-junk-rating-und-erhoht-die-aussichten-auf-positiv","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/fitch-bekraftigt-ungarns-junk-rating-und-erhoht-die-aussichten-auf-positiv\/","title":{"rendered":"Fitch bekr\u00e4ftigt Ungarns Junk-Rating und erh\u00f6ht die Aussichten auf positiv"},"content":{"rendered":"<p><strong>Budapest, 23. Mai (MTI) \u201eAktuelle Ratings\u201cbekr\u00e4ftigte in einer geplanten \u00dcberpr\u00fcfung am Freitagabend Ungarns \u201eBB plus\u201d-Staatskreditw\u00fcrdigkeit, eine Stufe unter Investment Grade.<\/strong><\/p>\n<p>Gleichzeitig hob Fitch Ungarns Ausblick von \u201cstabil\u201d auf \u201cpositiv\u201d<\/p>\n<p>W\u00e4hrend die ungarischen Beh\u00f6rden eine Modernisierung des Landes erwarten, wird der Schritt den lokalen Markt nicht \u00fcberraschen, wenn er n\u00e4chsten Dienstag nach den Pfingstfeiertagen wiederer\u00f6ffnet wird, da Analysten von Fitch in einem Interview mit Reuters Ende April sagten, eine Verbesserung sei unwahrscheinlich.<\/p>\n<p>Nach der Ver\u00f6ffentlichung der Rezension von Fitch Rating stieg der ungarische Forint von 307,68 auf dem Interbanken-Forex-Markt auf 306,87 pro Euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 23. Mai (MTI) \u201eAktuelle Ratings\u201cbekr\u00e4ftigte in einer geplanten \u00dcberpr\u00fcfung am Freitagabend Ungarns \u201eBB plus\u201d-Staatskreditw\u00fcrdigkeit, eine Stufe unter Investment Grade. Gleichzeitig hob Fitch Ungarns Ausblick von \u201cstabil\u201d auf \u201cpositiv\u201d W\u00e4hrend die ungarischen Beh\u00f6rden eine Modernisierung des Landes erwarten, wird der Schritt den lokalen Markt nicht \u00fcberraschen, wenn er n\u00e4chsten Dienstag nach den Pfingstfeiertagen wiederer\u00f6ffnet wird, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":767892,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1104],"class_list":["post-767891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"becsi","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=767891"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/767891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/767892"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=767891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=767891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=767891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}