{"id":768374,"date":"2015-04-25T10:00:13","date_gmt":"2015-04-25T08:00:13","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/besitzer-von-overdose-festgenommen\/"},"modified":"2015-04-25T10:00:13","modified_gmt":"2015-04-25T08:00:13","slug":"besitzer-von-overdose-festgenommen","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/besitzer-von-overdose-festgenommen\/","title":{"rendered":"Besitzer von Overdose festgenommen"},"content":{"rendered":"<p><strong>In der Mitteilung Die Nationale Steuer &#8211; und Zollverwaltung (NAV) sagte, eine kriminelle Organisation, die mit Zucker handelt, sei k\u00fcrzlich liquidiert worden, was 1,2 Milliarden HUF Mehrwertsteuer hinterzogen habe Einer dieser Steuerbetr\u00fcger ist Zoltan Mikoczy aus der Slowakei, der Besitzer von Overdose (ein ber\u00fchmtes ungarisches Rennpferd) ist und der von der Polizei in Gewahrsam genommen wurde, sagte nol.hu.<\/strong><\/p>\n<p>Zoltan Mikoczy wird des Mehrwertsteuerbetrugs verd\u00e4chtigt, der in einer kriminellen Organisation begangen wurde, sagte \u201ehvg.hu. Der Besitzer von Overdose, der auch als ungarisches Wunderpferd bekannt ist, konnte vor langer Zeit mit seinen Freunden die Mehrwertsteuer durch Zucker betr\u00fcgen.<\/p>\n<p>Nach Angaben von nol.hu haben Finanzinspektoren der NAV k\u00fcrzlich eine kriminelle Organisation, die mit Zucker handelte, liquidiert, wodurch sich 1,2 Mrd. HUF Mehrwertsteuer entzogen hat. M\u00e4nner aus Kiskoros und Akaszto werden verd\u00e4chtigt, die Organisation zu leiten, die im Auftrag fiktiver ungarischer Unternehmen aus der Slowakei, Polen und der Tschechischen Republik Kristallzucker erwarb. Diese Waren wurden \u00fcber ein Netzwerk ungarischer Unternehmen gef\u00fchrt und mit fiktiven Rechnungen an die inl\u00e4ndischen Kunden verkauft. Auch diese Kunden profitierten davon.<\/p>\n<p>In der NAV-Mitteilung wurde auch erw\u00e4hnt, dass zwei slowakische Staatsangeh\u00f6rige in Haft seien HVG fand heraus, dass einer von ihnen Zoltan Mikoczy ist Einheimische sagten der Zeitung, er sei am 14. April Dienstag von NAV-Leuten aus einem Hotel in Kiskoros gebracht worden.<\/p>\n<p>Das Bezirksgericht Kecskemet best\u00e4tigte, dass Mikoczy einer der Verd\u00e4chtigen war und er sich in Haft befand. Wenn er und seine 10 Freunde des Mehrwertsteuerbetrugs f\u00fcr schuldig befunden werden, k\u00f6nnen sie auch eine Gef\u00e4ngnisstrafe von 5-10 Jahren erhalten.<\/p>\n<p>Es ist nicht das erste Mal, dass Mikoczy Probleme mit den Beh\u00f6rden hat 2009 stand der Eigent\u00fcmer von Overdose vor dem rum\u00e4nischen Gericht wegen F\u00e4lschung, Unterschlagung und Konkursverbrechen Zoltan Mikoczy und sein ungarischer Gesch\u00e4ftspartner betrieben eine Fleischfabrik in Partium, Rum\u00e4nien, dagegen wurde ein Konkursverfahren eingeleitet, laut Polizei Nagyvarad\/Oradea wollen sie ihre Maschinen ihres Unternehmens in Liquidation mit gesch\u00e4tzten 43 Mio. HUF (700 Tsd. RON) von den rum\u00e4nischen Kreditgebern weglocken, so nol.hu.<\/p>\n<p>Das Tribunal Nagyvarad\/Oradea verurteilte Mikoczy zu einem Jahr sieben Monaten zu einem Jahr Haft, verb\u00fc\u00dfte seine Lebensgef\u00e4hrtin zwei Jahre zwei Monate Haft, Danach wollten die Beh\u00f6rden beide aus Rum\u00e4nien ausweisen, sie protestierten gegen das Urteil erster Instanz und beantragten ihre Freilassung, schlie\u00dflich gab die Berufungsverhandlung 2009 dem Antrag statt und lie\u00df sie frei.<\/p>\n<p><em>basierend auf dem Artikel von nol.hu<br \/>\n\u00dcbersetzt von B.A<\/em><\/p>\n<p><em>Foto: <span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"https:\/\/www.facebook.com\/pages\/Overdose\/39936848399?sk=photos_stream&amp;tab=photos\" target=\"_blank\" rel=\"noopener\">Facebook-Seite mit \u00dcberdosierung<\/a><\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der Mitteilung Die Nationale Steuer &#8211; und Zollverwaltung (NAV) sagte, eine kriminelle Organisation, die mit Zucker handelt, sei k\u00fcrzlich liquidiert worden, was 1,2 Milliarden HUF Mehrwertsteuer hinterzogen habe Einer dieser Steuerbetr\u00fcger ist Zoltan Mikoczy aus der Slowakei, der Besitzer von Overdose (ein ber\u00fchmtes ungarisches Rennpferd) ist und der von der Polizei in Gewahrsam genommen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":768375,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1066],"class_list":["post-768374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-hungary"],"blocksy_meta":[],"acf":[],"author_username":"becsi","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=768374"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/768375"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=768374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=768374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=768374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}