{"id":768555,"date":"2015-04-14T12:00:14","date_gmt":"2015-04-14T10:00:14","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/industrieimmobilien-zur-miete-rund-um-budapest\/"},"modified":"2015-04-14T12:00:14","modified_gmt":"2015-04-14T10:00:14","slug":"industrieimmobilien-zur-miete-rund-um-budapest","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/industrieimmobilien-zur-miete-rund-um-budapest\/","title":{"rendered":"Industrieimmobilien zur Miete rund um Budapest"},"content":{"rendered":"<p><strong>Laut Portfolio.hu \u00fcbertrifft die Agglomeration Budapest auf dem Markt f\u00fcr gewerbliche Immobilien, w\u00e4hrend letzterer nur der drittgr\u00f6\u00dfte des Landes ist, ist der Markt f\u00fcr gewerbliche Immobilien rund um Budapest mit seinem Anteil von 40% unbestreitbar der wichtigste Lagerstandort in Ungarn.<\/strong><\/p>\n<p>Das Kapital hat eine wichtige Rolle auf dem ungarischen Immobilienmarkt Die 85% des Bestandes an gewerblichem Eigentum konzentrieren sich auf Budapest und seine Umgebung; innerhalb dieses ist das gr\u00f6\u00dfte Gebiet die Agglomeration, wo mehr als 40% des gesamten ungarischen Bestandes an gewerblichem Eigentum zu finden sind.<\/p>\n<p><strong>Der gr\u00f6\u00dfte Markt<\/strong><\/p>\n<p>In der Agglomeration gibt es ein mehr als 2,4 Millionen Quadratmeter gro\u00dfes modernes Industriegebiet, das ist dreimal mehr als in der Hauptstadt, etwa 55% der Fl\u00e4chen sind das Ergebnis spekulativer Entwicklungen, w\u00e4hrend der Rest gr\u00f6\u00dftenteils in Privatbesitz ist.<\/p>\n<p>Geografisch gliedert sich die Agglomeration als Zentrum des gewerblichen Eigentumsgebiets in drei Teile, den n\u00f6rdlichen, s\u00fcdlichen und westlichen Teilmarkt, Die gr\u00f6\u00dfte geografische Konzentration findet sich im S\u00fcdsektor der Autobahn M0 und dem Knotenpunkt M0-M1-M7. Der gr\u00f6\u00dfte Teilmarkt ist also der s\u00fcdliche, wo mehr als die H\u00e4lfte des Mietbestands vorhanden ist Dieser Anteil betr\u00e4gt im Norden nur 11%.<\/p>\n<p><strong>Leerstand bleibt hoch<\/strong><\/p>\n<p>61 Prozent des aktuellen industriellen Agglomerationswohnungsbestandes wurden zwischen 2005 und 2010 errichtet, was wegen der Wirtschaftskrise zu einer erheblichen \u00dcberbauung f\u00fchrte, die Leerstandsquote hat 20% \u00fcberschritten und stand lange Zeit auf \u00e4hnlich hohem Niveau, kein Wunder, dass das Entwicklungsvolumen in den letzten 4 Jahren deutlich abgenommen hat, nur 130 Tausend Quadratmeter neue Fl\u00e4che wurden fertiggestellt, derzeit stehen 377 600 Quadratmeter leerstehende Geb\u00e4ude, die durchschnittliche Leerstandsquote liegt derzeit bei 16% in der Agglomeration Budapest, mehrere H\u00e4user, die bisher von ihren Eigent\u00fcmern genutzt wurden, stehen leer, was die erhebliche Gr\u00f6\u00dfe der Tausendquadratten ergibt, ist D.<\/p>\n<p><strong>Gr\u00f6\u00dfter Park<\/strong><\/p>\n<p>Prologis Park Budapest-Gyal findet sich im s\u00fcdlichen Teil der Agglomeration, an der Kreuzung der Autobahn M5 und des Ringes M0. Im Park befinden sich 8 Geb\u00e4ude, mit mehr als 150 Tausend Quadratmetern B\u00fcros und Lager, unter den Mietern befinden sich Iron Mountain, GE, Cargo Partner, Sauflon, Geodis Calberson, Nagel Hungaria und DieboldDer Park ist derzeit vollst\u00e4ndig verpachtet.<\/p>\n<p><a href=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2015\/04\/d16334_prologis_park_budapest_gyal_raktar.jpg\" data-pswp-width=\"\" data-pswp-height=\"\" data-cropped=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-16213 aligncenter\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2015\/04\/d16334_prologis_park_budapest_gyal_raktar-300x200.jpg\" alt=\"_prologis_park_budapest_gyal_raktar\" width=\"300\" height=\"200\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/d16334_prologis_park_budapest_gyal_raktar-300x200.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/d16334_prologis_park_budapest_gyal_raktar-600x400.jpg 600w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/d16334_prologis_park_budapest_gyal_raktar.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/a><strong>Gr\u00f6\u00dfte Parkfl\u00e4che zu vermieten<\/strong><\/p>\n<p>Der ATI-Sziget-Industriepark liegt auf der Insel Csepel, zwischen Szigetszentmiklos und Szigethalom und wurde 2002 erbaut. Die Anlage erstreckt sich \u00fcber insgesamt 87,7 Hektar mit insgesamt 84.000 m<sup>2<\/sup> Lagerfl\u00e4che Derzeit betr\u00e4gt die Gr\u00f6\u00dfe der zu vermietenden Fl\u00e4che 36 Tausend Quadratmeter Die B\u00fcrofl\u00e4che betr\u00e4gt 34 Tausend Quadratmeter, davon sind derzeit 28.700 zu vermieten.<\/p>\n<p>Die Miete betr\u00e4gt EUR2\/m<sup>2 <\/sup>F\u00fcr Lagerfl\u00e4chen und EUR 5-7 f\u00fcr B\u00fcrofl\u00e4chen Die Fl\u00e4chenerhaltungsgeb\u00fchr (Servicegeb\u00fchr) EUR 0,26\/qm. Unter den Mietern befinden sich Nilfisk Producer, Cleaning Equipment Manufacturer Ltd, Industrial Technique Hungary Ltd. (Mitglied der Atlas Copco Tools AB-Gruppe), die Obuda Bakery Ltd, die Draspo-Pace Car and Service Ltd, Dr. Marcus Ungarn, die Ostorhazi Coating Technology Ltd, die Persecutor Security Ltd. und Forest-Paper Ltd.<\/p>\n<p><a href=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2015\/04\/foto04n.jpg\" data-pswp-width=\"\" data-pswp-height=\"\" data-cropped=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-16216 aligncenter\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2015\/04\/foto04n-300x216.jpg\" alt=\"Park \u00e1ti sziget ipari\" width=\"300\" height=\"216\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/foto04n-300x216.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/foto04n.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/a><strong>Der teuerste Industriepark<\/strong><\/p>\n<p>Der East Gate Business Park wurde 2007 fertiggestellt, er liegt im Nordosten der Agglomeration Budapest, Fot. Es gibt 140 Tausend qm Lagerfl\u00e4che, von denen derzeit 6000 leer stehen Die Miete betr\u00e4gt EUR 4\/qm, was laut Raktar.info zu den teuersten geh\u00f6rt Die B\u00fcros kosten EUR 8,5\/qm. General Electric, Philip Morris, Lear Corporation, Igepa, Nefab, und Central Drinks geh\u00f6ren ebenfalls zu den Mietern.<\/p>\n<p><a href=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2015\/04\/rolunk.jpg\" data-pswp-width=\"\" data-pswp-height=\"\" data-cropped=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-16219 aligncenter\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2015\/04\/rolunk-300x201.jpg\" alt=\"egbp\" width=\"300\" height=\"201\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/rolunk-300x200.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/rolunk.jpg 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/a><strong>Der billigste Industriepark<\/strong><\/p>\n<p>Die Trimaran Storage Base befindet sich 30 km entfernt vom Zentrum von Budapest, in Monor Industriezone Die 32 Tausend m<sup>2<\/sup>&#8211; gro\u00dfe Fl\u00e4che hat 7 Geb\u00e4ude mit einer Gesamtfl\u00e4che von mehr als 13 Tausend qm, davon sind 10.400 qm zu vermieten Die Miete ist laut oto Raktar.info die niedrigste in der Agglomeration Budapest, sie kostet nur 1,4 EUR\/m<sup>2<\/sup>. B\u00fcros gibt es auf einer Gesamtfl\u00e4che von 650 qm, sie kosten EUR 3,5\/m<sup>2<\/sup>.<\/p>\n<p><a href=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2015\/04\/trimaran.jpg\" data-pswp-width=\"\" data-pswp-height=\"\" data-cropped=\"true\"><img loading=\"lazy\" decoding=\"async\" class=\" size-medium wp-image-16218 aligncenter\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2015\/04\/trimaran-300x204.jpg\" alt=\"Trimaran\" width=\"300\" height=\"204\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/trimaran-300x204.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/trimaran-116x80.jpg 116w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2015\/04\/trimaran.jpg 707w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\"><\/a><em>Basierend auf dem Artikel Portfolio.hu<br \/>\n\u00dcbersetzt von B.A<\/em><\/p>\n<p><em>Foto: www.egbp.hu, www.raktar.info, www.atisziget.hu, www.in-management.hu<br \/>\n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laut Portfolio.hu \u00fcbertrifft die Agglomeration Budapest auf dem Markt f\u00fcr gewerbliche Immobilien, w\u00e4hrend letzterer nur der drittgr\u00f6\u00dfte des Landes ist, ist der Markt f\u00fcr gewerbliche Immobilien rund um Budapest mit seinem Anteil von 40% unbestreitbar der wichtigste Lagerstandort in Ungarn. Das Kapital hat eine wichtige Rolle auf dem ungarischen Immobilienmarkt Die 85% des Bestandes an [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":768556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1066],"class_list":["post-768555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-hungary"],"blocksy_meta":[],"acf":[],"author_username":"becsi","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=768555"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/768556"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=768555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=768555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=768555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}