{"id":768829,"date":"2015-03-26T11:00:55","date_gmt":"2015-03-26T10:00:55","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/wirtschaftsminister-varga-ungarn-das-bip-wachstum-konnte-in-diesem-jahr-28-29-prozent-erreichen\/"},"modified":"2015-03-26T11:00:55","modified_gmt":"2015-03-26T10:00:55","slug":"wirtschaftsminister-varga-ungarn-das-bip-wachstum-konnte-in-diesem-jahr-28-29-prozent-erreichen","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/wirtschaftsminister-varga-ungarn-das-bip-wachstum-konnte-in-diesem-jahr-28-29-prozent-erreichen\/","title":{"rendered":"Wirtschaftsminister Varga: Ungarn Das BIP-Wachstum k\u00f6nnte in diesem Jahr 2,8-2,9 Prozent erreichen"},"content":{"rendered":"<p><strong>Budapest (MTI) (Die ungarische Regierung sch\u00e4tzt, dass das BIP-Wachstum in diesem Jahr 2,8-2,9 Prozent erreichen k\u00f6nnte, sagte Wirtschaftsminister Mihaly Varga am Mittwoch auf einer vom Wirtschaftsverband MGYOSZ organisierten Konferenz.<\/strong><\/p>\n<p>Die offizielle Prognose der Regierung f\u00fcr das BIP-Wachstum in diesem Jahr liegt derzeit bei 2,5 Prozent.<\/p>\n<p>Varga sagte, es sei nicht nur die Regierung, sondern auch Analysten und Institutionen, einschlie\u00dflich derjenigen, die der Regierung kritisch gegen\u00fcberstehen, und sagte, dass es nicht unrealistisch sei, mit einem BIP-Wachstum von rund 3 Prozent zu rechnen, und dass die f\u00fcr 2015-2016 beobachteten Risiken eher positiv als negativ seien Ungarn.<\/p>\n<p>Der Entwicklungszyklus der Europ\u00e4ischen Union 2014-2020 werde ein \u201cgutes Instrument sein, um die Impulse des Wirtschaftswachstums aufrechtzuerhalten\u201d, sagte der MinisterEr bekr\u00e4ftigte, dass 2007-2013 zwar nur 16 Prozent der EU-Mittel f\u00fcr die wirtschaftliche Entwicklung ausgegeben worden seien, diese Quote im aktuellen Zeitraum jedoch bei rund 60 Prozent l\u00e4ge.<\/p>\n<p>Varga f\u00fcgte hinzu, dass die Ankurbelung der Kreditvergabe f\u00fcr die Aufrechterhaltung des Wachstums von entscheidender Bedeutung sei und die von Premierminister Viktor Orban im Februar angek\u00fcndigte deutliche Senkung der Bankabgabe dazu beitragen k\u00f6nnte.<\/p>\n<p>Varga sagte, das Finanzamt m\u00fcsse einen neuen, an das kundenfreundliche Steuersystem angepassten Ansatz entwickeln, der das Wirtschaftswachstum f\u00f6rdert, anstatt es zu behindern. Er f\u00fcgte hinzu, dass das neue Gesetz \u00fcber die Steuerregeln am 1. Januar n\u00e4chsten Jahres eingef\u00fchrt werde.<\/p>\n<p>Wenn eine Betriebspr\u00fcfung nicht in sechs Monaten abgeschlossen werden kann, spiegelt sie Probleme auch mit dem Finanzamt wider Daraus folgt, dass das System gestrafft werden muss, sagte der Minister.<\/p>\n<blockquote>\n<p>\u201cWir erwarten von der Nationalen Steuer &#8211; und Zollbeh\u00f6rde (NAV) ein Verhalten, das das Wirtschaftswachstum nicht verlangsamt, sondern f\u00f6rdert, und die Wirtschaftsakteure unterst\u00fctzt\u201d, sagte er.<\/p>\n<\/blockquote>\n<p>In seiner jetzigen Steuerphilosophie sind alle Steuerzahler schlecht Das System ist zu streng, ohne dem Finanzamt eine M\u00f6glichkeit zu geben, F\u00e4lle einzeln zu beurteilen, allerdings ist es notwendig, zwischen guten und schlechten Steuerzahlern zu unterscheiden und das Amt sollte \u201cmit vern\u00fcnftigem Verst\u00e4ndnis an die Steuerzahler herantreten\u201d, sagte er.<\/p>\n<p>Die Regierung wolle den Ungarn die Verantwortung entziehen, bis 2017 ihre eigenen Einkommensteuererkl\u00e4rungen zu erstellen, sagte Varga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest (MTI) (Die ungarische Regierung sch\u00e4tzt, dass das BIP-Wachstum in diesem Jahr 2,8-2,9 Prozent erreichen k\u00f6nnte, sagte Wirtschaftsminister Mihaly Varga am Mittwoch auf einer vom Wirtschaftsverband MGYOSZ organisierten Konferenz. Die offizielle Prognose der Regierung f\u00fcr das BIP-Wachstum in diesem Jahr liegt derzeit bei 2,5 Prozent. Varga sagte, es sei nicht nur die Regierung, sondern auch [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":768830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1104],"class_list":["post-768829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=768829"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/768830"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=768829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=768829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=768829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}