{"id":768871,"date":"2015-03-23T15:39:53","date_gmt":"2015-03-23T14:39:53","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/die-franzosische-hypermarktkette-auchan-verhangte-eine-geldstrafe-von-1-mrd-huf\/"},"modified":"2015-03-23T15:39:53","modified_gmt":"2015-03-23T14:39:53","slug":"die-franzosische-hypermarktkette-auchan-verhangte-eine-geldstrafe-von-1-mrd-huf","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/die-franzosische-hypermarktkette-auchan-verhangte-eine-geldstrafe-von-1-mrd-huf\/","title":{"rendered":"Die franz\u00f6sische Hypermarktkette Auchan verh\u00e4ngte eine Geldstrafe von 1 Mrd. HUF"},"content":{"rendered":"<p><strong>Budapest, 23. M\u00e4rz (MTI) \u2013 Ungarns Wettbewerbsamt (GVH) hat Auchan Magyarorszag wegen Missbrauchs seiner marktbeherrschenden Stellung mit einer Geldstrafe von 1 Milliarde Forint (3,3 Mio. EUR) belegt.<\/strong><\/p>\n<p>GVH stellte fest, dass Auchan etwa drei Viertel seiner Non-Food-Lieferanten willk\u00fcrlich eine Geb\u00fchr f\u00fcr die Aufnahme seiner Produkte in seinen Bestand in den Jahren 2006-2014 erhoben hatteDiese Praxis verst\u00f6\u00dft gegen die ungarischen Einzelhandelsgesetze, sagte GVH am Montag in einer Erkl\u00e4rung.<\/p>\n<p>Auchan Magyarorszag verbuchte im vergangenen Jahr einen Nachsteuerverlust von 12,5 Milliarden Forint auf Einnahmen von 277,4 Milliarden, wie aus \u00f6ffentlichen Aufzeichnungen hervorgeht.<\/p>\n<p><em>Foto: www.kozelben.hu<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 23. M\u00e4rz (MTI) \u2013 Ungarns Wettbewerbsamt (GVH) hat Auchan Magyarorszag wegen Missbrauchs seiner marktbeherrschenden Stellung mit einer Geldstrafe von 1 Milliarde Forint (3,3 Mio. EUR) belegt. GVH stellte fest, dass Auchan etwa drei Viertel seiner Non-Food-Lieferanten willk\u00fcrlich eine Geb\u00fchr f\u00fcr die Aufnahme seiner Produkte in seinen Bestand in den Jahren 2006-2014 erhoben hatteDiese Praxis [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":768872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1066],"class_list":["post-768871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-hungary"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=768871"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/768872"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=768871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=768871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=768871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}