{"id":768949,"date":"2015-03-18T09:47:14","date_gmt":"2015-03-18T08:47:14","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/jaguar-land-rover-autofabrik-in-szombathely\/"},"modified":"2015-03-18T09:47:14","modified_gmt":"2015-03-18T08:47:14","slug":"jaguar-land-rover-autofabrik-in-szombathely","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/jaguar-land-rover-autofabrik-in-szombathely\/","title":{"rendered":"Jaguar, Land Rover Autofabrik in Szombathely?"},"content":{"rendered":"<p><strong>Laut Nyugat.hu kann die n\u00e4chste ungarische Automobilfabrik in der N\u00e4he der westungarischen Stadt gebaut werden, sagt hvg.hu.<\/strong><\/p>\n<p>Die indische Tata \u2013 der auch die britische Jaguar Land Rover Ltd geh\u00f6rt, beauftragte ein internationales Unternehmen, einen geeigneten Bereich f\u00fcr den Bau von Autos zu finden.<\/p>\n<p>Der Website wurde mitgeteilt, dass das Unternehmen \u00fcber das Au\u00dfenministerium mehrere St\u00e4dte kontaktiert hat. Szombathely blieb in der Endrunde, der Hauptkonkurrent ist Debrecen.<\/p>\n<p>Die Automobilfabrik w\u00e4re einer der gr\u00f6\u00dften Betriebe dieser Art in Ungarn und w\u00fcrde etwa 8-10 Tausend Menschen besch\u00e4ftigen.<\/p>\n<p>Es spricht sich f\u00fcr Szombathely aus, dass es ein 600 Morgen gro\u00dfes Land f\u00fcr industrielle Zwecke durch den ehemaligen Milit\u00e4rflughafen einschlie\u00dflich des Flughafens gibtNyugat.hu sagte in diesem Zusammenhang, dass in den letzten Wochen Bodenproben im Flughafen Szombathely genommen wurden.<\/p>\n<p>Die Website f\u00fcgt hinzu, dass die zust\u00e4ndigen Personen weder best\u00e4tigen noch dementieren und dass eine gro\u00dfe Geheimhaltung besteht.<\/p>\n<p>Es ist denkw\u00fcrdig, dass w\u00e4hrend des Besuchs der deutschen Bundeskanzlerin Angela Merkel Ger\u00fcchte aufkamen, BMW w\u00fcrde ein Werk in Ungarn bauen, aber der konkrete Standort wurde nicht festgelegt. Das Unternehmen bestritt daraufhin gegen\u00fcber mehreren Zeitungen, dass es ein Werk in Ungarn bauen wollte.<\/p>\n<p>Es st\u00e4rkt die M\u00f6glichkeit der Tata-Werksinvestition, dass das Unternehmen nach einem neuen Werksitz sucht, in dessen Zusammenhang auch \u00d6sterreich und die T\u00fcrkei als Standorte erzogen wurden Tata, dem seit 2008 die Marken Jaguar und Land Rover geh\u00f6ren, verdoppelte den bisher nicht so leistungsstarken Umsatz, w\u00e4hrend der Regentschaft erneuerten sie erfolgreich das veraltete Angebot der beiden britischen Marken, so zum Beispiel mit dem \u00e4u\u00dferst erfolgreichen Range Rover EvoqueBei Jaguar wird nun der Typ Jaguar XE eingef\u00fchrt, der als Konkurrent von BMW 3 gedacht ist, sagt hvg.hu.<\/p>\n<p><em>basierend auf dem Artikel von hvg.hu<br \/>\n\u00dcbersetzt von B.A<\/em><\/p>\n<p><em>Foto:<\/em> <em>Pixabay.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laut Nyugat.hu kann die n\u00e4chste ungarische Automobilfabrik in der N\u00e4he der westungarischen Stadt gebaut werden, sagt hvg.hu. Die indische Tata \u2013 der auch die britische Jaguar Land Rover Ltd geh\u00f6rt, beauftragte ein internationales Unternehmen, einen geeigneten Bereich f\u00fcr den Bau von Autos zu finden. Der Website wurde mitgeteilt, dass das Unternehmen \u00fcber das Au\u00dfenministerium mehrere [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":768950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1281],"tags":[1187,1104],"class_list":["post-768949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geschaft","tag-auto","tag-wirtschaft"],"blocksy_meta":[],"acf":[],"author_username":"becsi","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1281","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=768949"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/768949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/768950"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=768949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=768949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=768949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}