{"id":771284,"date":"2014-10-06T09:45:07","date_gmt":"2014-10-06T07:45:07","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/sps-automotive-performance-mercedes-gewinnt-12-h-ungarn\/"},"modified":"2014-10-06T09:45:07","modified_gmt":"2014-10-06T07:45:07","slug":"sps-automotive-performance-mercedes-gewinnt-12-h-ungarn","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/sps-automotive-performance-mercedes-gewinnt-12-h-ungarn\/","title":{"rendered":"SPS Automotive Performance Mercedes gewinnt 12 H Ungarn"},"content":{"rendered":"<p><strong><span style=\"line-height: 1.5em;\">Die 12 Stunden von Ungarn 2014 wurden vom Nr. 4 SPS Automotive Performance Mercedes-Benz SLS AMG gewonnen, gefahren von Lance David Arnold, Valentin Pierburg und Tim M\u00fcller, berichtet sportscar365.com.<\/span><\/strong><\/p>\n<p>Der Sportscar365.com sagte, er habe etwa nach der Zweidrittelmarke des Rennens die F\u00fchrung \u00fcbernommen, nachdem der lange f\u00fchrende Porsche Nr. 20 Stadler Motorsport eine Reihe von Problemen mit seinem Bremssystem hatte.<\/p>\n<p>Laut sportscar365.com entschieden sie schlie\u00dflich, dass dies die Sicherheit des Autos beeintr\u00e4chtigte, und schieden aus. F\u00fcr das in der Schweiz ans\u00e4ssige Team war es doppelt frustrierend, da sie gehofft hatten, das Saisonfinale der 24-Stunden-Serie mit einem Sieg zu beenden, der ihr Jahr beendet h\u00e4tte, da sie die Er\u00f6ffnungsrunde in Dubai gewonnen hatten.<\/p>\n<p>Zweiter in der Gesamtwertung war der Hofor Racing-Einsatz Nr. 1, der es zu einem Mercedes mit 1-2 machte.<\/p>\n<p><strong>Weiterlesen <a href=\"http:\/\/sportscar365.com\/gt\/24hseries\/sps-automotive-performance-mercedes-wins-12h-hungary\/\" target=\"_blank\" rel=\"noopener\">HIER<\/a>.<\/strong><\/p>\n<p><em>Foto: 24 H Serie\/Eric Teeken<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die 12 Stunden von Ungarn 2014 wurden vom Nr. 4 SPS Automotive Performance Mercedes-Benz SLS AMG gewonnen, gefahren von Lance David Arnold, Valentin Pierburg und Tim M\u00fcller, berichtet sportscar365.com. Der Sportscar365.com sagte, er habe etwa nach der Zweidrittelmarke des Rennens die F\u00fchrung \u00fcbernommen, nachdem der lange f\u00fchrende Porsche Nr. 20 Stadler Motorsport eine Reihe von [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":771285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":""},"categories":[1219],"tags":[1187],"class_list":["post-771284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-auto"],"blocksy_meta":[],"acf":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1219","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/771284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=771284"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/771284\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/771285"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=771284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=771284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=771284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}