{"id":775830,"date":"2025-08-02T16:34:00","date_gmt":"2025-08-02T14:34:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/wizz-air-und-anderen-billigfluggesellschaften-drohen-ernsthafte-rechtliche-schritte\/"},"modified":"2025-08-02T16:34:00","modified_gmt":"2025-08-02T14:34:00","slug":"wizz-air-und-anderen-billigfluggesellschaften-drohen-ernsthafte-rechtliche-schritte","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/wizz-air-und-anderen-billigfluggesellschaften-drohen-ernsthafte-rechtliche-schritte\/","title":{"rendered":"Wizz Air und anderen Billigfluggesellschaften drohen ernsthafte rechtliche Schritte"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Die europ\u00e4ischen Billigfluggesellschaften geraten zunehmend unter Druck, da der Bundesverband der Verbraucherzentralen (vzbv) Klage gegen EasyJet, Wizz Air und Vueling Airlines eingereicht hat. Er behauptet, dass diese Unternehmen von ihren Passagieren unrechtm\u00e4\u00dfig Geb\u00fchren f\u00fcr Handgep\u00e4ck verlangen.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c4rger f\u00fcr Wizz Air?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Ansicht von Ramona Pop, Pr\u00e4sidentin des vzbv, ist diese Praxis nicht nur irref\u00fchrend, sondern verst\u00f6\u00dft auch gegen EU-Recht. Die Kontroverse dreht sich darum, dass die beworbenen niedrigen Ticketpreise oft nur einen sehr kleinen pers\u00f6nlichen Gegenstand, wie einen kleinen Rucksack oder eine Handtasche, beinhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr jedes gr\u00f6\u00dfere Handgep\u00e4ck, das noch eine vern\u00fcnftige Gr\u00f6\u00dfe hat, wird eine zus\u00e4tzliche Geb\u00fchr erhoben. Verbrauchersch\u00fctzer argumentieren, dass dies Reisende in die Irre f\u00fchrt, die erst in der letzten Phase des Buchungsvorgangs von den zus\u00e4tzlichen Geb\u00fchren erfahren. Der Vzbv ist der Meinung, dass die Mitnahme von Handgep\u00e4ck nicht als zus\u00e4tzliche Dienstleistung betrachtet werden sollte, sondern im Ticketpreis enthalten sein sollte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Position der Organisation wird durch ein Urteil des Europ\u00e4ischen Gerichtshofs aus dem Jahr 2014 gest\u00fctzt, in dem Handgep\u00e4ck zu einem wesentlichen Bestandteil von Flugreisen erkl\u00e4rt wurde. Solange das Gep\u00e4ckst\u00fcck den Gr\u00f6\u00dfen-, Gewichts- und Sicherheitsvorschriften entspricht, d\u00fcrfen die Fluggesellschaften keine zus\u00e4tzlichen Geb\u00fchren erheben.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2025\/08\/Debrecen-airport-Wizz-Air-new-route.jpg\" alt=\"Debrecen airport Wizz Air new route\" class=\"wp-image-666474\"\/><figcaption class=\"wp-element-caption\">Foto: <a href=\"https:\/\/www.facebook.com\/photo.php?fbid=654676070158477&amp;set=pb.100068482698245.-2207520000&amp;type=3&amp;locale=hu_HU\" target=\"_blank\" rel=\"noopener\">Facebook\/Debrecen Nemzetk\u00f6zi Rep\u00fcl\u0151t\u00e9r<\/a><\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Regeln sollen versch\u00e4rft werden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Klage zielt nicht nur darauf ab, die drei Fluggesellschaften zur Rechenschaft zu ziehen, sondern auch darauf, strengere EU-weite Vorschriften durchzusetzen. Verbrauchersch\u00fctzer sagen, es sei an der Zeit, dass die EU einheitliche Gr\u00f6\u00dfenstandards f\u00fcr Handgep\u00e4ck festlegt, das kostenlos mit an Bord genommen werden kann. Pop betonte, dass die Passagiere vor sogenannten &#8220;Kostenfallen&#8221; gesch\u00fctzt werden m\u00fcssen, mit denen die Fluggesellschaften die wahren Kosten eines Fluges verschleiern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch auf EU-Ebene gewinnt das Thema an Dynamik. Im Juni billigte der Verkehrsausschuss des Europ\u00e4ischen Parlaments einen Vorschlag zur Harmonisierung der Gep\u00e4ckgr\u00f6\u00dfenvorschriften in der gesamten Union. Der Vorschlag sieht vor, dass die Fluggesellschaften jedem Passagier die Mitnahme eines pers\u00f6nlichen Gegenstands (bis zu 40\u00d730\u00d715 cm) und eines kleinen Handgep\u00e4cks (bis zu 100 cm Gesamtgr\u00f6\u00dfe und 7 kg) ohne zus\u00e4tzliche Kosten gestatten m\u00fcssen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Fluggesellschaften haben die Initiative scharf kritisiert. Sie argumentieren, dass sie die Wahlm\u00f6glichkeiten der Verbraucher einschr\u00e4nkt und langfristig zu h\u00f6heren Ticketpreisen f\u00fchren k\u00f6nnte. Das Modell der Billigfluggesellschaften beruht darauf, dass nur die Leistungen in Rechnung gestellt werden, die die Passagiere auch tats\u00e4chlich in Anspruch nehmen, argumentieren die Unternehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Zusammenhang zwischen der Klage und der vorgeschlagenen EU-Verordnung ist klar: Die Verbrauchergruppen hoffen, dass die kostenlose Mitnahme von Handgep\u00e4ck bei allen Fluggesellschaften gesetzlich vorgeschrieben wird. Wenn das Gericht den Argumenten des vzbv Recht gibt, k\u00f6nnte dies einen Pr\u00e4zedenzfall mit weitreichenden Auswirkungen auf ganz Europa schaffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine der umstrittensten Fragen im Flugverkehr steht wieder im Rampenlicht: Was ist eine Grundleistung und wo verl\u00e4uft die Grenze zwischen versteckten Kosten und transparenter Preisgestaltung? Eines ist sicher &#8211; der Ausgang des Prozesses k\u00f6nnte das Gesch\u00e4ftsmodell der europ\u00e4ischen Luftfahrt, wie wir es kennen, neu gestalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um diesen Artikel auf Ungarisch zu lesen oder zu teilen, klicken Sie hier: <a href=\"https:\/\/hellomagyar.hu\/2025\/08\/02\/wizz-air-fapadosok-per-poggyasz\/\" target=\"_blank\" rel=\"noopener\">Hell\u00f3 Magyar<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lesen Sie weitere Artikel <a href=\"https:\/\/dailynewshungary.com\/tag\/wizz-air\/\"><strong>\u00fcber Wizz Air<\/strong><\/a> auf Daily News Hungary!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lesen Sie auch:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/wizz-air-startet-einen-neuen-flug-von-budapest-in-eine-wunderschone-italienische-stadt\/\">Wizz Air startet neuen Flug von Budapest in eine wundersch\u00f6ne italienische Stadt<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/beeindruckende-zahlen-von-wizz-air-1-000-fluge-tag-1-start-alle-90-sekunden-dennoch-bleiben-ernsthafte-herausforderungen\/\">Erstaunliche Zahlen von Wizz Air: 1.000 Fl\u00fcge\/Tag, 1 Start\/Alle 90 Sekunden &#8211; und doch bleiben ernste Herausforderungen<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/wizz-air-nimmt-nach-13-jahren-wieder-fluge-vom-polnischen-flughafen-auf\/\">Wizz Air nimmt nach 13 Jahren wieder Fl\u00fcge von einem polnischen Flughafen auf<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die europ\u00e4ischen Billigfluggesellschaften geraten zunehmend unter Druck, da der Bundesverband der Verbraucherzentralen (vzbv) Klage gegen EasyJet, Wizz Air und Vueling Airlines eingereicht hat. Er behauptet, dass diese Unternehmen von ihren Passagieren unrechtm\u00e4\u00dfig Geb\u00fchren f\u00fcr Handgep\u00e4ck verlangen. \u00c4rger f\u00fcr Wizz Air? Nach Ansicht von Ramona Pop, Pr\u00e4sidentin des vzbv, ist diese Praxis nicht nur irref\u00fchrend, sondern [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":775831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[518],"tags":[1075,1115,1080,1079,1297,1076,1180],"class_list":["post-775830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-def","tag-budapest-flughafen","tag-flughafen","tag-reisen","tag-tourismus","tag-transport","tag-ungarn","tag-wizz-air"],"blocksy_meta":[],"acf":[],"author_username":"api","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Wizz Air","canonical_url":"","robots":"","primary_category":"3881","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"80","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/775830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=775830"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/775830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/775831"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=775830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=775830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=775830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}