{"id":776077,"date":"2025-08-09T04:34:00","date_gmt":"2025-08-09T02:34:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/tragisch-zwei-ungarische-soldaten-starben-kurzlich\/"},"modified":"2025-08-09T04:34:00","modified_gmt":"2025-08-09T02:34:00","slug":"tragisch-zwei-ungarische-soldaten-starben-kurzlich","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/tragisch-zwei-ungarische-soldaten-starben-kurzlich\/","title":{"rendered":"Tragisch: Zwei ungarische Soldaten starben k\u00fcrzlich"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>In den letzten Tagen sind zwei ungarische Soldaten auf tragische Weise ums Leben gekommen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am 5. August 2025 verstarb ein ungarischer Hauptfeldwebel w\u00e4hrend seines Dienstes bei der EUFOR-Friedensmission in Sarajevo. Der 47-j\u00e4hrige Soldat war seit August 2024 Teil der Mission und diente als Mitglied des Luftoperations- und Kontrollzentrums der ungarischen Verteidigungskr\u00e4fte. Die ungarischen Verteidigungskr\u00e4fte sorgten f\u00fcr die R\u00fcckf\u00fchrung des Verstorbenen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am 7. August 2025, w\u00e4hrend einer Marsch\u00fcbung zwischen Sirok und K\u00e9kestet\u0151, wurde ein 29-j\u00e4hriger Gefreiter der ungarischen Streitkr\u00e4fte krank und sein Kreislauf setzte kurz darauf aus. Ein am Ort des Geschehens anwesender Sanit\u00e4ter begann sofort mit Wiederbelebungsma\u00dfnahmen, die von den eintreffenden Rettungsdiensten fortgesetzt wurden. Leider war der Versuch, sein Leben zu retten, erfolglos. Experten untersuchen die Umst\u00e4nde der beiden Todesf\u00e4lle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Verteidigungsministerium und die ungarischen Streitkr\u00e4fte sprachen den Familien und Angeh\u00f6rigen der verstorbenen Soldaten ihr aufrichtiges Beileid aus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lesen Sie auch:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/breaking-us-soldat-stirbt-bei-trainingsunfall-in-ungarn\/\">US-Soldat stirbt bei Trainingsunfall in Ungarn<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Titelbild: <a href=\"https:\/\/depositphotos.com\/photos\/ukraine-soldier.html?filter=all&amp;qview=146480745\" target=\"_blank\" rel=\"noopener\">depositphotos.com<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den letzten Tagen sind zwei ungarische Soldaten auf tragische Weise ums Leben gekommen. Am 5. August 2025 verstarb ein ungarischer Hauptfeldwebel w\u00e4hrend seines Dienstes bei der EUFOR-Friedensmission in Sarajevo. Der 47-j\u00e4hrige Soldat war seit August 2024 Teil der Mission und diente als Mitglied des Luftoperations- und Kontrollzentrums der ungarischen Verteidigungskr\u00e4fte. Die ungarischen Verteidigungskr\u00e4fte sorgten [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":776078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[518],"tags":[1203,1711,1076,1130],"class_list":["post-776077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-def","tag-armee","tag-trauer","tag-ungarn","tag-ungarn-im-ausland"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"In den letzten Tagen sind zwei ungarische Soldaten auf tragische Weise ums Leben gekommen.","focus_keyword":"soldier","canonical_url":"","robots":"","primary_category":"3881","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"76","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/776077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=776077"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/776077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/776078"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=776077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=776077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=776077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}