{"id":778683,"date":"2025-10-14T19:55:17","date_gmt":"2025-10-14T17:55:17","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/neue-busse-bedienen-ab-morgen-die-fahrgaste-in-budapest\/"},"modified":"2025-10-15T08:21:49","modified_gmt":"2025-10-15T06:21:49","slug":"neue-busse-bedienen-fahrgaste-in-budapest","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/neue-busse-bedienen-fahrgaste-in-budapest\/","title":{"rendered":"Neue Busse bedienen ab morgen die Fahrg\u00e4ste in Budapest"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Ab Mittwoch werden die brandneuen Maximidi-Mercedes-Busse ihren Dienst aufnehmen, zun\u00e4chst auf der Linie 121 in \u00dajpest, gefolgt von der Linie 27, k\u00fcndigte Gergely Kar\u00e1csony, der B\u00fcrgermeister von Budapest, am Dienstag auf seiner Facebook-Seite an.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Er hob hervor, dass diese neuen Busse umweltfreundlich, barrierefrei, ger\u00e4umig und komfortabel sind und sogar mit Ladeger\u00e4ten f\u00fcr Mobiltelefone ausgestattet sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut seinem Posting werden in den kommenden Monaten 65 neue Fahrzeuge eintreffen und damit acht Prozent der Busflotte der BKV erneuern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <a href=\"https:\/\/www.facebook.com\/karacsonygergely\/posts\/1397453001743367?ref=embed_post\" target=\"_blank\" rel=\"noopener\">B\u00fcrgermeister betonte<\/a>: &#8220;Trotz aller Versuche der Regierung, uns die Mittel zu entziehen, weigern wir uns entschlossen, bei der Verbesserung des \u00f6ffentlichen Nahverkehrs aufzugeben. Wir arbeiten weiter an einem gr\u00fcneren, lebenswerteren Budapest.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/dailynewshungary.b-cdn.net\/wp-content\/uploads\/2025\/10\/New-buses-in-Budapest.webp\" alt=\"New buses in Budapest\" class=\"wp-image-674209\"\/><figcaption class=\"wp-element-caption\">Foto: FB\/Gergely Kar\u00e1csony<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\"><strong>Lesen Sie auch:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>M\u00f6glicherweise gibt es einen weiteren Direktflug <a href=\"https:\/\/dailynewshungary.com\/de\/moglicherweise-gibt-es-einen-weiteren-direktflug-zwischen-budapest-und-amerika\/\">zwischen Budapest und Amerika<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/tragisches-zugungluck-nahe-der-ungarischen-grenze-bombenalarm-im-budapester-express-fotos-videos\/\">Tragische Zugkollision nahe der ungarischen Grenze<\/a>, Bombenalarm im Budapest Express &#8211; Fotos, Videos, aktualisiert<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Klicken Sie f\u00fcr weitere <a href=\"https:\/\/dailynewshungary.com\/tag\/budapest\/\">Budapest<\/a> Nachrichten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ab Mittwoch werden die brandneuen Maximidi-Mercedes-Busse ihren Dienst aufnehmen, zun\u00e4chst auf der Linie 121 in \u00dajpest, gefolgt von der Linie 27, k\u00fcndigte Gergely Kar\u00e1csony, der B\u00fcrgermeister von Budapest, am Dienstag auf seiner Facebook-Seite an. Er hob hervor, dass diese neuen Busse umweltfreundlich, barrierefrei, ger\u00e4umig und komfortabel sind und sogar mit Ladeger\u00e4ten f\u00fcr Mobiltelefone ausgestattet sind. [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":778684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[518],"tags":[4273,1147,1080,1076],"class_list":["post-778683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-def","tag-ce","tag-entwicklung","tag-reisen","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Ab Mittwoch werden die brandneuen Maximidi-Mercedes-Busse in Budapest in Betrieb genommen, sagte B\u00fcrgermeister Gergely Kar\u00e1csony.","focus_keyword":"Budapest","canonical_url":"","robots":"","primary_category":"4291","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"69","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/778683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=778683"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/778683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/778684"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=778683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=778683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=778683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}