{"id":784197,"date":"2026-02-22T13:54:00","date_gmt":"2026-02-22T12:54:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/deutsche-rechtsextreme-nur-orban-kann-den-eu-beitritt-der-ukraine-blockieren\/"},"modified":"2026-02-23T10:13:35","modified_gmt":"2026-02-23T09:13:35","slug":"deutsche-rechtsextreme-nur-orban-kann-den-eu-beitritt-der-ukraine-blockieren","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/deutsche-rechtsextreme-nur-orban-kann-den-eu-beitritt-der-ukraine-blockieren\/","title":{"rendered":"Deutsche Rechtsextreme: Nur Orb\u00e1n kann den EU-Beitritt der Ukraine blockieren"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Viktor Orb\u00e1n ist die einzige Garantie daf\u00fcr, dass die Ukraine nicht in die Europ\u00e4ische Union aufgenommen wird, weil das Land nicht einmal die grundlegendsten Beitrittskriterien &#8211; einschlie\u00dflich der Korruptionsstandards &#8211; erf\u00fcllt, so Alice Weidel, Co-Vorsitzende der Alternative f\u00fcr Deutschland (AfD).<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/mandiner.hu\/belfold\/2026\/02\/orban-viktor-az-egyetlen-garanciaja-hogy-ukrajna-ne-jusson-be-az-eu-ba-maxima-alice-weidellel\" target=\"_blank\" rel=\"noopener\">In einem Interview<\/a> in der Sendung MAXIMA mit dem Chefredakteur von Mandiner sagte Weidel, dass die Ukraine aufgrund ihrer wirtschaftlichen Leistung und ihres politischen Systems nicht f\u00fcr eine EU-Mitgliedschaft geeignet sei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie bezeichnete das Land als einen &#8220;ungeordneten und v\u00f6llig dysfunktionalen Staat&#8221; und sagte, es sollte niemals in den Block aufgenommen werden. Ihrer Meinung nach w\u00e4ren L\u00e4nder wie Montenegro oder Serbien weitaus geeignetere Kandidaten, was darauf hindeutet, dass Br\u00fcssel diese L\u00e4nder mit der Ukraine verwechselt hat. Sie betonte au\u00dferdem, dass die Ukraine auch nicht der NATO beitreten sollte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Europa braucht Frieden, keine Eskalation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Weidel sagte, dass die AfD, \u00e4hnlich wie die ungarischen Regierungsparteien, dem Frieden in Europa Priorit\u00e4t einr\u00e4umt und glaubt, dass der Dialog mit beiden Seiten des Krieges aufrechterhalten werden muss. Sie kritisierte die Au\u00dfenpolitik Berlins und fragte, wie es sich Deutschland leisten k\u00f6nne, gleichzeitig schlechte Beziehungen zu den Vereinigten Staaten, China und Russland zu unterhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie bezeichnete die derzeitige europ\u00e4ische F\u00fchrung als &#8220;unglaublich sch\u00e4dlich&#8221; und warnte davor, dass deren Aktionen so viel &#8220;Porzellan&#8221; zerschlagen, dass die politischen Prozesse au\u00dfer Kontrolle geraten k\u00f6nnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weidel zufolge ist der Krieg in der Ukraine im Wesentlichen ein Stellvertreterkonflikt zwischen Washington und Moskau, und nur die Vereinigten Staaten haben den Hebel, um Frieden zu vermitteln. Aus europ\u00e4ischer Sicht, so f\u00fcgte sie hinzu, sollte die genaue Lage der russisch-ukrainischen Grenze zweitrangig sein, um eine weitere Eskalation zu verhindern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie kritisierte auch, dass die europ\u00e4ischen Staats- und Regierungschefs Wolodymyr Selenskyj gest\u00e4rkt haben, da er keine ausreichende Unterst\u00fctzung im eigenen Land habe. Stattdessen schlug sie vor, Europa solle sich zur\u00fcckziehen, neutral bleiben und als Vermittler auftreten, anstatt zu versuchen, eine dominante geopolitische Rolle zu spielen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Behauptungen \u00fcber Br\u00fcsseler Einfluss in Ungarn<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Weidel behauptete au\u00dferdem, dass Br\u00fcssel starken Einfluss auf die Wahlen in Ungarn aus\u00fcbt, um den Oppositionsf\u00fchrer an die Macht zu bringen. Sie bezeichnete Magyar P\u00e9ter als &#8220;nicht glaubw\u00fcrdig&#8221; und als &#8220;Marionette Br\u00fcssels&#8221; und behauptete, dass er Ungarn enger an EU-Richtlinien binden und die Unabh\u00e4ngigkeit des Landes schw\u00e4chen w\u00fcrde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Ich glaube nicht, dass er im April gew\u00e4hlt werden wird&#8221;, sagte sie, &#8220;aber diese Bewegung muss genau beobachtet werden, denn Br\u00fcssel versucht ganz klar, sich in die Innenpolitik des Landes einzumischen.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Falls Sie es verpasst haben:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dailynewshungary.com\/de\/rechtsextremer-afd-co-chef-ungarn-und-orban-modell-fur-deutschland\/\" data-type=\"link\" data-id=\"https:\/\/dailynewshungary.com\/de\/rechtsextremer-afd-co-chef-ungarn-und-orban-modell-fur-deutschland\/\">Rechtsextremer AfD-Ko-Vorsitzender: Ungarn und Orb\u00e1n als Vorbild f\u00fcr Deutschland<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viktor Orb\u00e1n ist die einzige Garantie daf\u00fcr, dass die Ukraine nicht in die Europ\u00e4ische Union aufgenommen wird, weil das Land nicht einmal die grundlegendsten Beitrittskriterien &#8211; einschlie\u00dflich der Korruptionsstandards &#8211; erf\u00fcllt, so Alice Weidel, Co-Vorsitzende der Alternative f\u00fcr Deutschland (AfD). In einem Interview in der Sendung MAXIMA mit dem Chefredakteur von Mandiner sagte Weidel, dass [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":784198,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[1177,1082,4564,1092,1102,1076,1128],"class_list":["post-784197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-deutschland","tag-europaische-union","tag-kategorie-ausenpolitik","tag-ukraine","tag-ungarische-regierung","tag-ungarn","tag-viktor-orban"],"blocksy_meta":[],"acf":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"default","telegram_post":"","_xlat_group_id":"d9db071a-30b1-48e9-99ab-d35ce3731c50"},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"ukraine","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"70","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/784197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=784197"}],"version-history":[{"count":2,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/784197\/revisions"}],"predecessor-version":[{"id":784231,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/784197\/revisions\/784231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/784198"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=784197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=784197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=784197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}