{"id":784263,"date":"2026-02-23T17:38:58","date_gmt":"2026-02-23T16:38:58","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/es-ist-entschieden-eu-sanktionen-blockiert-da-ungarn-und-die-slowakei-sich-weigern-das-20-russland-sanktionspaket-zu-unterstutzen-update\/"},"modified":"2026-02-24T10:29:11","modified_gmt":"2026-02-24T09:29:11","slug":"es-ist-entschieden-eu-sanktionen-blockiert-da-ungarn-und-die-slowakei-sich-weigern-das-20-russland-sanktionspaket-zu-unterstutzen-update","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/es-ist-entschieden-eu-sanktionen-blockiert-da-ungarn-und-die-slowakei-sich-weigern-das-20-russland-sanktionspaket-zu-unterstutzen-update\/","title":{"rendered":"Es ist entschieden! EU-Sanktionen blockiert, da Ungarn und die Slowakei sich weigern, das 20. Russland-Sanktionspaket zu unterst\u00fctzen \u2013 UPDATE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/haber.aa.com.tr\/#\" target=\"_blank\" rel=\"noopener\"><\/a><strong>Die Europ\u00e4ische Union hat bei ihrem Au\u00dfenministertreffen am Montag in Br\u00fcssel keine Einigung \u00fcber ihr j\u00fcngstes Sanktionspaket gegen Russland erzielt. Die EU-Au\u00dfenbeauftragte Kaja Kallas nannte das Ergebnis einen &#8220;R\u00fcckschlag&#8221;, versprach aber, die Arbeit fortzusetzen.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Das 20. Russland-Sanktionspaket wurde mit einem Veto belegt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Leider haben wir keine Einigung \u00fcber das 20. Sanktionspaket erzielt. Das ist ein R\u00fcckschlag und eine Botschaft, die wir heute nicht senden wollten, aber die Arbeit geht weiter&#8221;, sagte Kallas und f\u00fcgte hinzu, dass man mit den ungarischen und slowakischen Beh\u00f6rden in Kontakt stehe, um das Paket voranzubringen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kallas sagte, die Entscheidung, von der von allen EU-Staats- und Regierungschefs im Europ\u00e4ischen Rat erzielten Einigung abzur\u00fccken, sei &#8220;bedauerlich&#8221; und versto\u00dfe gegen die Klausel der &#8220;aufrichtigen Zusammenarbeit&#8221; in den EU-Vertr\u00e4gen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie sagte, dass EU-Ratspr\u00e4sident Antonio Costa und EU-Kommissionspr\u00e4sidentin Ursula von der Leyen das Problem mit Viktor Orban, dem ungarischen Ministerpr\u00e4sidenten, der das Paket ablehnt, ansprechen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die EU hatte urspr\u00fcnglich geplant, eingefrorene russische Guthaben zur Finanzierung der Sanktionen zu verwenden, aber Kallas deutete an, dass der Block zu diesem Plan zur\u00fcckkehren k\u00f6nnte, wenn der aktuelle Ansatz scheitert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Bezug auf die Ukraine betonte Kallas, dass Diplomatie einem Krieg vorzuziehen sei, beklagte aber, dass es nach mehr als einem Jahr der Gespr\u00e4che immer noch keinen Waffenstillstand im Ukraine-Krieg gibt, der diese Woche vier Jahre alt wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Nicht die Ukraine ist das Hindernis f\u00fcr den Frieden, sondern Russland. Wir m\u00fcssen das Drehbuch umdrehen, weg vom Druck auf die Ukraine, Territorium abzugeben, hin zu dem, was Russland tun muss, um die grundlegenden Bedingungen f\u00fcr einen gerechten und verlorenen Frieden zu erf\u00fcllen&#8221;, sagte sie und warnte, dass Moskaus &#8220;maximalistische Forderungen nicht mit minimalen Antworten erf\u00fcllt werden k\u00f6nnen.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kallas k\u00fcndigte an, dass der Block beschlossen habe, die maximale Gr\u00f6\u00dfe der russischen Mission in der EU auf 40 Personen zu begrenzen und f\u00fcgte hinzu, dass der Block daran arbeiten werde, &#8220;Hunderttausende ehemaliger russischer Soldaten&#8221; an der Einreise in den Schengen-Raum zu hindern, um zu verhindern, dass &#8220;Kriegsverbrecher und Saboteure auf den europ\u00e4ischen Stra\u00dfen herumlaufen&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie teilte den EU-Mitgliedstaaten auch ein Papier mit, in dem die Zugest\u00e4ndnisse aufgef\u00fchrt sind, die die EU von Russland erwarten sollte, darunter der R\u00fcckzug der russischen Truppen aus den besetzten Gebieten und die Einhaltung bestehender internationaler Abkommen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Naher Osten, Venezuela<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mit Blick auf den Nahen Osten kritisierte Kallas die Ausweitung der israelischen Befugnisse im Westjordanland, die gegen internationales Recht versto\u00dfe und die Aussichten auf einen k\u00fcnftigen pal\u00e4stinensischen Staat untergrabe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Sechsundzwanzig L\u00e4nder wollen Sanktionen gegen die gewaltt\u00e4tigen Siedler (im Westjordanland). Das Thema liegt schon seit geraumer Zeit auf dem Tisch, und einer will es nicht. Das ist eindeutig das Problem, das wir in unseren Entscheidungsprozessen haben&#8221;, sagte sie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zu den aktuellen Spannungen zwischen den USA und dem Iran warnte Kallas, dass sich die beiden L\u00e4nder &#8220;gef\u00e4hrlich auf einen Krieg zubewegen&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Das Fenster der Diplomatie ist sehr eng, und nat\u00fcrlich haben wir viele Sorgen mit dem Iran &#8230; aber jede milit\u00e4rische Intervention riskiert schwer zu kontrollierende Konsequenzen&#8221;, sagte sie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Bezug auf Venezuela sagte Kallas, dass die EU in K\u00fcrze einen neuen Ansatz diskutieren wird, indem sie vorschl\u00e4gt, die Sanktionen gegen die amtierende Pr\u00e4sidentin Delcy Rodriguez aufzuheben, sofern ein Konsens erzielt wird.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UPDATE &#8211; Szijj\u00e1rt\u00f3: Kallas dr\u00e4ngt darauf, dass ungarische und slowakische Soldaten in die Ukraine geschickt werden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Br\u00fcssel konspiriert mit Kiew, um die Energieversorgung Ungarns und der Slowakei zu bedrohen. Die Hohe Vertreterin der EU f\u00fcr Au\u00dfen- und Sicherheitspolitik steht in dieser Situation nicht an der Seite der beiden Mitgliedstaaten, sondern dr\u00e4ngt auf die Entsendung ungarischer und slowakischer Soldaten in die Ukraine, sagte P\u00e9ter Szijj\u00e1rt\u00f3, Minister f\u00fcr Ausw\u00e4rtige Angelegenheiten und Handel, am Montag in Br\u00fcssel. Auf einer Pressekonferenz im Anschluss an die Sitzung des Rates f\u00fcr Ausw\u00e4rtige Angelegenheiten der Europ\u00e4ischen Union berichtete der Minister, dass bei dem Treffen zwei &#8220;schockierende&#8221; Dinge ans Licht gekommen seien: zum einen, dass die Hohe Vertreterin der EU f\u00fcr Au\u00dfen- und Sicherheitspolitik, Kaja Kallas, m\u00f6chte, dass Ungarn und die Slowakei Soldaten in die Ukraine schicken, und zum anderen, dass Kiew tats\u00e4chlich mit Br\u00fcssel bei der Blockade von \u00d6llieferungen zusammenarbeitet. Er wies darauf hin, dass dieses Treffen mehrere Lektionen geliefert habe, die deutlich machten, dass die Europ\u00e4er sich auf einen langen Krieg vorbereiten, dass sie so schnell wie m\u00f6glich Soldaten und viel mehr Geld in die Ukraine schicken wollen und dass sie \u00fcber den zuk\u00fcnftigen EU-Beitritt des Landes als eine unvermeidliche und eindeutige Angelegenheit sprechen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Was die Vorbereitung auf einen langen Krieg angeht, so sprach der ukrainische Au\u00dfenminister \u00fcber die Ziele auf dem Schlachtfeld f\u00fcr dieses Jahr, d.h. f\u00fcr das ganze Jahr (&#8230;) Mehrere Kollegen aus der Europ\u00e4ischen Union best\u00e4tigten, dass die L\u00f6sung auf dem Schlachtfeld gesucht werden muss und dass wir uns auf einen langen Krieg vorbereiten m\u00fcssen&#8221;, sagte er.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Was mehr Geld angeht, so haben meine Kollegen deutlich gemacht, dass die zuvor vereinbarten 90 Milliarden Euro, die jetzt von Ungarn blockiert werden, nur einen Teil des Finanzbedarfs der Ukraine abdecken, und sie haben deutlich gemacht, dass in naher Zukunft eine Entscheidung getroffen werden muss, um noch mehr Ressourcen, noch mehr Geld, in die Ukraine zu schicken. Dies wurde vom ukrainischen Au\u00dfenminister best\u00e4tigt, der sagte, dass sie in diesem Jahr 155 Milliarden Euro ben\u00f6tigen, nur um die Armee zu unterhalten&#8221;, fuhr er fort. &#8220;Dann haben meine Kollegen, sowohl von der EU als auch der ukrainische Au\u00dfenminister, klar und deutlich gesagt, dass die Ukraine nat\u00fcrlich voll auf die Mitgliedschaft vorbereitet ist. Und hier ist die Obergrenze nicht gefallen, obwohl es eine realistische Chance daf\u00fcr gab&#8221;, sagte er.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00e9ter Szijj\u00e1rt\u00f3 erw\u00e4hnte auch, dass sein luxemburgischer Amtskollege nach den &#8220;Forderungen und Anschuldigungen&#8221; des ukrainischen Au\u00dfenministers per Videoschaltung fragte, ob Kiew damit einverstanden sei, dass ungarische und slowakische Experten den Zustand der Friendship-\u00d6lpipeline vor Ort begutachten, woraufhin Andriy Sibiha &#8220;verwirrt zu murmeln&#8221; begann und antwortete, dass er sich die Sache ansehen werde und sich mit jemandem dar\u00fcber beraten m\u00fcsse. Er war der Meinung, dass diese &#8220;Verwirrung&#8221; eindeutig beweise, dass die ukrainische Seite nicht die Wahrheit \u00fcber die \u00d6lpipeline sage, denn sonst h\u00e4tte sein ehemaliger offizieller Partner gesagt: &#8220;Nat\u00fcrlich k\u00f6nnen die ungarischen und slowakischen Experten jederzeit kommen.&#8221; &#8220;Mein armer Kollege aus Luxemburg, der dachte, er k\u00f6nne uns und den Slowaken einen gro\u00dfen Schlag versetzen, hat die Ukrainer im Grunde als L\u00fcgner entlarvt, was den Zustand der \u00d6lpipeline angeht, wenn sie behaupten, die Pipeline sei besch\u00e4digt oder physisch ungeeignet f\u00fcr den Transport&#8221;, stellte er fest.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Und die Hohe Vertreterin f\u00fcr Ausw\u00e4rtige Angelegenheiten, die ehemalige estnische Ministerpr\u00e4sidentin Kaja Kallas, hat noch \u00d6l ins Feuer gegossen, indem sie sagte, dass in dieser Situation vielleicht nicht Experten, sondern ungarische und slowakische Soldaten geschickt werden sollten&#8221;, sagte er. &#8220;Es ist schockierend und entsetzlich, dass die Ukrainer und Br\u00fcssel sich zusammentun, um die Energieversorgung von zwei EU-Mitgliedstaaten, Ungarn und der Slowakei, zu gef\u00e4hrden, und in dieser Situation, anstatt dass die Europ\u00e4ische Kommission den Mitgliedstaaten zur Seite steht, beginnt die Hohe Vertreterin der EU sogar darauf zu dr\u00e4ngen, ungarische und slowakische Soldaten in die Ukraine zu schicken&#8221;, f\u00fcgte er hinzu. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Minister erkl\u00e4rte, dass die ukrainische F\u00fchrung \u00fcber die Sch\u00e4den an der Pipeline l\u00fcge, da sie technisch voll in der Lage sei, die Versorgung wiederherzustellen, was mit den Informationen der slowakischen Regierung \u00fcbereinstimme. &#8220;Da die Ukrainer sich derzeit mit uns anlegen, da die Ukrainer derzeit unsere Souver\u00e4nit\u00e4t angreifen, (&#8230;) da die Ukrainer die Sicherheit der ungarischen Energieversorgung gef\u00e4hrden, ist Ungarn nicht gewillt, zu irgendeiner Entscheidung hier in Br\u00fcssel beizutragen, die den Interessen der Ukrainer dienen w\u00fcrde, die f\u00fcr die Ukrainer wichtig w\u00e4re&#8221;, warnte er. Dann erkl\u00e4rte er, dass er bei dem Treffen deutlich gemacht habe, dass die ungarische Regierung weder der Verabschiedung des 20. Sanktionspakets noch dem 90 Milliarden Euro schweren Kriegskredit zustimmen werde. &#8220;Nat\u00fcrlich wurden wir daraufhin von unserem slowakischen Kollegen massiv angegriffen, aber wir haben uns nicht beirren lassen und deutlich gemacht, dass wir unsere Position nicht \u00e4ndern werden, bis die Ukrainer die \u00d6llieferungen an Ungarn und die Slowakei wieder in vollem Umfang aufgenommen haben&#8221;, sagte er. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abschlie\u00dfend betonte er, dass es weiterhin t\u00e4glicher Anstrengungen bedarf, um sich aus dem Krieg herauszuhalten, die Preissenkungen f\u00fcr Versorgungsleistungen beizubehalten und zu verhindern, dass das Geld der ungarischen Bev\u00f6lkerung in die Ukraine flie\u00dft. &#8220;Wie k\u00f6nnen wir in diesem Fall am besten reagieren? Indem wir die nationale Petition zu einem durchschlagenden Erfolg machen. Denn die nationale Petition kann die Position der Regierung in Br\u00fcssel unterst\u00fctzen, die im Einklang mit den ungarischen Interessen steht&#8221;, schloss er.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Europ\u00e4ische Union hat bei ihrem Au\u00dfenministertreffen am Montag in Br\u00fcssel keine Einigung \u00fcber ihr j\u00fcngstes Sanktionspaket gegen Russland erzielt. Die EU-Au\u00dfenbeauftragte Kaja Kallas nannte das Ergebnis einen &#8220;R\u00fcckschlag&#8221;, versprach aber, die Arbeit fortzusetzen. Das 20. Russland-Sanktionspaket wurde mit einem Veto belegt &#8220;Leider haben wir keine Einigung \u00fcber das 20. Sanktionspaket erzielt. Das ist ein [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":784264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[4484],"tags":[4366,4460,4372,1772,1178,1084,1209,1173,1092,1102,1076],"class_list":["post-784263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energy","tag-category-business","tag-category-eu-relations","tag-category-politics","tag-european-union","tag-inpr","tag-krieg-in-der-ukraine","tag-russland","tag-slowakei","tag-ukraine","tag-ungarische-regierung","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"api","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"yes","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"default","telegram_post":"","_xlat_group_id":"70805087-8040-4852-8bb7-20efdf5ab511"},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"Die rechtsgerichtete ungarische und die sozialistische slowakische Regierung haben ihr Veto gegen das neue Russland-Sanktionspaket eingelegt.","focus_keyword":"Russland-Sanktionspaket","canonical_url":"","robots":"","primary_category":"4484","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"61","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/784263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=784263"}],"version-history":[{"count":1,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/784263\/revisions"}],"predecessor-version":[{"id":784293,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/784263\/revisions\/784293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/784264"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=784263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=784263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=784263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}