{"id":785776,"date":"2026-04-04T09:04:00","date_gmt":"2026-04-04T07:04:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/der-ungarische-geheimdienst-hat-zugegebenermasen-einen-die-theiss-partei-unterstutzenden-geschaftsmann-uberwacht\/"},"modified":"2026-04-04T09:04:00","modified_gmt":"2026-04-04T07:04:00","slug":"der-ungarische-geheimdienst-hat-zugegebenermasen-einen-die-theiss-partei-unterstutzenden-geschaftsmann-uberwacht","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/der-ungarische-geheimdienst-hat-zugegebenermasen-einen-die-theiss-partei-unterstutzenden-geschaftsmann-uberwacht\/","title":{"rendered":"Der ungarische Geheimdienst hat zugegebenerma\u00dfen einen die Theiss-Partei unterst\u00fctzenden Gesch\u00e4ftsmann \u00fcberwacht"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Der ungarische Verfassungsschutz (Alkotm\u00e1nyv\u00e9delmi Hivatal, AH) ist erneut ins Visier geraten, nachdem berichtet wurde, dass er einen Gesch\u00e4ftsmann \u00fcberwacht hat, der Verbindungen zu oppositionellen Kreisen hatte, darunter auch zu Personen, die mit der Thei\u00df-Partei in Verbindung stehen.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der als F. bekannte Gesch\u00e4ftsmann wurde vom Geheimdienst \u00fcberwacht<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Laut Dokumenten, die investigative Journalisten erhalten haben, wurde der Gesch\u00e4ftsmann &#8211; genannt &#8220;F.&#8221; &#8211; zwischen Ende 2024 und Anfang 2025 unter Beobachtung. In dieser Zeit soll er Kontakte zu politischen und wirtschaftlichen Akteuren unterhalten und dabei geholfen haben, Treffen mit Oppositionellen und Freiwilligen zu arrangieren, die mit der entstehenden Thei\u00df-Partei in Verbindung stehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Existenz der \u00dcberwachung wurde von der AH selbst best\u00e4tigt, die angab, dass der Gesch\u00e4ftsmann im Rahmen eines laufenden Verfahrens in ihren Zust\u00e4ndigkeitsbereich geraten war, was eine rechtliche Grundlage f\u00fcr die \u00dcberwachungst\u00e4tigkeit darstellte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Falls Sie es verpasst haben sollten, lesen Sie hier, warum die Rekordzahl von <a href=\"https:\/\/dailynewshungary.com\/de\/warum-die-rekordzahl-an-auslands-und-umzugsstimmen-der-theis-partei-auftrieb-geben-konnte\/\/\">Wahlregistrierungen<\/a> aus dem Ausland und von <a href=\"https:\/\/dailynewshungary.com\/de\/warum-die-rekordzahl-an-auslands-und-umzugsstimmen-der-theis-partei-auftrieb-geben-konnte\/\/\">Transferw\u00e4hlern der ungarischen Theiss-Partei Auftrieb geben k\u00f6nnte<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Durchgesickerte Mitteilungen und das Etikett &#8220;MP<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eines der Schl\u00fcsseldokumente, das an <a href=\"https:\/\/444.hu\/2026\/04\/04\/kuldom-a-heti-mp-s-informaciokat-ezzel-kuldtek-egy-lehallgatas-reszleteit-egymasnak-az-alkotmanyvedelmi-hivatal-munkatarsai?utm_source=rss_feed&amp;utm_medium=rss&amp;utm_campaign=rss_syndication\" target=\"_blank\" rel=\"noopener\">444<\/a> gesendet wurde, ist eine interne E-Mail, die Telefonanrufe und Textnachrichten im Zusammenhang mit dem Gesch\u00e4ftsmann zusammenfasst. Die Nachricht begann angeblich mit der Zeile: &#8220;Liebe Kollegen, ich sende Ihnen die w\u00f6chentlichen MP-Informationen&#8221;, gefolgt von Ausz\u00fcgen aus Gespr\u00e4chen und Terminvereinbarungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Abk\u00fcrzung &#8220;MP&#8221; ist zu einem zentralen Punkt der Kontroverse geworden. W\u00e4hrend viele Beobachter vermuten, dass es sich um den Oppositionellen P\u00e9ter Magyar handelt, besteht die AH darauf, dass es f\u00fcr &#8220;Hungarian Proliferation&#8221; steht, ein Begriff, der mit der Verbreitung von Massenvernichtungswaffen und Technologien mit doppeltem Verwendungszweck verbunden ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mehrere Quellen, die mit den nationalen Sicherheitspraktiken vertraut sind, haben diese Erkl\u00e4rung jedoch in Frage gestellt und darauf hingewiesen, dass sich die abgeh\u00f6rten Gespr\u00e4che weitgehend auf politische Netzwerke zu konzentrieren scheinen und nicht auf Aktivit\u00e4ten, die mit Waffenhandel oder Verbreitungsrisiken zu tun haben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insider-Bombe aus Ungarns Milit\u00e4r: <a href=\"https:\/\/dailynewshungary.com\/de\/insider-bombe-aus-ungarns-militar-offizier-der-verteidigungsstreitkrafte-uber-moralkollaps-und-massenaustritte\/\/\">Offizier der Verteidigungsstreitkr\u00e4fte \u00fcber Zusammenbruch der Moral und Massenaustritte<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Art der abgeh\u00f6rten Gespr\u00e4che<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Abschriften enthalten angeblich logistische Diskussionen \u00fcber Treffen mit Oppositionsanh\u00e4ngern sowie ein privates Gespr\u00e4ch, in dem der Gesch\u00e4ftsmann und ein Freund beil\u00e4ufig \u00fcber die politische Landschaft Ungarns sprachen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Themen waren unter anderem die St\u00e4rke der regierenden Fidesz-Partei, die Aussichten des Vorsitzenden der Thei\u00df-Partei, P\u00e9ter Magyar, und Ministerpr\u00e4sident Viktor Orb\u00e1n. Kritiker argumentieren, dass die Aufnahme eines solchen Austauschs Bedenken dar\u00fcber aufkommen l\u00e4sst, ob nachrichtendienstliche Instrumente zur \u00dcberwachung politischer Aktivit\u00e4ten und nicht f\u00fcr echte Bedrohungen der nationalen Sicherheit eingesetzt wurden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mehr Ungarn glauben nun, dass <a href=\"https:\/\/dailynewshungary.com\/de\/mehr-ungarn-glauben-jetzt-dass-orban-verlieren-konnte-da-die-theis-partei-10-tage-vor-der-wahl-in-fuhrung-geht\/\/\">Orb\u00e1n verlieren k\u00f6nnte<\/a>, da die Theiss-Partei 10 Tage vor der Wahl in F\u00fchrung geht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Geheimdienstpraktiken in Frage gestellt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine weitere Kontroverse betrifft die Methode der Informationsweitergabe. Sicherheitsexperten, die in den Berichten zitiert werden, weisen darauf hin, dass es h\u00f6chst ungew\u00f6hnlich ist, sensibles \u00dcberwachungsmaterial \u00fcber interne E-Mails zu verbreiten, selbst \u00fcber sichere Netzwerke, da solche Daten normalerweise \u00fcber geheime und streng kontrollierte Kan\u00e4le gehandhabt werden. Dies hat zu Spekulationen \u00fcber interne Verfahren gef\u00fchrt und dar\u00fcber, ob die Protokolle ordnungsgem\u00e4\u00df befolgt wurden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Politische Reaktionen und weitergehende Auswirkungen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Tisza-Partei r\u00e4umte ein, dass der Gesch\u00e4ftsmann zuvor Treffen f\u00fcr einige ihrer Mitglieder organisiert hatte, erkl\u00e4rte jedoch, dass die Verbindungen inzwischen abgebrochen worden seien. Die Theiss-Partei kritisierte die angebliche \u00dcberwachung scharf und bezeichnete sie als schwerwiegenden Machtmissbrauch und Teil eines umfassenderen Musters der politischen Einmischung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Zwischenzeit betonte ein Vertreter der AH, dass die Nachrichtendienste unabh\u00e4ngig vom politischen Umfeld weiterarbeiten m\u00fcssen und r\u00e4umte ein, dass die Situation die Agentur in eine schwierige Lage gebracht hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Gekennzeichnetes Bild: <a href=\"https:\/\/www.facebook.com\/photo.php?fbid=24848527114755069&amp;set=pb.100000733720126.-2207520000&amp;type=3\" target=\"_blank\" rel=\"noopener\">P\u00e9ter Magyar\/Facebook<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der ungarische Verfassungsschutz (Alkotm\u00e1nyv\u00e9delmi Hivatal, AH) ist erneut ins Visier geraten, nachdem berichtet wurde, dass er einen Gesch\u00e4ftsmann \u00fcberwacht hat, der Verbindungen zu oppositionellen Kreisen hatte, darunter auch zu Personen, die mit der Thei\u00df-Partei in Verbindung stehen. Der als F. bekannte Gesch\u00e4ftsmann wurde vom Geheimdienst \u00fcberwacht Laut Dokumenten, die investigative Journalisten erhalten haben, wurde der [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":785777,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[4396],"tags":[1091,2026,4483,1313,1102,1076],"class_list":["post-785776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ungarisch","tag-fidesz","tag-kategorie-politik","tag-kategorie-ungarische-parlamentswahlen-2026","tag-peter-magyar-und-die-theiss-partei","tag-ungarische-regierung","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"api","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":"92e4780a-5c1a-4563-8dd4-5cb037d65650"},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Thei\u00df Partei","canonical_url":"","robots":"","primary_category":"4396","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"76","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/785776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=785776"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/785776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/785777"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=785776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=785776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=785776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}