{"id":787683,"date":"2026-05-13T13:44:00","date_gmt":"2026-05-13T11:44:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ehemaliger-premierminister-orban-lobt-das-ausergewohnliche-ungarische-wirtschaftswachstum-unter-seiner-fuhrung-und-bezeichnet-die-magyarische-regierung-als-liberales-kabinett\/"},"modified":"2026-05-13T16:47:54","modified_gmt":"2026-05-13T14:47:54","slug":"ehemaliger-premierminister-orban-lobt-das-ausergewohnliche-ungarische-wirtschaftswachstum-unter-seiner-fuhrung-und-bezeichnet-die-magyarische-regierung-als-liberales-kabinett","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ehemaliger-premierminister-orban-lobt-das-ausergewohnliche-ungarische-wirtschaftswachstum-unter-seiner-fuhrung-und-bezeichnet-die-magyarische-regierung-als-liberales-kabinett\/","title":{"rendered":"Ehemaliger Premierminister Orb\u00e1n lobt das au\u00dfergew\u00f6hnliche ungarische Wirtschaftswachstum unter seiner F\u00fchrung und bezeichnet die magyarische Regierung als liberales Kabinett"},"content":{"rendered":"<p><strong>Ungarn hat jetzt eine liberale Regierung, und die scheidende patriotische Regierung hat eine Bilanz ihrer Leistungen gezogen, sagte Viktor Orb\u00e1n, der ehemalige Premierminister, in einem Video, das am Mittwoch in den sozialen Medien ver\u00f6ffentlicht wurde.<\/strong><\/p>\n\n\n\n<p>Orb\u00e1n <a href=\"https:\/\/mti.hu\/en\/articles\/2026\/05\/13\/orban-hungary-under-liberal-leadership\" target=\"_blank\" rel=\"noopener\">sagte,<\/a> zu den Errungenschaften seiner Regierung geh\u00f6re, dass Ungarns Wirtschaftswachstum an zweiter Stelle in der Europ\u00e4ischen Union stehe und seine <em>&#8220;arbeitsorientierte Wirtschaftspolitik seit 2010 eine Million Arbeitspl\u00e4tze geschaffen hat&#8221;.<\/em><\/p>\n\n\n\n<p>Er verwies auf Steuerbefreiungen f\u00fcr Familien, die Kinder erziehen, und auf die PIT-Befreiung f\u00fcr M\u00fctter mit mehr als einem Kind. Als weitere Errungenschaften seiner Regierung nannte er die PIT-Befreiung f\u00fcr junge Menschen unter 25 Jahren, Studenten- und Arbeitnehmerdarlehen und die 3-Prozent-Hypothek mit festem Zinssatz sowie die Preissenkung f\u00fcr Versorgungsunternehmen und die Rente f\u00fcr den 13. und 14.<\/p>\n\n\n\n<p>Orb\u00e1n sagte, dass der Mindestlohn seit 2010 um das 4,5-fache und der Durchschnittslohn um das Vierfache gestiegen sei. Der Durchschnittslohn von \u00c4rzten liege jetzt bei rund 2 Millionen Forint (5.600 Euro) und der von Lehrern bei fast einer Million, f\u00fcgte er hinzu.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Orb\u00e1n stolz auf Flughafenkauf, Auslands- und Goldreserven<\/h2>\n\n\n\n<p>Er sagte, dass die vorherige Regierung das Staatsverm\u00f6gen verdoppelt habe. &#8220;Wir haben den Flughafen [Liszt International] und die Energieunternehmen von Ausl\u00e4ndern zur\u00fcckgekauft und die ungarischen Goldreserven von 3 Tonnen auf mehr als 100 Tonnen erh\u00f6ht. Die Devisenreserven sind die h\u00f6chsten in der Geschichte&#8221;, sagte er.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/dailynewshungary.b-cdn.net\/wp-content\/uploads\/2026\/03\/Orban-Viktor-4.webp\" alt=\"Orb\u00e1n Viktor ukraine\" class=\"wp-image-692266\"\/><figcaption class=\"wp-element-caption\">Foto: <a href=\"https:\/\/www.facebook.com\/photo.php?fbid=1497622675068659&amp;set=pb.100044628210344.-2207520000&amp;type=3\" target=\"_blank\" rel=\"noopener\">Facebook\/Orb\u00e1n Viktor<\/a><\/figcaption><\/figure>\n\n<p><em>&#8220;Ungarn ist heute das sicherste europ\u00e4ische Land, und es gibt keine Migranten auf seinem Territorium. Das ist der Ausgangspunkt der liberalen Regierung&#8221;,<\/em> sagte er.<\/p>\n\n\n\n<p><em>&#8220;Unsere Erfolgsbilanz spricht f\u00fcr sich selbst. Von heute an wird Ungarn von einer liberalen Regierung gef\u00fchrt. Hoffen wir, dass sie nicht verspielt, was unsere patriotischen Kr\u00e4fte in den letzten 16 Jahren aufgebaut haben<\/em>&#8220;, sagte Orb\u00e1n in einem englischsprachigen Beitrag auf X.<\/p>\n\n\n\n<p><strong>Falls Sie es verpasst haben:<\/strong><\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background\"><strong><a href=\"https:\/\/dailynewshungary.com\/de\/breaking-anita-orban-kundigt-grosen-ausenpolitischen-kurswechsel-an-und-spricht-uber-eu-gelder-migration-eu-forderungen-und-ungarische-truppen-in-der-ukraine\/\/\">Anita Orb\u00e1n k\u00fcndigt gro\u00dfen au\u00dfenpolitischen Kurswechsel an<\/a>, diskutiert \u00fcber EU-Gelder, Migration, EU-Forderungen, ungarische Truppen in der Ukraine<\/strong><br><br><strong>Tisza will die ungarische Wirtschaft umkrempeln: <a href=\"https:\/\/dailynewshungary.com\/de\/tisza-will-die-ungarische-wirtschaft-umkrempeln-preisobergrenzen-mitnahmeeffekte-mehrwertsteuersenkungen-freier-wettbewerb-der-ungarische-euro-und-russisches-ol\/\/\">Preisobergrenzen, Mitnahmeeffekte, Mehrwertsteuersenkungen, freier Wettbewerb, der ungarische Euro und russisches \u00d6l<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ungarn hat jetzt eine liberale Regierung, und die scheidende patriotische Regierung hat eine Bilanz ihrer Leistungen gezogen, sagte Viktor Orb\u00e1n, der ehemalige Premierminister, in einem Video, das am Mittwoch in den sozialen Medien ver\u00f6ffentlicht wurde. Orb\u00e1n sagte, zu den Errungenschaften seiner Regierung geh\u00f6re, dass Ungarns Wirtschaftswachstum an zweiter Stelle in der Europ\u00e4ischen Union stehe und [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":787684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":""},"categories":[4396],"tags":[4372,4273,1066,4687],"class_list":["post-787683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ungarisch","tag-category-politics","tag-ce","tag-hungary","tag-orban-government"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"default","telegram_post":"","_xlat_group_id":"9c07b1f1-7b1d-43fc-beeb-b104b36c845b"},"public_rank_math_data":{"title":"Ehemaliger Premierminister Orb\u00e1n behauptet, die Regierung von P\u00e9ter Magyar sei liberal","description":"Ungarn wird jetzt von einer liberalen Regierung regiert, und die scheidende patriotische Regierung hat eine Bilanz ihrer Errungenschaften gezogen, so Orb\u00e1n.","focus_keyword":"Orb\u00e1n","canonical_url":"","robots":"","primary_category":"4396","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"77","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/787683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=787683"}],"version-history":[{"count":1,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/787683\/revisions"}],"predecessor-version":[{"id":787686,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/787683\/revisions\/787686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/787684"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=787683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=787683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=787683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}