{"id":787799,"date":"2026-05-15T16:24:00","date_gmt":"2026-05-15T14:24:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ungarisches-reiseburo-bricht-zusammen-hunderte-von-kunden-fordern-ruckerstattung\/"},"modified":"2026-05-15T16:24:00","modified_gmt":"2026-05-15T14:24:00","slug":"ungarisches-reiseburo-bricht-zusammen-hunderte-von-kunden-fordern-ruckerstattung","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ungarisches-reiseburo-bricht-zusammen-hunderte-von-kunden-fordern-ruckerstattung\/","title":{"rendered":"Ungarisches Reiseb\u00fcro bricht zusammen, Hunderte von Kunden fordern R\u00fcckerstattung"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Ein ungarisches Reiseb\u00fcro ist faktisch zusammengebrochen, nachdem ihm die Betriebslizenz entzogen wurde, so dass m\u00f6glicherweise Hunderte von Kunden im Ungewissen \u00fcber Erstattungen und Entsch\u00e4digungen sind. Die Zahl der betroffenen Reisenden k\u00f6nnte bereits 400 \u00fcbersteigen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Travel Teachers Kft. hat seine Kunden per E-Mail dar\u00fcber informiert, dass das Budapester Regierungsamt dem Unternehmen die Lizenz als Reiseveranstalter mit Wirkung zum 30. April 2026 entzogen hat. Das bedeutet, dass das Reiseb\u00fcro nach diesem Datum nicht mehr legal Reisen organisieren darf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Gesch\u00e4ftsf\u00fchrer und Inhaber des Unternehmens erkl\u00e4rte, dass einer der Hauptgr\u00fcnde f\u00fcr die Krise der Verlust des professionellen Managers des Unternehmens ab dem 24. M\u00e4rz 2026 war, eine zwingende Voraussetzung f\u00fcr die T\u00e4tigkeit als Reiseveranstalter in Ungarn. Trotz der Versuche, das Problem zu l\u00f6sen, sagte das Unternehmen, dass es nicht in der Lage sei, die rechtlichen Bedingungen zu erf\u00fcllen, um den Betrieb fortzusetzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gleichzeitig verzeichnete die Agentur Berichten zufolge ein erhebliches Umsatzwachstum, das eine Erh\u00f6hung der gesetzlich vorgeschriebenen finanziellen Sicherheitsleistung erforderlich machte, <a href=\"https:\/\/utazomajom.hu\/becsodolt-egy-magyar-utazasi-iroda\/\" target=\"_blank\" rel=\"noopener\">schreibt Utaz\u00f3majom<\/a>. Nach Angaben des Unternehmens stellten die Versicherer zus\u00e4tzliche finanzielle Bedingungen, die es realistischerweise nicht mehr erf\u00fcllen konnte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fl\u00fcge und Unterkunft bereits bezahlt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Travel Teachers behauptete, dass viele anstehende Reisen bereits im Voraus vorbereitet worden waren. In mehreren F\u00e4llen waren die Flugtickets bereits gekauft, die Unterk\u00fcnfte gebucht und bezahlt und die Partnerunternehmen entsch\u00e4digt worden, um sicherzustellen, dass die Reisen in der erwarteten Qualit\u00e4t stattfinden konnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Unternehmen argumentierte jedoch, dass negative Diskussionen und Panik, die sich in den sozialen Medien und auf Online-Plattformen schnell verbreiteten, einen schweren Vertrauensverlust bei den Kunden ausl\u00f6sten. Laut der Erkl\u00e4rung f\u00fchrte dies zu einer Welle von gleichzeitigen R\u00fcckerstattungsantr\u00e4gen, die die Liquidit\u00e4t des Unternehmens au\u00dferordentlich belasteten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/travelteachers.hu\/\" target=\"_blank\" rel=\"noopener\">Die Website des Reiseb\u00fcros<\/a> wird derzeit gewartet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entsch\u00e4digungsverfahren ist unklar<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Situation rund um die Entsch\u00e4digung ist sehr ungewiss.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Travel Teachers erkl\u00e4rte, dass alle Unterlagen im Zusammenhang mit Reisevertr\u00e4gen und Kundenzahlungen an die Beh\u00f6rden \u00fcbergeben w\u00fcrden, die das Material dann an die Eur\u00f3pai Utaz\u00e1si Biztos\u00edt\u00f3 Zrt. (EUB) WEITERLEITET.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die EUB <a href=\"https:\/\/eub.hu\/dokumentumok\/Fontos_informaciok_a_Travel_Teachers_Kft-vel_kapcsolatban.pdf\" target=\"_blank\" rel=\"noopener\">teilte<\/a> jedoch auf ihrer Website <a href=\"https:\/\/eub.hu\/dokumentumok\/Fontos_informaciok_a_Travel_Teachers_Kft-vel_kapcsolatban.pdf\" target=\"_blank\" rel=\"noopener\">mit<\/a>, dass das Budapester Regierungsamt den Versicherer nicht erm\u00e4chtigt habe, mit den Erstattungen zu beginnen. Daher erkl\u00e4rte der Versicherer, dass derzeit keine Entsch\u00e4digungsverpflichtung bestehe und riet den Kunden, sich bei Anspr\u00fcchen direkt an das Reiseb\u00fcro zu wenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Zwischenzeit best\u00e4tigte das Budapester Regierungsb\u00fcro den betroffenen Kunden, dass es bis zum 14. Mai um 13:32 Uhr keine offizielle Mitteilung des Gesch\u00e4ftsf\u00fchrers des Unternehmens \u00fcber die Insolvenz oder die Unf\u00e4higkeit zur R\u00fcckzahlung an die Reisenden erhalten hatte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Angaben eines betroffenen Kunden erkl\u00e4rten die Beh\u00f6rden, dass sie derzeit keine Anhaltspunkte daf\u00fcr haben, dass Travel Teachers nicht in der Lage ist, Vorsch\u00fcsse und Teilnahmegeb\u00fchren f\u00fcr Reisen zu erstatten, die rechtlich nicht mehr durchgef\u00fchrt werden k\u00f6nnen. Folglich ist zum jetzigen Zeitpunkt weder die Entsch\u00e4digungsfunktion des Versicherers noch eine direkte Intervention der Regierung offiziell ausgel\u00f6st worden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Facebook-Gruppen f\u00fcr betroffene Reisende wachsen schnell<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Frustrierte Kunden haben bereits begonnen, sich online zu organisieren. <a href=\"https:\/\/www.facebook.com\/groups\/35917683031155952\" target=\"_blank\" rel=\"noopener\">Eine<\/a> f\u00fcr betroffene Reisende eingerichtete <a href=\"https:\/\/www.facebook.com\/groups\/35917683031155952\" target=\"_blank\" rel=\"noopener\">Facebook-Gruppe<\/a> hat am 15. Mai um 16 Uhr 354 Mitglieder, eine andere <a href=\"https:\/\/www.facebook.com\/groups\/840641269084019\" target=\"_blank\" rel=\"noopener\">private Gruppe<\/a> hat 120 Teilnehmer.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-paragraph\"><strong>Falls Sie es verpasst haben: <a href=\"https:\/\/dailynewshungary.com\/de\/40-jahriges-reiseburo-in-ungarn-von-auslandischem-verlustbringendem-konkurrenten-ermordet\/\/\">40 Jahre altes Reiseb\u00fcro in Ungarn von ausl\u00e4ndischem, verlustbringendem Konkurrenten &#8220;ermordet&#8221;?<\/a><\/strong><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ein ungarisches Reiseb\u00fcro ist faktisch zusammengebrochen, nachdem ihm die Betriebslizenz entzogen wurde, so dass m\u00f6glicherweise Hunderte von Kunden im Ungewissen \u00fcber Erstattungen und Entsch\u00e4digungen sind. Die Zahl der betroffenen Reisenden k\u00f6nnte bereits 400 \u00fcbersteigen. Travel Teachers Kft. hat seine Kunden per E-Mail dar\u00fcber informiert, dass das Budapester Regierungsamt dem Unternehmen die Lizenz als Reiseveranstalter mit [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":787800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[4393],"tags":[1066,1292,1298],"class_list":["post-787799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-travel","tag-hungary","tag-money","tag-travel"],"blocksy_meta":[],"acf":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":"9b7ede65-b712-44e0-ae77-f6bd37997cee"},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"reiseb\u00fcro","canonical_url":"","robots":"","primary_category":"4393","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"80","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/787799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=787799"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/787799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/787800"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=787799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=787799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=787799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}