{"id":788583,"date":"2026-06-03T16:54:00","date_gmt":"2026-06-03T14:54:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/bmw-debrecen-spricht-von-neuen-schichten-wegen-der-enormen-nachfrage-nach-dem-modell-bmw-ix3\/"},"modified":"2026-06-04T08:52:55","modified_gmt":"2026-06-04T06:52:55","slug":"bmw-debrecen-spricht-von-neuen-schichten-wegen-der-enormen-nachfrage-nach-dem-modell-bmw-ix3","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/bmw-debrecen-spricht-von-neuen-schichten-wegen-der-enormen-nachfrage-nach-dem-modell-bmw-ix3\/","title":{"rendered":"BMW Debrecen spricht von neuen Schichten wegen der enormen Nachfrage nach dem Modell BMW iX3"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Der deutsche Automobilhersteller BMW wird in seinem neuen Werk in Ungarn wahrscheinlich zus\u00e4tzliche Schichten einrichten, um der &#8220;enormen Nachfrage&#8221; gerecht zu werden, sagte der Leiter des BMW Group Werks Debrecen am Dienstag auf einer internationalen Pressekonferenz.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hans-Peter Kemser sagte, das Werk arbeite derzeit im Zweischichtbetrieb und produziere 30 Autos pro Stunde. Er f\u00fcgte hinzu, dass innerhalb von nur sechs Monaten mehr als 50.000 Bestellungen f\u00fcr das vollelektrische <a href=\"https:\/\/dailynewshungary.com\/de\/bmw-ix3-ruckruf-elektro-gelandewagen-aus-debrecen-als-potenziell-gefahrlich-eingestuft\/\/\">Modell BMW iX3<\/a>, das das Werk herstellt, eingegangen seien, <a href=\"https:\/\/mti.hu\/en\/articles\/2026\/06\/03\/bmw-debrecen-could-add-shifts-meet-demand\" target=\"_blank\" rel=\"noopener\">schrieb MTI<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der BMW iX3 ist das erste Modell der Neuen Klasse, das in die Serienproduktion geht. BMW plant, in Zukunft rund 40 weitere Modelle auf den Markt zu bringen, die weltweit produziert werden sollen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">BMW er\u00f6ffnete sein mehr als 2 Milliarden Euro teures Werk in Debrecen im Herbst 2025. Dort werden j\u00e4hrlich rund 150.000 Elektroautos vom Band laufen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Werk in Debrecen ist der erste von f\u00fcnf BMW Produktionsstandorten auf der ganzen Welt, in denen die Batterien vor Ort zusammengebaut werden, um die Lieferketten zu verk\u00fcrzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kemser hob das Engagement des BMW Group Werks Debrecen f\u00fcr seine Mitarbeiter, f\u00fcr die Ausbildung und f\u00fcr langfristige Partnerschaften hervor und verwies auf eine externe Fakult\u00e4t der Universit\u00e4t von Debrecen, die am Standort t\u00e4tig ist.<\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-paragraph\"><strong>Falls Sie es verpasst haben: <a href=\"https:\/\/dailynewshungary.com\/de\/schockierendes-video-zeigt-wie-ein-bmw-in-einen-spielplatz-pflugt-auf-dem-kinder-spielten\/\/\">Schockierendes Video zeigt einen BMW, der in einen Spielplatz pfl\u00fcgt<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Titelbild: <a href=\"https:\/\/depositphotos.com\/editorial\/paris-oct-2018-bmw-ix3-electric-suv-car-showcased-paris-220956030.html\" target=\"_blank\" rel=\"noopener\">depositphotos<\/a>.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der deutsche Automobilhersteller BMW wird in seinem neuen Werk in Ungarn wahrscheinlich zus\u00e4tzliche Schichten einrichten, um der &#8220;enormen Nachfrage&#8221; gerecht zu werden, sagte der Leiter des BMW Group Werks Debrecen am Dienstag auf einer internationalen Pressekonferenz. Hans-Peter Kemser sagte, das Werk arbeite derzeit im Zweischichtbetrieb und produziere 30 Autos pro Stunde. Er f\u00fcgte hinzu, dass [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":788584,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[4398],"tags":[4706,4366,4273,1116,1683],"class_list":["post-788583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economy","tag-car-industry","tag-category-business","tag-ce","tag-debrecen","tag-hungarian-economy"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"default","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"BMW Debrecen spricht von neuen Schichten aufgrund der enormen Nachfrage","description":"Der deutsche Automobilhersteller BMW wird in seinem neuen Werk in Ungarn wahrscheinlich zus\u00e4tzliche Schichten einrichten, um die \"enorme Nachfrage\" zu befriedigen.","focus_keyword":"BMW","canonical_url":"","robots":"","primary_category":"4398","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"64","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/788583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=788583"}],"version-history":[{"count":1,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/788583\/revisions"}],"predecessor-version":[{"id":788609,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/788583\/revisions\/788609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/788584"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=788583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=788583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=788583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}