{"id":789355,"date":"2026-06-21T14:14:00","date_gmt":"2026-06-21T12:14:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/die-ungarische-ausenministerin-anita-orban-erklart-dass-dokumente-vor-dem-regierungswechsel-von-szijjartos-team-geschreddert-wurden\/"},"modified":"2026-06-22T09:24:34","modified_gmt":"2026-06-22T07:24:34","slug":"die-ungarische-ausenministerin-anita-orban-erklart-dass-dokumente-vor-dem-regierungswechsel-von-szijjartos-team-geschreddert-wurden","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/die-ungarische-ausenministerin-anita-orban-erklart-dass-dokumente-vor-dem-regierungswechsel-von-szijjartos-team-geschreddert-wurden\/","title":{"rendered":"Die ungarische Au\u00dfenministerin Anita Orb\u00e1n erkl\u00e4rt, dass Dokumente vor dem Regierungswechsel von Szijj\u00e1rt\u00f3s Team geschreddert wurden"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Die ungarische Au\u00dfenministerin Anita Orb\u00e1n hat in einem Interview mit \u00d6sterreichs f\u00fchrender Tageszeitung <em>\u201eDer Standard\u201c<\/em> offenbart, dass im Ministerium f\u00fcr ausw\u00e4rtige Angelegenheiten und Handel \u201eziemlich viele\u201c Dokumente vernichtet wurden, bevor die neue Regierung ihr Amt antrat.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00d6sterreichisches Interview thematisiert vernichtete Akten, die Ukraine und die Energieabh\u00e4ngigkeit<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Orb\u00e1n gab w\u00e4hrend ihres j\u00fcngsten Besuchs in Wien ein gemeinsames Interview mit der \u00f6sterreichischen Au\u00dfenministerin Beate Meinl-Reisinger, in dem die beiden Ministerinnen \u00fcber regionale Zusammenarbeit, Ungarns Beziehungen zur Europ\u00e4ischen Union, Migration, die Ukraine und Energiesicherheit sprachen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die \u00f6sterreichische Zeitung stellte fest, dass die beiden Minister offenbar eine konstruktive Arbeitsbeziehung pflegen, und hob zugleich hervor, dass die neue ungarische Regierung versucht, internationale Partnerschaften wieder aufzubauen, die sich in den letzten Jahren verschlechtert hatten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einer der auff\u00e4lligsten Momente des Interviews ereignete sich, als <em><a href=\"https:\/\/www.derstandard.at\/consent\/tcf\/story\/3000000327836\/ungarns-neue-aussenministerin-da-wurde-so-einiges-geschreddert\" target=\"_blank\" rel=\"noopener\">\u201eDer Standard\u201c<\/a><\/em> Orb\u00e1n zu Berichten befragte, wonach im ungarischen Au\u00dfenministerium nach der Wahl, aber noch vor der offiziellen Macht\u00fcbergabe gro\u00dfe Mengen an Dokumenten vernichtet worden seien. Ihre Antwort fiel kurz, aber unmissverst\u00e4ndlich aus:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201eJa, es wurde ziemlich viel geschreddert.\u201c<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ministerin ging nicht n\u00e4her darauf ein, um welche Art von Dokumenten es sich handelte oder ob eine Untersuchung geplant ist.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Forbananita.tisza%2Fposts%2Fpfbid0ScHJfgbYRqU94S3GYBp2aX8SomJ1e5SXATiVkSo56PdSKR12z95pgmvn1xwqmDDGl&#038;show_text=false&#038;width=500\" width=\"500\" height=\"366\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">Wien lobt Ungarns Reformbem\u00fchungen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Mittelpunkt des Interviews standen zudem die Bem\u00fchungen Ungarns, die eingefrorenen EU-Mittel freizugeben. Meinl-Reisinger lobte das Tempo der von der neuen ungarischen Regierung eingeleiteten Reformen und beschrieb den Prozess als mit \u201eunglaublicher Geschwindigkeit\u201c voranschreitend. Sie betonte, dass Ungarn ein wichtiger Partner innerhalb der Europ\u00e4ischen Union sei, und hob die Bedeutung der St\u00e4rkung der Rechtsstaatlichkeit hervor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut Anita Orb\u00e1n steht Budapest vor einer anspruchsvollen Frist bis zum 31. August, um ein Reformpaket abzuschlie\u00dfen, das f\u00fcr die Freigabe der ausgesetzten EU-Mittel erforderlich ist. Sie hob Ma\u00dfnahmen hervor, darunter die geplante Abschaffung des Amtes zum Schutz der Souver\u00e4nit\u00e4t, neue Initiativen zur Korruptionsbek\u00e4mpfung sowie Ungarns Antrag auf Beitritt zur Europ\u00e4ischen Staatsanwaltschaft.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Neue Regierung strebt engere Zusammenarbeit in Migrationsfragen an<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das Thema Migration war ein weiterer Schwerpunkt der Diskussion. Orb\u00e1n erkl\u00e4rte, dass Ungarn weiterhin gegen illegale Migration eintrete und beabsichtige, strenge Grenzschutzma\u00dfnahmen beizubehalten. Sie argumentierte jedoch, dass sich der Ansatz der neuen Regierung erheblich von dem ihrer Vorg\u00e4ngerin unterscheide.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201eDer gro\u00dfe Unterschied zur vorherigen Regierung besteht darin, dass wir mit unseren Partnern zusammenarbeiten wollen\u201c, sagte sie.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Die \u00f6sterreichische Au\u00dfenministerin betonte, dass Migration nach wie vor eine gemeinsame europ\u00e4ische Herausforderung sei, die gemeinsame L\u00f6sungen erfordere, und \u00e4u\u00dferte zugleich die Hoffnung, dass die Kontrollen an den Binnengrenzen der EU letztendlich abgebaut werden k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wiederaufbau regionaler Partnerschaften<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Orb\u00e1n skizzierte zudem Pl\u00e4ne zur Wiederbelebung der regionalen Zusammenarbeit, insbesondere innerhalb der Visegr\u00e1d-Gruppe (V4), in der Ungarn, Polen, die Tschechische Republik und die Slowakei zusammengeschlossen sind. Sie best\u00e4tigte, dass die ungarische Regierung beabsichtige, dem B\u00fcndnis \u201eneue Energie\u201c zu verleihen, und verwies in diesem Zusammenhang auf ein bevorstehendes Treffen der vier Ministerpr\u00e4sidenten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>\u00d6sterreich hat sich in j\u00fcngster Zeit zu einem der engsten diplomatischen Partner Budapests in der Region entwickelt. W\u00e4hrend ihres Besuchs in Wien er\u00f6rterten Anita Orb\u00e1n und Beate Meinl-Reisinger die Vorbereitungen f\u00fcr k\u00fcnftige regionale Initiativen sowie eine neue Phase in den ungarisch-\u00f6sterreichischen Beziehungen.<\/p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><figcaption class=\"wp-element-caption\">\n<\/figcaption><img decoding=\"async\" src=\"https:\/\/dailynewshungary.b-cdn.net\/wp-content\/uploads\/2026\/06\/Beate-Meinl-Reisinger-Anita-Orban-1280x853.webp\" alt=\"Beate Meinl-Reisinger and Anita Orb\u00e1n austria hungary foreign affairs ministers\" class=\"wp-image-700070\"\/><figcaption class=\"wp-element-caption\">Beate Meinl-Reisinger und Anita Orb\u00e1n. Foto: <a href=\"https:\/\/www.facebook.com\/photo?fbid=122128898829205555&amp;set=pcb.122128898853205555\" target=\"_blank\" rel=\"noopener\">Facebook\/Orb\u00e1n Anita<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Die Abh\u00e4ngigkeit von russischer Energie bleibt eine Herausforderung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ministerinnen sprachen zudem die seit langem bestehende Abh\u00e4ngigkeit Ungarns von russischer Energie an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anita Orb\u00e1n r\u00e4umte ein, dass die neue Regierung erhebliche strukturelle Abh\u00e4ngigkeiten \u00fcbernommen habe, darunter die russische Nukleartechnologie im Kernkraftwerk Paks sowie umfangreiche \u00d6l- und Gasliefervertr\u00e4ge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie erkl\u00e4rte, die Regierung pr\u00fcfe derzeit diese Abh\u00e4ngigkeiten und setze sich dabei weiterhin f\u00fcr eine sichere und bezahlbare Energieversorgung ein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meinl-Reisinger argumentierte, Europa habe die Risiken einer zu starken Abh\u00e4ngigkeit von einem einzigen Lieferanten erkannt, und forderte gr\u00f6\u00dfere Investitionen in heimische und diversifizierte Energiequellen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ungarn \u00e4ndert seinen Kurs in Bezug auf die Ukraine<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In Bezug auf die Ukraine erkl\u00e4rte Orb\u00e1n, ihre Regierung habe bereits Verhandlungen aufgenommen, die auf eine Verbesserung der Lage der ungarischen Minderheit in Transkarpatien abzielen, und behauptete, bei Themen wie Bildung und Rechten in der \u00f6ffentlichen Verwaltung seien Fortschritte erzielt worden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie best\u00e4tigte zudem, dass Ungarn das Veto aufgehoben habe, das zuvor den Fortschritt im EU-Beitrittsprozess der Ukraine blockiert hatte. Die \u00f6sterreichische Ministerin ging noch einen Schritt weiter und argumentierte, die vorherige ungarische Regierung habe Bedenken hinsichtlich der Minderheitenrechte in erster Linie als politisches Instrument genutzt, um die europ\u00e4ische Integration der Ukraine zu behindern, anstatt sich ernsthaft mit dem Thema auseinanderzusetzen.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Forbananita.tisza%2Fposts%2Fpfbid0Sqw45nJGdqFm5c6zMP6MowAFQZNQarxTwPHZjrQ3Xz3EUQxkZRN8Z39SG8aKG7L3l&#038;show_text=true&#038;width=500\" width=\"500\" height=\"805\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-paragraph\"><strong>Haben Sie schon davon geh\u00f6rt? <a href=\"https:\/\/dailynewshungary.com\/de\/ungarns-parlament-schreitet-voran-vermogenssteuer-bildungsreform-regulierung-von-ki-und-sozialen-medien-fur-kinder\/\/\">Ungarns Parlament treibt Reformen voran: Verm\u00f6genssteuer, Bildungsreform, Regulierung von KI und sozialen Medien f\u00fcr Kinder<\/a><\/strong><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Direkte Kommunikation und Desinformation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das Interview endete mit einer Diskussion \u00fcber Desinformation und politische Kommunikation. Anita Orb\u00e1n verwies auf die landesweite Wahlkampftour von Ministerpr\u00e4sident P\u00e9ter Magyar und erkl\u00e4rte, der direkte Kontakt zu den W\u00e4hlern sei aufgrund des eingeschr\u00e4nkten Zugangs zu den staatlichen Medien vor der Wahl von entscheidender Bedeutung gewesen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meinl-Reisinger bezeichnete den Kampf gegen Desinformation als eine der gr\u00f6\u00dften politischen Herausforderungen Europas und wies darauf hin, dass die j\u00fcngsten Erfahrungen Ungarns zu den europ\u00e4ischen Bem\u00fchungen zur Bek\u00e4mpfung dieses Ph\u00e4nomens beitragen k\u00f6nnten.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-paragraph\"><strong>Falls Sie es verpasst haben: <a href=\"https:\/\/dailynewshungary.com\/de\/eine-arbeitsreiche-woche-fur-das-ungarische-ausenministerium-eu-gesprache-v4-diplomatie-treffen-in-osterreich-und-gipfel-in-brussel\/\/\">Eine arbeitsreiche Woche f\u00fcr das ungarische Au\u00dfenministerium: EU-Gespr\u00e4che, V4-Diplomatie, Treffen in \u00d6sterreich und Gipfel in Br\u00fcssel<\/a><\/strong><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Die ungarische Au\u00dfenministerin Anita Orb\u00e1n hat in einem Interview mit \u00d6sterreichs f\u00fchrender Tageszeitung \u201eDer Standard\u201c offenbart, dass im Ministerium f\u00fcr ausw\u00e4rtige Angelegenheiten und Handel \u201eziemlich viele\u201c Dokumente vernichtet wurden, bevor die neue Regierung ihr Amt antrat. \u00d6sterreichisches Interview thematisiert vernichtete Akten, die Ukraine und die Energieabh\u00e4ngigkeit Orb\u00e1n gab w\u00e4hrend ihres j\u00fcngsten Besuchs in Wien ein [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":789356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[4273,1082,4564,4482,1129,4673,4719,4715,1102,1076],"class_list":["post-789355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-ce","tag-europaische-union","tag-kategorie-ausenpolitik","tag-kategorie-ungarische-politik","tag-osterreich","tag-peter-magyar","tag-regierung-magyar","tag-regierung-orban","tag-ungarische-regierung","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"default","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Anita Orb\u00e1n","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"76","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/789355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=789355"}],"version-history":[{"count":1,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/789355\/revisions"}],"predecessor-version":[{"id":789377,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/789355\/revisions\/789377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/789356"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=789355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=789355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=789355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}