{"id":789547,"date":"2026-06-24T20:12:35","date_gmt":"2026-06-24T18:12:35","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/eilmeldung-ungarisches-kind-sturzte-von-einem-aussichtspunkt-am-schloss-bled\/"},"modified":"2026-06-25T09:17:28","modified_gmt":"2026-06-25T07:17:28","slug":"eilmeldung-ungarisches-kind-sturzte-von-einem-aussichtspunkt-am-schloss-bled","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/eilmeldung-ungarisches-kind-sturzte-von-einem-aussichtspunkt-am-schloss-bled\/","title":{"rendered":"Eilmeldung \u2013 Ungarisches Kind st\u00fcrzte von einem Aussichtspunkt am Schloss Bled"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Ein ungarisches Kind wurde am Mittwoch schwer verletzt, nachdem es von einem Aussichtspunkt in der N\u00e4he der Burg Bled in Slowenien gest\u00fcrzt war, teilte die \u00f6rtliche Polizei mit.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ersten Berichten zufolge war die ungarische Familie auf einem Weg in der N\u00e4he der Burg unterwegs, als das Kind am Aussichtspunkt ausrutschte, \u00fcber die Mauer st\u00fcrzte und den steilen Abhang hinunterrollte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>Das Kind wurde vor Ort erstversorgt und anschlie\u00dfend mit einem Milit\u00e4rhubschrauber ins Klinische Zentrum Ljubljana geflogen.<\/p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><figcaption class=\"wp-element-caption\">\n<\/figcaption><img decoding=\"async\" src=\"https:\/\/dailynewshungary.b-cdn.net\/wp-content\/uploads\/2026\/06\/Hungarian-child-fell-from-Bled-castle.webp\" alt=\"Hungarian child fell from Bled castle\" class=\"wp-image-700523\"\/><figcaption class=\"wp-element-caption\">Die Burg Bled aus der Vogelperspektive. Foto: <a href=\"https:\/\/depositphotos.com\/photo\/aerial-view-bled-castle-overlooking-lake-bled-slovenia-europe-500172714.html\" target=\"_blank\" rel=\"noopener\">depositphotos.com<\/a><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">An der Rettungsaktion waren Polizei, Rettungssanit\u00e4ter, Bergretter und ein Team des Luftrettungsdienstes beteiligt. Der Unfallort wurde von der Kriminalpolizei, einem Untersuchungsrichter und einem Staatsanwalt untersucht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Polizei <a href=\"https:\/\/mti.hu\/en\/articles\/2026\/06\/24\/hungarian-child-seriously-injured-fall-bled-castle\" target=\"_blank\" rel=\"noopener\">teilte mit<\/a>, dass sie die gesammelten Beweismittel an die Staatsanwaltschaft \u00fcbergeben werde, die \u00fcber etwaige weitere Ma\u00dfnahmen entscheiden werde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Falls Sie es verpasst haben:<\/strong><\/p>\n\n\n\n<p class=\"has-very-light-gray-to-cyan-bluish-gray-gradient-background has-background wp-block-paragraph\"><strong>Wie ist das m\u00f6glich? <a href=\"https:\/\/dailynewshungary.com\/de\/wie-ist-das-moglich-gericht-lasst-den-budapester-kannibalen-frei-er-kann-nun-weiterhin-menschliche-uberreste-sammeln\/\/\">Gericht l\u00e4sst den \u201eKannibalen von Budapest\u201c<\/a> frei \u2013 er kann weiterhin menschliche \u00dcberreste sammeln<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein ungarisches Kind wurde am Mittwoch schwer verletzt, nachdem es von einem Aussichtspunkt in der N\u00e4he der Burg Bled in Slowenien gest\u00fcrzt war, teilte die \u00f6rtliche Polizei mit. Ersten Berichten zufolge war die ungarische Familie auf einem Weg in der N\u00e4he der Burg unterwegs, als das Kind am Aussichtspunkt ausrutschte, \u00fcber die Mauer st\u00fcrzte und [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":789548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[4745],"tags":[4273,1502,1739],"class_list":["post-789547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reise","tag-ce","tag-kinder","tag-slowenien"],"blocksy_meta":[],"acf":[],"author_username":"ugyelet","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"no","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"default","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"Ungarisches Kind bei Sturz am Schloss Bled schwer verletzt","description":"Ein ungarisches Kind wurde am Mittwoch schwer verletzt, nachdem es von einem Aussichtspunkt in der N\u00e4he des Schlosses Bled in Slowenien gest\u00fcrzt war, teilte die \u00f6rtliche Polizei mit.","focus_keyword":"Bled","canonical_url":"","robots":"","primary_category":"4745","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"70","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/789547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=789547"}],"version-history":[{"count":1,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/789547\/revisions"}],"predecessor-version":[{"id":789559,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/789547\/revisions\/789559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/789548"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=789547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=789547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=789547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}