{"id":790332,"date":"2026-07-15T15:24:00","date_gmt":"2026-07-15T13:24:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/einige-ungarn-versuchen-krebs-mit-entwurmungsmitteln-fur-tiere-zu-behandeln-das-sagt-der-gesundheitsbeauftragte-dazu\/"},"modified":"2026-07-15T15:24:00","modified_gmt":"2026-07-15T13:24:00","slug":"einige-ungarn-versuchen-krebs-mit-entwurmungsmitteln-fur-tiere-zu-behandeln-das-sagt-der-gesundheitsbeauftragte-dazu","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/einige-ungarn-versuchen-krebs-mit-entwurmungsmitteln-fur-tiere-zu-behandeln-das-sagt-der-gesundheitsbeauftragte-dazu\/","title":{"rendered":"Einige Ungarn versuchen, Krebs mit Entwurmungsmitteln f\u00fcr Tiere zu behandeln: Das sagt der Gesundheitsbeauftragte dazu"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Ungarns oberster Gesundheitsbeauftragter hat davor gewarnt, dass manche Menschen tiermedizinische Entwurmungsmittel, die Ivermectin oder Fenbendazol enthalten, zur Behandlung von Krebs einsetzen. Er betonte, dass diese Produkte nicht f\u00fcr die Anwendung am Menschen zugelassen sind, keine wissenschaftlich nachgewiesene Wirkung gegen Krebs haben und die Gesundheit sowie die Heilungschancen der Patienten ernsthaft gef\u00e4hrden k\u00f6nnen.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Erkl\u00e4rung, die am Mittwoch von der obersten Gesundheitsbeauftragten Beatrix Oroszi abgegeben wurde, wurde zum Schutz von Krebspatienten ver\u00f6ffentlicht, nachdem sich in den sozialen Medien und in der Presse unverantwortliche Behauptungen verbreitet hatten, in denen tiermedizinische Antiparasitika als Behandlungsmittel f\u00fcr Krebserkrankungen beim Menschen beworben wurden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Warnung folgt auf die Enth\u00fcllung des Fitnessunternehmers Norbert Schobert in einem Interview auf dem YouTube-Kanal <a href=\"https:\/\/www.youtube.com\/watch?v=UyDMVhNy7tY\" target=\"_blank\" rel=\"noopener\">\u201eJeszenszky-kaland\u201c<\/a>, in dem er berichtete, dass er die Krebsbehandlung seiner Frau, R\u00e9ka Rubint, mit einem f\u00fcr Hunde und Katzen bestimmten Entwurmungsmittel erg\u00e4nzt habe. Schobert erkl\u00e4rte, er habe das Tierarzneimittel in einer Tierapotheke gekauft und es seiner Frau verabreicht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Es gibt keine wissenschaftlichen Belege f\u00fcr die behauptete Wirksamkeit bei der Krebsbehandlung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Oroszi r\u00e4umte ein, dass Krebspatienten und ihre Familien sich oft in einer besonders schutzbed\u00fcrftigen Lage befinden und nat\u00fcrlich jede m\u00f6gliche Behandlungsoption in Betracht ziehen m\u00f6chten. Sie betonte jedoch, dass Entscheidungen im Gesundheitswesen ausschlie\u00dflich auf glaubw\u00fcrdigen, wissenschaftlich belegten Erkenntnissen beruhen sollten und nicht auf unbegr\u00fcndeten Behauptungen, die im Internet kursieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach Angaben der medizinischen Leiterin liegen derzeit keine Ergebnisse klinischer Studien vor, die belegen, dass Ivermectin oder Fenbendazol sicher oder wirksam zur Behandlung von Krebs eingesetzt werden k\u00f6nnen. Daher ist keiner der beiden Wirkstoffe in den von ungarischen oder internationalen onkologischen Leitlinien empfohlenen Krebstherapien enthalten.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Sie betonte zudem, dass Tierarzneimittel nicht f\u00fcr die Anwendung am Menschen zugelassen sind und bei Einnahme durch Menschen ernsthafte Gesundheitsrisiken bergen k\u00f6nnen.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Das Aufschieben einer bew\u00e4hrten Behandlung kann die \u00dcberlebenschancen verringern<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In der Erkl\u00e4rung wurde ferner davor gewarnt, dass das Aufschieben oder Unterbrechen einer evidenzbasierten Krebsbehandlung zugunsten unbewiesener Alternativen die Heilungschancen eines Patienten erheblich verringern k\u00f6nnte. Oroszi warnte zudem davor, sich auf pers\u00f6nliche Erfahrungsberichte und individuelle Genesungsgeschichten zu verlassen, die in sozialen Medien geteilt werden, und wies darauf hin, dass solche Berichte keine wissenschaftlichen Beweise darstellen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201eDie Wirksamkeit und Sicherheit eines Arzneimittels oder einer Behandlung kann nur durch ordnungsgem\u00e4\u00df konzipierte klinische Studien nachgewiesen werden\u201c, sagte sie.<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Patienten werden dringend gebeten, ihren Arzt zu konsultieren<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Chief Medical Officer forderte Krebspatienten und ihre Angeh\u00f6rigen nachdr\u00fccklich auf, ihren behandelnden Arzt zu konsultieren, bevor sie ein neues Produkt einnehmen oder eine alternative Therapie ausprobieren. Sie wies darauf hin, dass der behandelnde Arzt mit dem Gesundheitszustand des Patienten, der laufenden Behandlung und den potenziellen Risiken vertraut sei und daher die einzige Person sei, die verantwortungsvolle, individuell abgestimmte medizinische Beratung leisten k\u00f6nne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oroszi f\u00fcgte hinzu, dass zuverl\u00e4ssige Gesundheitsinformationen von medizinischen Fachkr\u00e4ften, zust\u00e4ndigen Beh\u00f6rden und anerkannten Fachverb\u00e4nden stammen sollten, die ihre Empfehlungen alle auf wissenschaftliche Erkenntnisse, klinische Leitlinien und kontinuierlich ausgewertete medizinische Erfahrungen st\u00fctzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Warnung an Medien und Online-Influencer<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Chief Medical Officer forderte zudem die Medien, Pers\u00f6nlichkeiten des \u00f6ffentlichen Lebens und Ersteller von Online-Inhalten auf, bei der Diskussion gesundheitsbezogener Themen besondere Verantwortung zu zeigen. Sie warnte davor, dass wissenschaftlich unbegr\u00fcndete Behauptungen, die ein breites Publikum erreichen, die Entscheidungen von Patienten beeinflussen, falsche Hoffnungen wecken und letztendlich die sichere Patientenversorgung gef\u00e4hrden k\u00f6nnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oroszi f\u00fcgte hinzu, dass die ungarischen Gesundheitsbeh\u00f6rden Falschinformationen im Gesundheitsbereich weiterhin genau beobachten und alle verf\u00fcgbaren fachlichen und rechtlichen Mittel einsetzen werden, um Patienten zu sch\u00fctzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eDie Sicherheit von Krebspatienten ist eine gemeinsame Verantwortung. Unser vorrangiges Ziel ist es, sicherzustellen, dass jeder Patient Behandlungen und Informationen erh\u00e4lt, deren Wirksamkeit und Sicherheit durch wissenschaftliche Erkenntnisse belegt sind\u201c, erkl\u00e4rte die Chief Medical Officer.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-pale-ocean-gradient-background has-text-color has-background has-link-color wp-elements-9f72f51d85a155d724cb34b6df5d2d0a wp-block-paragraph\"><strong>Falls Sie es verpasst haben: <a href=\"https:\/\/dailynewshungary.com\/de\/mann-nach-gewaltsamem-eingreifen-der-ungarischen-polizei-bei-einer-identitatskontrolle-im-koma\/\/\">Mann nach gewaltsamem Eingreifen der ungarischen Polizei bei einer Identit\u00e4tskontrolle im Koma<\/a><\/strong><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ungarns oberster Gesundheitsbeauftragter hat davor gewarnt, dass manche Menschen tiermedizinische Entwurmungsmittel, die Ivermectin oder Fenbendazol enthalten, zur Behandlung von Krebs einsetzen. Er betonte, dass diese Produkte nicht f\u00fcr die Anwendung am Menschen zugelassen sind, keine wissenschaftlich nachgewiesene Wirkung gegen Krebs haben und die Gesundheit sowie die Heilungschancen der Patienten ernsthaft gef\u00e4hrden k\u00f6nnen. Die Erkl\u00e4rung, die [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":790333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[4406],"tags":[4891,4829,1099,1076],"class_list":["post-790332","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-gesundheitswesen","tag-kategorie-gesundheit-2","tag-tiere","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Krebs","canonical_url":"","robots":"","primary_category":"4406","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"77","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/790332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=790332"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/790332\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/790333"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=790332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=790332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=790332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}