{"id":790611,"date":"2026-07-22T22:04:51","date_gmt":"2026-07-22T20:04:51","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ministerprasident-peter-magyar-die-zustimmung-fur-fidesz-sinkt-zum-ersten-mal-seit-30-jahren-unter-20\/"},"modified":"2026-07-23T12:22:59","modified_gmt":"2026-07-23T10:22:59","slug":"ministerprasident-peter-magyar-die-zustimmung-fur-fidesz-sinkt-zum-ersten-mal-seit-30-jahren-unter-20","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ministerprasident-peter-magyar-die-zustimmung-fur-fidesz-sinkt-zum-ersten-mal-seit-30-jahren-unter-20\/","title":{"rendered":"Ministerpr\u00e4sident P\u00e9ter Magyar: Die Zustimmung f\u00fcr Fidesz sinkt zum ersten Mal seit 30 Jahren unter 20 %"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Ministerpr\u00e4sident P\u00e9ter Magyar erkl\u00e4rte am Mittwoch, dass die Zustimmung f\u00fcr Fidesz zum ersten Mal seit 30 Jahren unter 20 % gefallen sei, und teilte die Ergebnisse einer neuen Meinungsumfrage von Z\u00e1vecz Research auf Facebook mit.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut der vom Ministerpr\u00e4sidenten zitierten Umfrage kommt die Tisza-Partei bei den entschlossenen W\u00e4hlern auf 74 % Zustimmung, w\u00e4hrend Fidesz bei 19 % liegt.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201eFidesz lag seit 30 Jahren nicht mehr unter 20 %, und nun hat die Partei sogar einen Insolvenzverwalter\u201c, schrieb Magyar mit Blick auf die aktuelle Lage der Partei.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Er f\u00fcgte hinzu, dass die ehemalige Regierungspartei \u201eimmer schneller denselben Abw\u00e4rtskurs wie in der Gyurcs\u00e1ny-\u00c4ra einschl\u00e4gt\u201c, w\u00e4hrend sich seine Regierung weiterhin auf die Regierungsarbeit konzentriere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eUnterdessen arbeitet die Tisza-Regierung jeden Tag f\u00fcr ein funktionierendes und menschenw\u00fcrdiges Ungarn. Heute beschlie\u00dfen wir Mehrwertsteuersenkungen\u201c, schrieb der Ministerpr\u00e4sident und schloss: \u201eSchritt f\u00fcr Schritt. Ihnen bleiben nur noch Lamas und Spucken.\u201c<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fpeter.magyar.102%2Fposts%2Fpfbid02tjUm4v7gcpgwth6P9GZJ6rGphEmJSSrXuQ4hDsVeSPDDdQNBeP41nTZeu79tfybEl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"679\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">Umfrage deutet auf dramatischen politischen Wandel hin<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die neuesten Ergebnisse von Z\u00e1vecz Research, die von den Meinungsforschern Endre Hann und Tibor Z\u00e1vecz in der Sendung <em><a href=\"https:\/\/www.youtube.com\/watch?v=iXDyVQTsJ4w\" target=\"_blank\" rel=\"noopener\">\u201eSzinten t\u00fal\u201c<\/a><\/em> er\u00f6rtert wurden, deuten auf einen tiefgreifenden Wandel in der politischen Landschaft Ungarns hin.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Der Umfrage zufolge genie\u00dft Tisza unter den entschlossenen W\u00e4hlern eine Zustimmung von 74 %, w\u00e4hrend das B\u00fcndnis aus Fidesz und KDNP auf 19 % kommt.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Die Untersuchung deutet zudem darauf hin, dass die Zustimmung f\u00fcr Fidesz in der Gesamtbev\u00f6lkerung von 27 % auf 16 % gesunken ist, was einem R\u00fcckgang von etwa 2,1 Millionen Anh\u00e4ngern auf rund 1,2 Millionen entspricht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tisza gewinnt in ehemaligen Fidesz-Hochburgen an Boden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Meinungsforscher argumentierten, dass Tisza die Fidesz inzwischen in mehreren Bev\u00f6lkerungsgruppen \u00fcberholt habe, die traditionell die Kernw\u00e4hlerschaft der konservativen Partei bildeten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut Tibor Z\u00e1vecz hat die Opposition sogar unter W\u00e4hlern mit geringerem Einkommen und niedrigerem sozialen Status einen deutlichen Vorsprung herausgearbeitet. Die Umfrage deutet zudem auf eine markante Verschiebung bei den j\u00fcngeren W\u00e4hlern hin; den Forschern zufolge hat Fidesz Schwierigkeiten, wieder Anschluss an eine Generation zu finden, die sie einst zu vertreten suchte.<\/p>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fexanumber%2Fposts%2Fpfbid0GeU961X7r2CmbLpXPcP4XtkXqSxcD8mb1EDA6wm7dNRSBnMUb3dMoMzbaJPxNex1l&#038;show_text=true&#038;width=500\" width=\"500\" height=\"565\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\"><\/iframe>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-pale-ocean-gradient-background has-text-color has-background has-link-color wp-elements-1 wp-block-paragraph\"><strong>Haben Sie dies gelesen? <a href=\"https:\/\/dailynewshungary.com\/de\/tragisch-fur-fidesz-fuhrender-ungarischer-politikexperte-warnt-die-partei-verspiele-ihre-chance-auf-eine-erholung\/\/\">\u201eTragisch f\u00fcr Fidesz\u201c: F\u00fchrender ungarischer Politikexperte warnt, die Partei verspiele ihre Chance auf eine Erholung<\/a><\/strong><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Die Forscher f\u00fchren mehrere Faktoren f\u00fcr den Niedergang von Fidesz an<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Analysten wiesen darauf hin, dass ein Grund f\u00fcr den Niedergang der Zusammenbruch des langj\u00e4hrigen Images von Fidesz als unbesiegbare politische Kraft sei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sie wiesen zudem auf den R\u00fcckzug oder die geringere \u00f6ffentliche Rolle mehrerer prominenter Fidesz-Politiker sowie auf die Auswirkungen von Korruptionsvorw\u00fcrfen und Kontroversen rund um die Verwendung \u00f6ffentlicher Gelder hin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Den Forschern zufolge hat die Fidesz nach ihrer Wahlniederlage bislang noch keine nennenswerte Selbstreflexion gezeigt und st\u00fctzt sich weiterhin auf politische Botschaften, die ihrer Ansicht nach bei den W\u00e4hlern keinen Anklang mehr finden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zwar stellten sie fest, dass das rasante Wachstum von Tisza letztendlich an eine nat\u00fcrliche Grenze sto\u00dfen k\u00f6nnte, doch argumentierten sie, dass die Schwierigkeiten von Fidesz keine Anzeichen einer Entspannung zeigen. Endre Hann wies sogar darauf hin, dass nicht ausgeschlossen werden k\u00f6nne, dass Fidesz in seiner derzeitigen Form die aktuelle politische Krise langfristig nicht \u00fcberstehen werde.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-pale-ocean-gradient-background has-text-color has-background has-link-color wp-elements-2 wp-block-paragraph\"><strong>Falls Sie es verpasst haben: <a href=\"https:\/\/dailynewshungary.com\/de\/die-jungste-umfrage-zeigt-dass-orban-und-seine-fidesz-partei-um-ihr-uberleben-kampfen-wahrend-ministerprasident-magyar-heute-einen-weiteren-grosen-sieg-errungen-hat\/\/\">Neue Untersuchungen deuten darauf hin, dass Orb\u00e1n und Fidesz um ihr \u00dcberleben k\u00e4mpfen, da ehemalige Getreue abwandern und Ministerpr\u00e4sident P\u00e9ter Magyar einen weiteren gro\u00dfen Sieg errungen hat<\/a><\/strong><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ministerpr\u00e4sident P\u00e9ter Magyar erkl\u00e4rte am Mittwoch, dass die Zustimmung f\u00fcr Fidesz zum ersten Mal seit 30 Jahren unter 20 % gefallen sei, und teilte die Ergebnisse einer neuen Meinungsumfrage von Z\u00e1vecz Research auf Facebook mit. Laut der vom Ministerpr\u00e4sidenten zitierten Umfrage kommt die Tisza-Partei bei den entschlossenen W\u00e4hlern auf 74 % Zustimmung, w\u00e4hrend Fidesz bei [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":790612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[4273,1091,4766,4673,4674,1139,1102,1076,1128],"class_list":["post-790611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-ce","tag-fidesz","tag-kategorie-ungarische-politik-2","tag-peter-magyar","tag-tisza-partei","tag-umfrage","tag-ungarische-regierung","tag-ungarn","tag-viktor-orban"],"blocksy_meta":[],"acf":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"default","telegram_post":"","_xlat_group_id":"37d92454-6d55-4530-a7b6-09bf6bcb4e3b"},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"Fidesz","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"71","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/790611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=790611"}],"version-history":[{"count":1,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/790611\/revisions"}],"predecessor-version":[{"id":790632,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/790611\/revisions\/790632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/790612"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=790611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=790611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=790611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}