{"id":791382,"date":"2026-08-12T13:54:00","date_gmt":"2026-08-12T11:54:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/ministerprasident-magyar-kundigt-masnahmen-zur-anhebung-des-donau-pegels-in-der-nahe-des-kernkraftwerks-paks-an\/"},"modified":"2026-08-12T16:23:37","modified_gmt":"2026-08-12T14:23:37","slug":"ministerprasident-magyar-kundigt-masnahmen-zur-anhebung-des-donau-pegels-in-der-nahe-des-kernkraftwerks-paks-an","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/ministerprasident-magyar-kundigt-masnahmen-zur-anhebung-des-donau-pegels-in-der-nahe-des-kernkraftwerks-paks-an\/","title":{"rendered":"Ministerpr\u00e4sident Magyar k\u00fcndigt Ma\u00dfnahmen zur Anhebung des Donau-Pegels in der N\u00e4he des Kernkraftwerks Paks an"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Die ungarische Regierung hat den sofortigen Bau eines unter Wasser liegenden Flussbettwehrs an der Donau in der N\u00e4he von Paks angeordnet und bereitet eine au\u00dfergew\u00f6hnliche vor\u00fcbergehende Ma\u00dfnahme vor: Zwei 80 Meter lange Lastk\u00e4hne k\u00f6nnten bei Bedarf gezielt versenkt werden, um den Wasserstand des Flusses anzuheben.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Regierung hat dringende Ma\u00dfnahmen ergriffen, um die K\u00fchlwasserversorgung des Kernkraftwerks Paks zu sichern, da die au\u00dfergew\u00f6hnlich niedrigen Wasserst\u00e4nde der Donau weiterhin eine Herausforderung darstellen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ministerpr\u00e4sident P\u00e9ter Magyar <a href=\"https:\/\/www.facebook.com\/reel\/4553492911560851?locale=hu_HU\" target=\"_blank\" rel=\"noopener\">gab am Mittwoch bekannt<\/a>, dass unverz\u00fcglich mit dem Bau eines Unterwasserwehrs zwischen dem Kernkraftwerk und der Ortschaft Dunaszentbenedek begonnen werde. Das Projekt soll sicherstellen, dass der Wasserstand im K\u00fchlkanal des Kraftwerks nicht unter -90 Zentimeter f\u00e4llt, damit das wichtigste Kraftwerk des Landes weiterhin mit voller Leistung betrieben werden kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ein Bauprojekt mit einem Volumen von 150.000 Kubikmetern<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Anschluss an eine Regierungssitzung vor Ort in Paks erkl\u00e4rte Magyar, die Arbeiten w\u00fcrden bereits am Donnerstag beginnen. Insgesamt werden rund 150.000 Kubikmeter Gestein f\u00fcr den Bau der unter Wasser liegenden Barriere in der Donau verwendet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Projekt wird als vorrangige Investition behandelt, wobei die Beh\u00f6rden rund um die Uhr Bauarbeiten anordnen. Zur Unterst\u00fctzung des Projekts wurden zudem 100 Soldaten eingesetzt, w\u00e4hrend General P\u00e1l K\u00e1d\u00e1r mit der Koordinierung der Bauarbeiten betraut wurde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An der technischen Planung wird die Technische und Wirtschaftswissenschaftliche Universit\u00e4t Budapest beteiligt sein, w\u00e4hrend die erforderlichen Genehmigungsverfahren parallel zu den Bauarbeiten ablaufen werden. Laut Magyar k\u00f6nnte die dauerhafte Anlage den erforderlichen Wasserstand bereits innerhalb weniger Wochen sicherstellen.<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-electric-grass-gradient-background has-text-color has-background has-link-color wp-elements-1 wp-block-paragraph\"><strong>Verpassen Sie keine Schlagzeile: Treten Sie <\/strong><a href=\"https:\/\/whatsapp.com\/channel\/0029Vb1zD97C6ZvpeGjezE1Y\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>dem offiziellen WhatsApp-Kanal von Daily News Hungary<\/strong><\/a><strong>bei <\/strong><strong>!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sollte der Wasserstand erneut sinken, k\u00f6nnten zwei Lastk\u00e4hne versenkt werden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Regierung bereitet zudem eine eher ungew\u00f6hnliche Notfallma\u00dfnahme vor. Zwei 80 Meter lange Lastk\u00e4hne werden in der N\u00e4he von Paks in Bereitschaft versetzt. Sollte der Wasserstand der Donau vor Fertigstellung des permanenten Wehrs erneut rapide sinken, k\u00f6nnte die Regierung die Schiffe an einer kontrollierten Stelle absichtlich versenken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Laut Magyar k\u00f6nnte dies den Wasserstand vor\u00fcbergehend um bis zu 20 Zentimeter anheben und so dazu beitragen, eine vollst\u00e4ndige Abschaltung des Kernkraftwerks zu verhindern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ma\u00dfnahme wird in Betracht gezogen, da der Wasserstand in diesem Sommer bereits auf au\u00dfergew\u00f6hnlich niedrige Werte gesunken ist. Obwohl die Donau in den letzten Tagen vor\u00fcbergehend angestiegen ist, deuten Prognosen darauf hin, dass sie bald wieder unter -140 Zentimeter fallen k\u00f6nnte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eine Abschaltung von Paks k\u00f6nnte Milliarden kosten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Regierung begr\u00fcndet diesen au\u00dfergew\u00f6hnlichen Eingriff mit den potenziellen wirtschaftlichen Folgen eines vollst\u00e4ndigen Ausfalls der Kraftwerksleistung. Magyar erkl\u00e4rte, eine vollst\u00e4ndige Abschaltung des Kernkraftwerks Paks w\u00fcrde den Staatshaushalt monatlich mindestens 50 Milliarden HUF belasten. Im Vergleich dazu werden die derzeit von der Regierung angeordneten Ma\u00dfnahmen voraussichtlich rund 6 Milliarden HUF kosten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die niedrigen Wasserst\u00e4nde haben den Betrieb des Kraftwerks bereits beeintr\u00e4chtigt. Einer der Bl\u00f6cke lief zuvor mit reduzierter Leistung, obwohl die dritte Turbine von Block 2 Anfang dieser Woche wieder in Betrieb genommen wurde, nachdem der Pegel der Donau um 19 Zentimeter \u00fcber ihren j\u00fcngsten Tiefstand gestiegen war. Die j\u00fcngste Entwicklung deutet jedoch darauf hin, dass der Fluss bald wieder extrem niedrige Pegel erreichen k\u00f6nnte.<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-electric-grass-gradient-background has-text-color has-background has-link-color wp-elements-2 wp-block-paragraph\"><strong>Lesen Sie mehr \u00fcber <a href=\"https:\/\/dailynewshungary.com\/tag\/energy-crisis-in-hungary\/\">die Wasser- und Energiekrise<\/a> in Ungarn <a href=\"https:\/\/dailynewshungary.com\/tag\/energy-crisis-in-hungary\/\">auf Daily News Hungary<\/a>.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Paks hat bereits zuvor vor diesem Problem gewarnt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die langfristigen Auswirkungen der zunehmend niedrigen Wasserst\u00e4nde der Donau geben auch unter Experten Anlass zur Sorge. Der stellvertretende B\u00fcrgermeister von Paks, Istv\u00e1n Barnab\u00e1s, forderte k\u00fcrzlich die Regierung auf, alle m\u00f6glichen L\u00f6sungen zu pr\u00fcfen, um die langfristige K\u00fchlwasserversorgung des Kernkraftwerks unter sich \u00e4ndernden klimatischen Bedingungen sicherzustellen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unterdessen <a href=\"https:\/\/24.hu\/fn\/gazdasag\/2026\/08\/12\/podcast-della-aszodi-attila-paksi-atomeromu\/\" target=\"_blank\" rel=\"noopener\">erkl\u00e4rte<\/a> Attila Asz\u00f3di, ehemaliger Regierungsbeauftragter f\u00fcr den Ausbau von Paks, <a href=\"https:\/\/24.hu\/fn\/gazdasag\/2026\/08\/12\/podcast-della-aszodi-attila-paksi-atomeromu\/\" target=\"_blank\" rel=\"noopener\">k\u00fcrzlich gegen\u00fcber 24.hu<\/a>, er habe die Regierung bereits 2018 darauf hingewiesen, dass k\u00fcnftige Wasserst\u00e4nde und Temperaturen der Donau Probleme f\u00fcr den zuverl\u00e4ssigen Betrieb des Kraftwerks verursachen k\u00f6nnten, sobald die neuen Reaktoren in Betrieb gehen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-pale-ocean-gradient-background has-text-color has-background has-link-color wp-elements-3 wp-block-paragraph\"><strong>Falls Sie es verpasst haben: <a href=\"https:\/\/dailynewshungary.com\/de\/steigende-donau-ein-auserst-heikler-streng-regulierter-prozess-begann-im-kernkraftwerk-paks\/\/\">Steigende Donau: Im Kernkraftwerk Paks begann ein \u00e4u\u00dferst heikler, streng regulierter Prozess<\/a><\/strong><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Die ungarische Regierung hat den sofortigen Bau eines unter Wasser liegenden Flussbettwehrs an der Donau in der N\u00e4he von Paks angeordnet und bereitet eine au\u00dfergew\u00f6hnliche vor\u00fcbergehende Ma\u00dfnahme vor: Zwei 80 Meter lange Lastk\u00e4hne k\u00f6nnten bei Bedarf gezielt versenkt werden, um den Wasserstand des Flusses anzuheben. Die Regierung hat dringende Ma\u00dfnahmen ergriffen, um die K\u00fchlwasserversorgung des [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":791383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"yes","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1081],"tags":[4273,1239,4766,1928,1304,1114,1872,4673,1113,1102,1076],"class_list":["post-791382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik","tag-ce","tag-donau","tag-kategorie-ungarische-politik-2","tag-klima","tag-klimawandel","tag-natur","tag-paks-projekt","tag-peter-magyar","tag-umwelt","tag-ungarische-regierung","tag-ungarn"],"blocksy_meta":[],"acf":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"default","telegram_post":"","_xlat_group_id":"26cdbf44-a3c0-443c-b7a7-a3f6fdd0b6e9"},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"paks","canonical_url":"","robots":"","primary_category":"1081","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"71","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/791382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=791382"}],"version-history":[{"count":1,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/791382\/revisions"}],"predecessor-version":[{"id":791386,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/791382\/revisions\/791386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/791383"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=791382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=791382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=791382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}