{"id":791389,"date":"2026-08-12T16:34:00","date_gmt":"2026-08-12T14:34:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/de\/budapests-lang-erwartete-u-bahn-erweiterung-kommt-endlich-in-gang-dutzende-hauser-stehen-ihr-im-weg\/"},"modified":"2026-08-12T16:34:00","modified_gmt":"2026-08-12T14:34:00","slug":"budapests-lang-erwartete-u-bahn-erweiterung-kommt-endlich-in-gang-dutzende-hauser-stehen-ihr-im-weg","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/de\/budapests-lang-erwartete-u-bahn-erweiterung-kommt-endlich-in-gang-dutzende-hauser-stehen-ihr-im-weg\/","title":{"rendered":"Budapests lang erwartete U-Bahn-Erweiterung kommt endlich in Gang: Dutzende H\u00e4user stehen ihr im Weg"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Budapests seit langem diskutierter Plan zur Verl\u00e4ngerung der U-Bahn-Linie 3 k\u00f6nnte nun endlich in die Bauphase \u00fcbergehen, da die Stadt derzeit die bestehenden Pl\u00e4ne f\u00fcr einen neuen Abschnitt bis nach R\u00e1kospalota-\u00dajpest pr\u00fcft. Bevor jedoch mit den Arbeiten begonnen werden kann, m\u00fcssen rund 24 Grundst\u00fccke \u2013 die meisten davon Wohngeb\u00e4ude \u2013 erworben werden, w\u00e4hrend das Projekt einem engen Zeitplan unterliegt und vor einer ungew\u00f6hnlichen Herausforderung steht: Die Verl\u00e4ngerung m\u00fcsste zun\u00e4chst mit den bestehenden, in Russland gebauten Z\u00fcgen der Linie bedient werden.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Pl\u00e4ne zur Verl\u00e4ngerung der M3 stehen wieder auf der Tagesordnung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das Budapester Verkehrsamt (BKK) hat mit der \u00dcberpr\u00fcfung der bestehenden Pl\u00e4ne f\u00fcr die Verl\u00e4ngerung der U-Bahn-Linie 3 von \u00dajpest-K\u00f6zpont in Richtung R\u00e1kospalota-\u00dajpest begonnen. Im Rahmen dieser \u00dcberpr\u00fcfung wird untersucht, wie die rund 1,9 Kilometer lange Verl\u00e4ngerung gebaut werden k\u00f6nnte, wie das Projekt in Phasen unterteilt werden k\u00f6nnte, wie lange die Bauarbeiten dauern k\u00f6nnten und welche Risiken dem Vorhaben im Wege stehen k\u00f6nnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die U-Bahn-Linie 3 erreichte \u00dajpest-K\u00f6zpont vom Stadtzentrum aus im Jahr 1990. Trotz fr\u00fcherer Pl\u00e4ne, die Linie in Richtung K\u00e1poszt\u00e1smegyer fortzusetzen, wurde die Verl\u00e4ngerung nie realisiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Projekt steht nun im Rahmen des <a href=\"https:\/\/dailynewshungary.com\/de\/ungarn-stellt-10-milliarden-euro-modernisierungsprogramm-fur-das-eisenbahnnetz-vor-neue-zuge-flughafenanbindung-und-schnellere-fahrzeiten-versprochen\/\/\">\u201eBaross-G\u00e1bor-Eisenbahnentwicklungsplans\u201c<\/a> der Regierung wieder auf der Tagesordnung. In der ersten Phase soll die Linie bis zum Bahnhof R\u00e1kospalota-\u00dajpest verl\u00e4ngert werden.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-pale-ocean-gradient-background has-text-color has-background has-link-color wp-elements-1 wp-block-paragraph\"><strong>Falls Sie es verpasst haben: <a href=\"https:\/\/dailynewshungary.com\/de\/ungarn-startet-55-milliarden-euro-modernisierung-des-schienennetzes-entwicklungsplan-erhalt-grunes-licht-2\/\/\">Ungarn plant eine Eisenbahnmodernisierung im Umfang von 5,5 Milliarden Euro, nachdem der Entwicklungsplan gr\u00fcnes Licht erhalten hat<\/a><\/strong><\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Zwei neue Bahnh\u00f6fe k\u00f6nnten die Verkehrsanbindung im Norden Budapests grundlegend ver\u00e4ndern<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Den vorliegenden Pl\u00e4nen zufolge w\u00fcrde der neue Abschnitt in der N\u00e4he der \u00c1rp\u00e1d \u00fat 119, am Ende des bestehenden Untergrundbauwerks, beginnen und sich \u00fcber eine L\u00e4nge von etwa 1,9 Kilometern erstrecken. Es sollen zwei neue Bahnh\u00f6fe entstehen: einer in der N\u00e4he der R\u00f3zsa-Stra\u00dfe und ein weiterer am Bahnhof R\u00e1kospalota-\u00dajpest.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Letzterer k\u00f6nnte f\u00fcr Pendler von besonderer Bedeutung sein, da er Anschl\u00fcsse an die Bahnstrecken Budapest\u2013V\u00e1c\u2013Szob und Budapest\u2013Veresegyh\u00e1z\u2013V\u00e1c schaffen w\u00fcrde. Fahrg\u00e4ste aus den n\u00f6rdlichen Vororten k\u00f6nnten somit in \u00dajpest in die Linie M3 umsteigen, anstatt den gesamten Weg bis zum Bahnhof Nyugati zur\u00fccklegen zu m\u00fcssen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verl\u00e4ngerung ist im offenen Bauverfahren geplant und nicht im herk\u00f6mmlichen Tiefbauverfahren. Die BKK hat zudem alle erforderlichen Genehmigungen der Eisenbahnbeh\u00f6rde verl\u00e4ngert; diese bleiben bis Dezember 2028 g\u00fcltig. Die Organisation bereitet derzeit die Ausschreibungsunterlagen vor, die f\u00fcr das Vergabeverfahren f\u00fcr den Bau erforderlich sind.<\/p><figure class=\"wp-block-image aligncenter size-full\"><figcaption class=\"wp-element-caption\">\n<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image aligncenter size-full\"><figcaption class=\"wp-element-caption\">\n<\/figcaption><img decoding=\"async\" src=\"https:\/\/dailynewshungary.b-cdn.net\/wp-content\/uploads\/2025\/05\/Budapest-M3-metro-line3-1.webp\" alt=\"Budapest M3 metro line3 (1)\" class=\"wp-image-658483\"\/><figcaption class=\"wp-element-caption\">Foto: <a href=\"https:\/\/bkk.hu\/hirek\/2025\/05\/szuletesnap-a-fold-alatt-ket-eve-fejezodott-be-az-m3-as-metro-felujitasa.14360\/\" target=\"_blank\" rel=\"noopener\">BKK<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Zun\u00e4chst m\u00fcssen 24 Grundst\u00fccke erworben werden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bevor die Bauarbeiten jedoch richtig in Gang kommen k\u00f6nnen, gilt es noch eine gro\u00dfe H\u00fcrde zu \u00fcberwinden.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Entlang der geplanten Trasse m\u00fcssten rund 24 Grundst\u00fccke erworben werden. Bei den meisten handelt es sich um Wohngeb\u00e4ude, die auf Fl\u00e4chen stehen, die bereits vor Jahrzehnten f\u00fcr das k\u00fcnftige U-Bahn-Projekt ausgewiesen wurden.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Die Budapester st\u00e4dtische Verm\u00f6gensverwaltungsgesellschaft muss daher so bald wie m\u00f6glich mit dem Erwerb der Grundst\u00fccke oder der Einleitung von Enteignungsverfahren beginnen. Eine Sch\u00e4tzung aus dem Jahr 2021 bezifferte die Kosten f\u00fcr den Erwerb der Grundst\u00fccke auf rund 2,8 Milliarden HUF, wobei der aktuelle Betrag aufgrund von Ver\u00e4nderungen bei den Immobilienpreisen erheblich h\u00f6her ausfallen k\u00f6nnte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Projekt erfordert zudem eine enge Zusammenarbeit zwischen der Hauptstadt, ihren Unternehmen und den Gemeinden der Budapester Bezirke IV und XV.<\/p>\n\n\n\n<p class=\"has-text-align-center has-black-color has-electric-grass-gradient-background has-text-color has-background has-link-color wp-elements-2 wp-block-paragraph\"><strong>Verpassen Sie keine Schlagzeile: Treten Sie <\/strong><a href=\"https:\/\/whatsapp.com\/channel\/0029Vb1zD97C6ZvpeGjezE1Y\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>dem offiziellen WhatsApp-Kanal von Daily News Hungary<\/strong><\/a><strong>bei <\/strong><strong>!<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Uhr tickt bereits<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die BKK hat darauf hingewiesen, dass das Projekt nur unter extrem engen Zeitvorgaben realisiert werden k\u00f6nne. Angesichts des Umfangs und der Komplexit\u00e4t des Vorhabens steht nur begrenzt Zeit zur Verf\u00fcgung, weshalb die Zusammenarbeit zwischen nationalen und lokalen Beh\u00f6rden von besonderer Bedeutung ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Ende 2028 auslaufenden Genehmigungen stellen eine weitere Frist dar. Sollten bis dahin keine ausreichenden Fortschritte erzielt werden, k\u00f6nnten weitere Verl\u00e4ngerungen oder zus\u00e4tzliche Genehmigungsverfahren erforderlich werden. Auch der Bau selbst k\u00f6nnte eine erhebliche Investition darstellen. Eine fr\u00fchere Analyse der MBH Bank sch\u00e4tzte, dass die Erweiterung um zwei Stationen zu aktuellen Preisen 120\u2013160 Milliarden HUF kosten k\u00f6nnte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Projekt w\u00fcrde sich nicht unbedingt durch Fahrgeldeinnahmen amortisieren. Zu seinen weiterreichenden Vorteilen k\u00f6nnten jedoch k\u00fcrzere Fahrzeiten, geringere Pendlerkosten, ein besserer Zugang zu Arbeitspl\u00e4tzen, weniger Verkehrsunf\u00e4lle und geringere Umweltsch\u00e4den z\u00e4hlen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Analyse sch\u00e4tzte, dass die Erweiterung \u00fcber einen Bewertungszeitraum von 30 Jahren j\u00e4hrlich indirekte gesellschaftliche Vorteile in H\u00f6he von rund 8 Milliarden HUF generieren m\u00fcsste, um als wirtschaftlich lohnenswert zu gelten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die neue U-Bahn-Verbindung k\u00f6nnte zudem die Immobilienwerte im Umfeld der k\u00fcnftigen Stationen in die H\u00f6he treiben. Der Analyse zufolge k\u00f6nnten Wohnimmobilien im Umkreis von etwa 500 bis 800 Metern um die Station R\u00e1kospalota-\u00dajpest letztendlich bis zu 10 % mehr wert sein, als dies ohne die Investition der Fall w\u00e4re.<\/p><figure class=\"wp-block-image aligncenter size-large\"><figcaption class=\"wp-element-caption\">\n<\/figcaption><\/figure>\n\n<figure class=\"wp-block-image aligncenter size-large\"><figcaption class=\"wp-element-caption\">\n<\/figcaption><img decoding=\"async\" src=\"https:\/\/dailynewshungary.b-cdn.net\/wp-content\/uploads\/2025\/05\/Budapest-M3-metro-line2-1280x853.webp\" alt=\"Budapest M3 metro line\" class=\"wp-image-658482\"\/><figcaption class=\"wp-element-caption\">Foto: <a href=\"https:\/\/bkk.hu\/hirek\/2025\/05\/szuletesnap-a-fold-alatt-ket-eve-fejezodott-be-az-m3-as-metro-felujitasa.14360\/\" target=\"_blank\" rel=\"noopener\">BKK<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Die in Russland gebauten Z\u00fcge sind nicht mehr wegzudenken<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine der ungew\u00f6hnlicheren Herausforderungen des Projekts betrifft die Z\u00fcge selbst. Laut BKK muss der bestehende \u201eMetrowagonmash\u201c-Zugpark der Linie M3 zumindest f\u00fcr die n\u00e4chsten 20 Jahre als gegeben betrachtet werden. Das bedeutet, dass der geplante Ausbau bis nach R\u00e1kospalota-\u00dajpest zun\u00e4chst mit der bestehenden Flotte betrieben werden m\u00fcsste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies w\u00fcrde das Flottenmanagement der BKV st\u00e4rker belasten, obwohl die BKK der Ansicht ist, dass die derzeitigen Z\u00fcge f\u00fcr den Betrieb der um zwei Haltestellen erweiterten Strecke weiterhin ausreichen k\u00f6nnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Situation ist zum Teil darauf zur\u00fcckzuf\u00fchren, dass eine Option auf sieben zus\u00e4tzliche Z\u00fcge im Rahmen des Vertrags der BKV mit dem russischen Hersteller abgelaufen ist. Metrowagonmash unterliegt zudem aufgrund des russischen Krieges gegen die Ukraine Sanktionen, was den direkten Kauf weiterer Z\u00fcge derzeit unm\u00f6glich macht. Neues Rollmaterial w\u00fcrde an Bedeutung gewinnen, sollte die vollst\u00e4ndige Verl\u00e4ngerung bis nach K\u00e1poszt\u00e1smegyer letztendlich umgesetzt werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">K\u00f6nnte Budapest endlich die lang ersehnte Verl\u00e4ngerung erhalten?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verl\u00e4ngerung der Linie M3 ist nicht unbedingt die dringendste Investition in den Schienenverkehr, die Budapest t\u00e4tigen k\u00f6nnte. Sie hat jedoch gegen\u00fcber vielen anderen vorgeschlagenen Projekten einen wesentlichen Vorteil: Ein Gro\u00dfteil der Vorarbeiten ist bereits geleistet worden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die derzeitige \u00dcberpr\u00fcfung wird zeigen, ob die bestehenden Pl\u00e4ne, Genehmigungen, Grundst\u00fccksvereinbarungen und verf\u00fcgbaren Z\u00fcge eine realistische Grundlage bilden, um das Projekt endlich vom Papier in die Bauphase zu \u00fcberf\u00fchren. Nach mehr als drei Jahrzehnten des Wartens, seit die M3 \u00dajpest-K\u00f6zpont erreicht hat, k\u00f6nnte die seit langem versprochene Nordverl\u00e4ngerung nun endlich eine neue Chance erhalten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapests seit langem diskutierter Plan zur Verl\u00e4ngerung der U-Bahn-Linie 3 k\u00f6nnte nun endlich in die Bauphase \u00fcbergehen, da die Stadt derzeit die bestehenden Pl\u00e4ne f\u00fcr einen neuen Abschnitt bis nach R\u00e1kospalota-\u00dajpest pr\u00fcft. Bevor jedoch mit den Arbeiten begonnen werden kann, m\u00fcssen rund 24 Grundst\u00fccke \u2013 die meisten davon Wohngeb\u00e4ude \u2013 erworben werden, w\u00e4hrend das Projekt [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":791390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_display_image":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[4453],"tags":[2330,1111,4682,1080,1209,1102,1076,1145],"class_list":["post-791389","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wirtschaft","tag-ausbau-der-u-bahn-linie-3","tag-budapest","tag-magyarische-regierung","tag-reisen","tag-russland","tag-ungarische-regierung","tag-ungarn","tag-verkehr"],"blocksy_meta":[],"acf":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":"c80be495-34d0-4252-b9c6-d4351fa5e326"},"public_rank_math_data":{"title":"%title% %sep% %sitename% U-Bahn-Linie \u201e","description":"","focus_keyword":"\u201c","canonical_url":"","robots":"","primary_category":"4453","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"79","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/791389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/comments?post=791389"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/posts\/791389\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media\/791390"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/media?parent=791389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/categories?post=791389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/de\/wp-json\/wp\/v2\/tags?post=791389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}