{"id":653994,"date":"2024-11-04T17:43:33","date_gmt":"2024-11-04T16:43:33","guid":{"rendered":"https:\/\/dailynewshungary.com\/it\/il-parlamento-ungherese-proroga-nuovamente-lo-stato-di-emergenza\/"},"modified":"2024-11-04T17:43:33","modified_gmt":"2024-11-04T16:43:33","slug":"il-parlamento-ungherese-proroga-nuovamente-lo-stato-di-emergenza","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/it\/il-parlamento-ungherese-proroga-nuovamente-lo-stato-di-emergenza\/","title":{"rendered":"Il Parlamento ungherese proroga nuovamente lo stato di emergenza"},"content":{"rendered":"<header><\/header>\n<div class=\"space-y-8 font-content-roboto text-content-base\">\n<p class=\"whitespace-pre-wrap\"><strong>Luned\u00ec il Parlamento ha votato per conferire al governo il potere di prolungare di 180 giorni lo stato di emergenza in relazione alla guerra in Ucraina.<\/strong><\/p>\n<section class=\"whitespace-pre-wrap\">La mozione \u00e8 stata approvata con 130 voti favorevoli, mentre 49 deputati hanno votato contro la modifica della legge sulle norme da applicare in caso di guerra in un paese vicino e in caso di catastrofi umanitarie.<\/section>\n<section class=\"whitespace-pre-wrap\">Secondo la legge, \u00e8 necessario uno stato di emergenza prolungato per gestire la catastrofe umanitaria causata dalla guerra in Ucraina e affrontarne le conseguenze economiche.<\/section>\n<\/div>\n<section><\/section>\n<section>leggi anche:&nbsp;<\/section>\n<section><a href=\"https:\/\/dailynewshungary.com\/it\/il-ministero-degli-esteri-nordcoreano-elogia-il-primo-ministro-orban-per-la-posizione-anti-ue\/\">Il ministero degli Esteri nordcoreano elogia il primo ministro Orb\u00e1n per la posizione anti-UE<\/a><\/section>\n<section>Ungheresi della Transcarpazia a rischio: gli attacchi russi minacciano la struttura segreta ucraina a soli 12 km dal confine ungherese <a href=\"https:\/\/dailynewshungary.com\/it\/ungheresi-della-transcarpazia-a-rischio-gli-attacchi-russi-minacciano-la-struttura-segreta-ucraina-a-soli-12-km-dal-confine-ungherese\/\">dettagli QUI<\/a><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec il Parlamento ha votato per conferire al governo il potere di prolungare di 180 giorni lo stato di emergenza in relazione alla guerra in Ucraina. La mozione \u00e8 stata approvata con 130 voti favorevoli, mentre 49 deputati hanno votato contro la modifica della legge sulle norme da applicare in caso di guerra in un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_display_image":"yes","footnotes":""},"categories":[1190],"tags":[1078,1079,1077,1295,1178,1069],"class_list":["post-653994","post","type-post","status-publish","format-standard","hentry","category-notizie-flash","tag-fidesz","tag-governo-ungherese","tag-guerra-in-ucraina","tag-parlamento-ungherese","tag-russia","tag-ungheria"],"blocksy_meta":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%titolo% %sep% %nomesito%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1190","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/653994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/comments?post=653994"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/653994\/revisions"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media?parent=653994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/categories?post=653994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/tags?post=653994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}