{"id":655743,"date":"2024-08-26T16:35:20","date_gmt":"2024-08-26T14:35:20","guid":{"rendered":"https:\/\/dailynewshungary.com\/it\/annunciata-la-data-di-riapertura-della-stazione-ferroviaria-di-budapest-keleti-dopo-lincidente-del-deragliamento-del-treno\/"},"modified":"2024-08-26T16:35:20","modified_gmt":"2024-08-26T14:35:20","slug":"annunciata-la-data-di-riapertura-della-stazione-ferroviaria-di-budapest-keleti-dopo-lincidente-del-deragliamento-del-treno","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/it\/annunciata-la-data-di-riapertura-della-stazione-ferroviaria-di-budapest-keleti-dopo-lincidente-del-deragliamento-del-treno\/","title":{"rendered":"Annunciata la data di riapertura della stazione ferroviaria di Budapest Keleti dopo l\u2019incidente del deragliamento del treno"},"content":{"rendered":"<p><strong>Il traffico alla stazione di Keleti, dove domenica \u00e8 deragliato un treno passeggeri, dovrebbe tornare alla normalit\u00e0 entro marted\u00ec mattina, il CEO di M\u00c1V ha detto ai giornalisti che le cause del deragliamento del treno saranno indagate pi\u00f9 tardi.<\/strong><\/p>\n<p>Come <strong><a href=\"https:\/\/dailynewshungary.com\/it\/rottura-intercity-deragliato-paralizzando-il-traffico-ferroviario-nella-trafficata-stazione-ferroviaria-di-budapest-foto\/\" target=\"_blank\" rel=\"noopener\">precedentemente riportato<\/a><\/strong> con DNH, cinque carrozze del treno Claudiopolis InterCity 5 da Cluj-Napoca (Kolozsv\u00e1r) a Budapest sono deragliate vicino alla stazione di Keleti domenica sera, bloccando il traffico da e per la stazione Le operazioni di soccorso tecnico sono proseguite fino a luned\u00ec mattina e pomeriggio.<\/p>\n<p><a href=\"https:\/\/24.hu\/belfold\/2024\/08\/26\/mav-vasut-lezaras-palayazar-keleti-palayudvar-vitezy-david-lazar-janos\/\" target=\"_blank\" rel=\"noopener\"><strong>Secondo 24.hu<\/strong>,<\/a> il traffico alla stazione di Keleti dovrebbe essere ripristinato entro marted\u00ec mattina, rimane tuttavia incerto se il traffico ferroviario sar\u00e0 pienamente operativo su tutti i binari, per accelerare il processo gli esperti hanno trovato una soluzione che evita la necessit\u00e0 di smantellare le linee aeree, portare gru, e poi ricostruirle, hanno invece utilizzato dei paranchi per far decollare e rimettere nuovamente sui binari i cinque carri deragliati.<\/p>\n<p>Le Ferrovie Ungheresi (M\u00c1V) hanno tenuto una conferenza stampa nel sito, dove L\u00e1szl\u00f3 Mos\u00f3czi, amministratore delegato di M\u00c1V-Start, ha affermato che la stazione Keleti \u00e8 sostituita dalle stazioni R\u00e1kos e K theb\u00e1nya-Fels the. Tuttavia, poich\u00e9 la capacit\u00e0 di queste stazioni \u00e8 molto inferiore, i servizi ferroviari sono stati ridotti. In alternativa, sono operativi i servizi di autobus e i passeggeri possono utilizzare la linea M4 della metropolitana per raggiungere Kelenf\u00f6ld.<\/p>\n<p>M\u00c1V ha stimato che fino a 100.000 passeggeri potrebbero essere colpiti dai ritardi Le Ferrovie Ungheresi non sono a conoscenza di eventuali lesioni personali legate all&#8217;incidente.<\/p>\n<figure id=\"attachment_608779\" aria-describedby=\"caption-attachment-608779\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-608779\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-train-derailment-rescue.jpg\" alt=\"soccorso deragliamento treno Keleti\" width=\"1024\" height=\"683\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-train-derailment-rescue.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-train-derailment-rescue-768x512.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-train-derailment-rescue-333x222.jpg 333w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-train-derailment-rescue-248x165.jpg 248w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-train-derailment-rescue-112x75.jpg 112w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-train-derailment-rescue-480x320.jpg 480w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption id=\"caption-attachment-608779\" class=\"wp-caption-text\">Operazioni di recupero in corso vicino alla stazione di Keleti Foto: M\u00c1V<\/figcaption><\/figure>\n<h2>Le cause del deragliamento del treno dovranno essere indagate in seguito<\/h2>\n<p>Le Ferrovie ungheresi devono ancora rilasciare dettagli completi sulle circostanze che hanno fatto precipitare l&#8217;incidente. Zolt\u00e1n Paff\u00e9ri, amministratore delegato di M\u00c1V, ha tuttavia affermato che il primo passo \u00e8 riparare il sito e che la valutazione dei danni e la ricostruzione dell&#8217;incidente inizieranno solo una volta completato questo processo.<\/p>\n<p>Quanto a una domanda sul fatto se ci fosse la possibilit\u00e0 che un altro treno avrebbe potuto colpire i vagoni deragliati, l&#8217;amministratore delegato ha detto che \u201cIl macchinista del treno proveniente da dietro ha fermato il treno azionando i freni di emergenza-\u201d<\/p>\n<p>Secondo R\u00e9ka N\u00e9meth, vicedirettore generale di M\u00c1V per le operazioni in pista, una parte del cambio si \u00e8 rotta, tuttavia non \u00e8 ancora possibile determinare se ci\u00f2 abbia causato l&#8217;incidente o se la rottura sia stata causata dall&#8217;incidente stesso.<\/p>\n<p>Ha sottolineato che gli scambi ferroviari vengono ispezionati ogni mese e che l&#8217;interruttore che si \u00e8 rotto nell&#8217;incidente \u00e8 stato ispezionato il 30 luglio, momento in cui non sono stati identificati problemi con la sua funzionalit\u00e0. N\u00e9meth ha sottolineato che in seguito al deragliamento del treno tutti gli scambi saranno soggetti a ispezione e che anche la polizia sar\u00e0 coinvolta nelle indagini sulle cause dell&#8217;incidente.<\/p>\n<p>Ulteriori informazioni sul deragliamento del treno e sugli orari modificati dei trasporti pubblici nella zona sono disponibili nell&#8217;altro rapporto di DNH <strong><a href=\"https:\/\/dailynewshungary.com\/it\/guarda-video-appena-pubblicato-del-deragliamento-del-treno-alla-stazione-ferroviaria-di-budapest-keleti\/\" target=\"_blank\" rel=\"noopener\">QUI<\/a><\/strong>.<\/p>\n<figure id=\"attachment_608700\" aria-describedby=\"caption-attachment-608700\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-608700\" src=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-station-budapest.jpg\" alt=\"Stazione ferroviaria di Keleti, Ungheria Fonte: M\u00c1V\" width=\"1200\" height=\"800\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-station-budapest.jpg 1200w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-station-budapest-768x512.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-station-budapest-333x222.jpg 333w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-station-budapest-248x165.jpg 248w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-station-budapest-1030x687.jpg 1030w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-station-budapest-113x75.jpg 113w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2024\/08\/keleti-station-budapest-480x320.jpg 480w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption id=\"caption-attachment-608700\" class=\"wp-caption-text\">Il deragliamento del treno dall&#8217;alto alla stazione ferroviaria di Keleti, Ungheria Fonte: M\u00c1V<\/figcaption><\/figure>\n<h2>Una tragicommedia negli ultimi tre giorni di M\u00c1V, mentre L\u00e1z\u00e1r resta in silenzio<\/h2>\n<p>Esaminando lo scorso fine settimana, 444 <strong><a href=\"https:\/\/444.hu\/2024\/08\/26\/a-mav-72-oraja-vivja-a-halaltusajat-lazar-janos-pedig-csendben-nezi\" target=\"_blank\" rel=\"noopener\">raccolti<\/a><\/strong> una miriade di problemi che i passeggeri del M\u00c1V hanno dovuto affrontare Tutto \u00e8 iniziato sabato a mezzogiorno, quando una ferrovia si \u00e8 rotta tra Szabadbatty\u00e1n e Kiscs\u00e9ripuszta, paralizzando i treni sul Lago Balaton, con eventi complicati dal fatto che non tutti i passeggeri potevano salire sugli autobus sostitutivi inviati.<\/p>\n<p>Poi c&#8217;\u00e8 stato il deragliamento a Keleti, mentre il traffico \u00e8 stato bloccato alla stazione di Nyugati dopo che un treno InterCity si \u00e8 scontrato con un&#8217;auto sulla linea principale per Cegl\u00e9d.<\/p>\n<p>Luned\u00ec mattina, un treno InterCity da Kassa a Hatvan e poi un treno sulla linea V\u00e1c vicino a Fels\u0151g\u00f6d hanno colpito qualcuno, provocando l&#8217;interruzione del traffico su entrambe le linee. Pi\u00f9 tardi, quello stesso giorno, una rotaia rotta ha costretto alla chiusura di un binario tra le stazioni di K theb\u00e1nya-Als\u00f3 e Nyugati. Infine, un treno InterCity da Szombathely a Budapest si \u00e8 scontrato con un camion sulla sponda settentrionale del Lago Balaton, bloccando completamente il traffico sulla linea del Nord Balaton.<\/p>\n<p>44 ha criticato anche il fatto che una figura di alto rango (ovvero Paff\u00e9ri 4) abbia parlato solo 73 ore dopo l&#8217;inizio della serie di incidenti, mentre J\u00e1nos L\u00e1z\u00e1r, ministro responsabile dei trasporti, finora non ha detto nulla sugli incidenti ferroviari.<\/p>\n<p><strong>Leggi anche:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/dailynewshungary.com\/it\/ritardi-dei-treni-internazionali-previsti-in-ungheria-la-prossima-settimana-interessati-i-treni-cechi-e-slovacchi\/\" target=\"_blank\" rel=\"noopener\">Ritardi dei treni internazionali previsti in Ungheria la prossima settimana: interessati i treni cechi e slovacchi<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Il traffico alla stazione di Keleti, dove domenica \u00e8 deragliato un treno passeggeri, dovrebbe tornare alla normalit\u00e0 entro marted\u00ec mattina, il CEO di M\u00c1V ha detto ai giornalisti che le cause del deragliamento del treno saranno indagate pi\u00f9 tardi. Come precedentemente riportato con DNH, cinque carrozze del treno Claudiopolis InterCity 5 da Cluj-Napoca (Kolozsv\u00e1r) a [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":655744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_display_image":"yes","footnotes":""},"categories":[1207],"tags":[1158,1494,1480,1069,1174],"class_list":["post-655743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societa-in-ungheria","tag-budapest","tag-mav","tag-treno","tag-ungheria","tag-viaggio"],"blocksy_meta":[],"author_username":"busidora","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"hidden","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%titolo% %sep% %nomesito%","description":"","focus_keyword":"deragliamento treno","canonical_url":"","robots":"","primary_category":"1207","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"74","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/655743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/comments?post=655743"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/655743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media\/655744"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media?parent=655743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/categories?post=655743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/tags?post=655743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}