{"id":706090,"date":"2018-02-14T07:30:01","date_gmt":"2018-02-14T06:30:01","guid":{"rendered":"https:\/\/dailynewshungary.com\/it\/governo-di-presentare-una-versione-piu-severa-del-disegno-di-legge-stop-soros\/"},"modified":"2018-02-14T07:30:01","modified_gmt":"2018-02-14T06:30:01","slug":"governo-di-presentare-una-versione-piu-severa-del-disegno-di-legge-stop-soros","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/it\/governo-di-presentare-una-versione-piu-severa-del-disegno-di-legge-stop-soros\/","title":{"rendered":"Governo di presentare una versione pi\u00f9 severa del disegno di legge \u2018Stop Soros\u2019"},"content":{"rendered":"<p><strong>Marted\u00ec il governo ha presentato una versione di \u201csignificativamente pi\u00f9 rigorosa del <a href=\"https:\/\/dailynewshungary.com\/it\/il-governo-annuncia-il-pacchetto-legalestop-soros\/\" target=\"_blank\" rel=\"noopener\">Proposta di legge Stop Soros\u201d<\/a> al Parlamento, dopo aver apportato diverse modifiche al progetto di legge originale, ha detto il segretario di Stato per le comunicazioni governative.<\/strong><\/p>\n<p>Il pi\u00f9 grande <a href=\"https:\/\/dailynewshungary.com\/it\/ulteriori-restrizioni-proposte-al-pacchetto-stop-soros\/\" target=\"_blank\" rel=\"noopener\">cambiare<\/a> fatto alla bozza originale riguarda la clausola che obbliga le organizzazioni che promuovono la migrazione a registrare le loro attivit\u00e0, ha detto Bence Tuzson in una conferenza stampa. Secondo la versione modificata, le organizzazioni in questione sarebbero tenute a chiedere il permesso al ministro degli Interni per organizzare, sostenere o finanziare la migrazione, ha detto Tuzson. Le loro richieste saranno esaminate in termini di implicazioni sulla sicurezza nazionale, ha aggiunto.<\/p>\n<p>Il disegno di legge prevede anche disposizioni che richiedono una maggioranza di due terzi, il che significa che queste dovranno essere sostenute dall&#8217;opposizione se vogliono essere approvate, ha detto Tuzson.<\/p>\n<blockquote>\n<p>Ha detto che il governo ha valutato pi\u00f9 di 600 proposte di emendamento al disegno di legge e \u201c ha tratto da esse le giuste conclusioni.<\/p>\n<\/blockquote>\n<p>Il segretario di Stato del ministero della Giustizia, P\u00e1l V\u00f6lner, ha affermato che la clausola della legge che lega il sostegno alla migrazione all&#8217;ottenimento del permesso ministeriale richiede un emendamento alla legge ungherese sulla sicurezza nazionale. Ha detto che le organizzazioni avranno la possibilit\u00e0 di ricorrere in appello contro la decisione del ministro per motivi procedurali.<\/p>\n<p>Se un&#8217;organizzazione sostiene, finanzia o organizza la migrazione senza permesso, ricever\u00e0 un avvertimento dal pubblico ministero di cessare le sue attivit\u00e0 e il suo numero di imposta sar\u00e0 sospeso, ha detto V\u00f6lner. Se l&#8217;organizzazione in questione non tiene ancora conto dell&#8217;avvertimento del pubblico ministero, ricever\u00e0 una multa fino a 1,8 milioni di fiorini (5.770 euro), ha affermato. Se continua a rifiutarsi di conformarsi, l&#8217;organizzazione dovr\u00e0 affrontare un&#8217;azione legale che potrebbe concludersi con il suo scioglimento come ONG in Ungheria.<\/p>\n<p>La clausola del disegno di legge che impone alle organizzazioni che promuovono la migrazione di pagare una tassa del 25% sulle donazioni ricevute dall&#8217;estero \u00e8 stata lasciata intatta, ha detto V\u00f6lner. Tuttavia, secondo il disegno di legge modificato, non si applicherebbe alle organizzazioni che non utilizzano tali donazioni per tali scopi\u201d.<\/p>\n<p><em>immagine in evidenza: Facebook<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec il governo ha presentato una versione di \u201csignificativamente pi\u00f9 rigorosa del Proposta di legge Stop Soros\u201d al Parlamento, dopo aver apportato diverse modifiche al progetto di legge originale, ha detto il segretario di Stato per le comunicazioni governative. Il pi\u00f9 grande cambiare fatto alla bozza originale riguarda la clausola che obbliga le organizzazioni che [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":706091,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_display_image":"","footnotes":""},"categories":[1185],"tags":[1450,1264,1551,1318],"class_list":["post-706090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-in-ungheria","tag-diritto","tag-ong","tag-soros","tag-tasse"],"blocksy_meta":[],"author_username":"kovacszsoka","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%titolo% %sep% %nomesito%","description":"La modifica pi\u00f9 grande apportata alla bozza originaria riguarda la clausola che obbliga le organizzazioni che promuovono la migrazione a registrare le proprie attivit\u00e0","focus_keyword":"Fermo Soros","canonical_url":"","robots":"","primary_category":"1185","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"50","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/706090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/comments?post=706090"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/706090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media\/706091"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media?parent=706090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/categories?post=706090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/tags?post=706090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}