{"id":717031,"date":"2017-01-01T13:15:15","date_gmt":"2017-01-01T12:15:15","guid":{"rendered":"https:\/\/dailynewshungary.com\/it\/il-presidente-ungherese-commemora-il-compromesso-del-1867-nel-discorso-di-capodanno\/"},"modified":"2017-01-01T13:15:15","modified_gmt":"2017-01-01T12:15:15","slug":"il-presidente-ungherese-commemora-il-compromesso-del-1867-nel-discorso-di-capodanno","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/it\/il-presidente-ungherese-commemora-il-compromesso-del-1867-nel-discorso-di-capodanno\/","title":{"rendered":"Il presidente ungherese commemora il compromesso del 1867 nel discorso di Capodanno"},"content":{"rendered":"<p><strong>Budapest, 1 gennaio (MTI) Il presidente J\u00e1nos \u00c1der ha sottolineato l&#8217;imminente 150\u00b0 anniversario dello storico compromesso ungherese con i suoi governanti asburgici nel suo discorso trasmesso dalla televisione pubblica nei primi minuti del 2017.<\/strong><\/p>\n<p>Riferendosi al Compromesso del 1867, \u00c1der disse di aver ignorato un&#8217;era di sviluppo nazionale senza precedenti, in cui le citt\u00e0 ungheresi subirono importanti cambiamenti, furono costruite strade e ferrovie e inizi\u00f2 l&#8217;istruzione pubblica.<\/p>\n<p>Per quanto riguarda l&#8217;anno scorso, il presidente ha preso atto delle medaglie vinte dagli atleti olimpici ungheresi, dei gol dell&#8217;Ungheria al campionato europeo di calcio e dei risultati scientifici e culturali del paese. Ha detto che il paese dovrebbe anche apprezzare gli \u201cungheresi che rendono le nostre vite pi\u00f9 belle, migliori e pi\u00f9 felici nelle proprie posizioni e secondo le proprie possibilit\u00e0\u201d.<\/p>\n<p>\u00c1der ha commemorato gli autori ungheresi Imre Kert\u00e9sz, P\u00e9ter Esterh\u00e1zy, S\u00e1ndor Cso\u00f3ri e il pianista Zolt\u00e1n Kocsis, morto durante l&#8217;anno. \u201cRimarranno con noi per sempre, perch\u00e9 i loro successi ci hanno reso tutti pi\u00f9 ricchi, ha detto.<\/p>\n<p>Nel suo discorso, \u00c1der ha augurato a\u201cpi\u00f9 pace, calma, comprensione e rispetto reciproco nel 2017, e ha chiesto la benedizione di Dio per la nazione ungherese\u201d.<\/p>\n<p><em>Foto: MTI<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Budapest, 1 gennaio (MTI) Il presidente J\u00e1nos \u00c1der ha sottolineato l&#8217;imminente 150\u00b0 anniversario dello storico compromesso ungherese con i suoi governanti asburgici nel suo discorso trasmesso dalla televisione pubblica nei primi minuti del 2017. Riferendosi al Compromesso del 1867, \u00c1der disse di aver ignorato un&#8217;era di sviluppo nazionale senza precedenti, in cui le citt\u00e0 ungheresi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":717032,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_display_image":"","footnotes":""},"categories":[1185],"tags":[1341,1600],"class_list":["post-717031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-in-ungheria","tag-presidente-dellungheria","tag-vigilia-di-capodanno"],"blocksy_meta":[],"author_username":"alk","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%titolo% %sep% %nomesito%","description":"","focus_keyword":"presidente","canonical_url":"","robots":"","primary_category":"1185","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"58","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/717031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/comments?post=717031"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/717031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media\/717032"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media?parent=717031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/categories?post=717031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/tags?post=717031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}