{"id":721378,"date":"2016-07-14T20:45:49","date_gmt":"2016-07-14T18:45:49","guid":{"rendered":"https:\/\/dailynewshungary.com\/it\/ecco-che-arriva-il-primo-sistema-di-consegna-con-droni-in-ungheria\/"},"modified":"2016-07-14T20:45:49","modified_gmt":"2016-07-14T18:45:49","slug":"ecco-che-arriva-il-primo-sistema-di-consegna-con-droni-in-ungheria","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/it\/ecco-che-arriva-il-primo-sistema-di-consegna-con-droni-in-ungheria\/","title":{"rendered":"Ecco che arriva il primo sistema di consegna con droni in Ungheria"},"content":{"rendered":"<p><strong><a href=\"http:\/\/orientpress.hu\/cikk\/dronok-szallitjak-a-jovoben-az-ebedet\" target=\"_blank\" rel=\"noopener\">Secondo orientpress.hu, <\/a>il team di NetPinc\u00e9r sta testando un sistema di consegna di cibo tramite droni basato sull&#8217;esempio di Singapore Se i corrieri aerei vengono messi in azione reale, allora il tempo di consegna potrebbe essere ridotto dall&#8217;attuale 1 ora a 30 minuti In pochi anni la vista dei droni che volano in aria a 100-150 metri pu\u00f2 diventare naturale come la vista delle auto per le strade.<\/strong><\/p>\n<p>Recentemente \u00e8 stato riferito che Foodpanda Singapore ha testato l&#8217;opzione di consegna di cibo con droni Se i test pratici si rivelano buoni, allora i corrieri con droni potrebbero essere messi al lavoro dal prossimo anno, Alla notizia della loro azienda gemella, NetPinc\u00e9r ha deciso di avviare anche test sperimentali.<\/p>\n<p>G\u00e1bor Sz\u00f3r\u00e1d, il manager dell&#8217;azienda, ha affermato che l&#8217;opzione della consegna dei droni pone molte domande; tuttavia, credono nella totale automazione del processo di consegna nel lungo periodo. Un passo importante potrebbe essere la consegna con droni controllati da uomini, seguiti dai corrieri di droni completamente autoguidati.<\/p>\n<p>\u201cLa preparazione del cibo di solito richiede 15 minuti I restanti 30-45 minuti di consegna sono tutti circa i processi logistici Questo \u00e8 ci\u00f2 che potrebbe essere ridotto alla sua met\u00e0 con i droni\u201d ha detto il manager Ha anche aggiunto che sono costantemente alla ricerca di nuovi, metodi di consegna innovativi. \u201cThe 21<sup>st<\/sup> century \u00e8 tutto incentrato su &#8216;adesso&#8217; Non siamo disposti ad aspettare a lungo, vogliamo tutto immediatamente Quando si tratta di consegna di cibo, la rapidit\u00e0 \u00e8 particolarmente importante poich\u00e9 le persone di solito ordinano quando hanno gi\u00e0 fame, non un&#8217;ora prima.\u201d<\/p>\n<p>Il manager ha sottolineato che i test attuali sono solo il primo passo del processo. \u201cSiamo stati principalmente spinti da una onesta curiosit\u00e0 Dobbiamo risolvere un sacco di questioni legali e tecniche prima di vedere i droni volare con le pizze sulle citt\u00e0 Ma prendiamo sul serio la sfida, stiamo negoziando con possibili partner al momento.\u201d<\/p>\n<p>Szil\u00e1rd F\u00fcl\u00f6p, il manager di FlyBySense che fornisce supporto tecnico per l&#8217;esperimento, ha affermato che i droni pi\u00f9 diffusi nella vita civica sono inadeguati per la consegna del cibo. La loro capacit\u00e0 portante teorica \u00e8 di soli 0,2 kg e tutti i grammi vanno a scapito della sicurezza. Anche se i droni pi\u00f9 grandi e professionali potrebbero tranquillamente trasportare anche 5-6 kg-s.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-74870\" src=\"https:\/\/dailynewshungary.com\/wp-content\/uploads\/2016\/07\/drone-delivery2-300x200.jpg\" alt=\"consegna drone2\" width=\"600\" height=\"400\" srcset=\"https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/07\/drone-delivery2-300x200.jpg 300w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/07\/drone-delivery2-768x512.jpg 768w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/07\/drone-delivery2-1024x683.jpg 1024w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/07\/drone-delivery2-220x147.jpg 220w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/07\/drone-delivery2-600x400.jpg 600w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/07\/drone-delivery2-610x407.jpg 610w, https:\/\/contentf5.dailynewshungary.com\/wp-content\/uploads\/2016\/07\/drone-delivery2.jpg 1200w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\"><\/p>\n<p>\u201cL&#8217;altro collo di bottiglia \u00e8 il controllo del drone Possono essere controllati solo per 400 metri con gli occhi senza aiuto Ma i droni pi\u00f9 grandi possono essere guidati per 2-3 chilometri con l&#8217;aiuto della loro telecamera.\u201d Ha aggiunto che la vera sfida non sono in realt\u00e0 le questioni tecniche, ma la difficile regolamentazione. \u201cIdealmente bisogna ottenere il permesso di pilotare tutti i droni poich\u00e9 l&#8217;attuale regolamento dichiara che si pu\u00f2 pilotare un veicolo aereo senza pilota solo in uno spazio aereo separato. Questa non \u00e8 troppo simile alla vita.\u201d<\/p>\n<p>I legislatori si sono resi conto dell&#8217;indifendibilit\u00e0 della situazione Il Ministero dello Sviluppo Nazionale sta attualmente lavorando a un&#8217;ordinanza che regoli il problema, che probabilmente sar\u00e0 operativa dall&#8217;inizio del prossimo anno. Szil\u00e1rd F\u00fcl\u00f6p pensa che i droni siano il futuro.<\/p>\n<p>\u201cDobbiamo accettare che i droni diventeranno parte della nostra vita quotidiana Tra qualche anno la vista dei droni che volano in aria a 100-150 metri pu\u00f2 diventare naturale come la vista delle auto per le strade, infatti, queste voleranno senza il controllo umano Se tutto va bene, l&#8217;auto autoguidata sar\u00e0 presentata nel 2017 Perch\u00e9 allora i droni dovrebbero aver bisogno del contributo umano?\u201d<\/p>\n<p><em>Foto: NetPinc\u00e9r<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo orientpress.hu, il team di NetPinc\u00e9r sta testando un sistema di consegna di cibo tramite droni basato sull&#8217;esempio di Singapore Se i corrieri aerei vengono messi in azione reale, allora il tempo di consegna potrebbe essere ridotto dall&#8217;attuale 1 ora a 30 minuti In pochi anni la vista dei droni che volano in aria a [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":721379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_display_image":"","footnotes":""},"categories":[1314],"tags":[1147,1383,1749,1373],"class_list":["post-721378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia-in-ungheria","tag-cibo","tag-drone","tag-invenzione","tag-tecnologia-2"],"blocksy_meta":[],"author_username":"Szandi","telegram_post":"","public_post_metadata":{"breaking_news":"","important":"","csempe":"","center_tile":"","disable_thumbnail":"","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%titolo% %sep% %nomesito%","description":"","focus_keyword":"","canonical_url":"","robots":"","primary_category":"1314","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/721378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/comments?post=721378"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/721378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media\/721379"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media?parent=721378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/categories?post=721378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/tags?post=721378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}