{"id":791881,"date":"2026-07-15T11:34:00","date_gmt":"2026-07-15T09:34:00","guid":{"rendered":"https:\/\/dailynewshungary.com\/it\/viktor-orban-e-stato-avvistato-mentre-guardava-la-semifinale-dei-mondiali-a-dallas-con-alcuni-membri-della-sua-famiglia-video\/"},"modified":"2026-07-15T11:34:00","modified_gmt":"2026-07-15T09:34:00","slug":"viktor-orban-e-stato-avvistato-mentre-guardava-la-semifinale-dei-mondiali-a-dallas-con-alcuni-membri-della-sua-famiglia-video","status":"publish","type":"post","link":"https:\/\/dailynewshungary.com\/it\/viktor-orban-e-stato-avvistato-mentre-guardava-la-semifinale-dei-mondiali-a-dallas-con-alcuni-membri-della-sua-famiglia-video\/","title":{"rendered":"Viktor Orb\u00e1n \u00e8 stato avvistato mentre guardava la semifinale dei Mondiali a Dallas con alcuni membri della sua famiglia \u2013 video"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>L\u2019ex primo ministro ungherese Viktor Orb\u00e1n ha assistito alla vittoria della Spagna per 2-0 sulla Francia nella semifinale dei Mondiali dagli spalti dello stadio di Dallas, accompagnato da diversi membri della sua famiglia.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Orb\u00e1n, noto appassionato di calcio, aveva gi\u00e0 annunciato in precedenza la sua intenzione di <a href=\"https:\/\/dailynewshungary.com\/it\/viktor-orban-sotto-accusa-dopo-aver-dichiarato-la-morte-della-democrazia-ungherese-per-poi-volare-ai-mondiali\/\/\">assistere alle<\/a> fasi <a href=\"https:\/\/dailynewshungary.com\/it\/viktor-orban-sotto-accusa-dopo-aver-dichiarato-la-morte-della-democrazia-ungherese-per-poi-volare-ai-mondiali\/\/\">finali<\/a> del torneo negli Stati Uniti. Le immagini che lo ritraggono mentre assiste alla partita sono apparse inaspettatamente online dopo che alcuni utenti lo hanno individuato in una <a href=\"https:\/\/www.youtube.com\/live\/pvpR2LBevPk\" target=\"_blank\" rel=\"noopener\">diretta<\/a> trasmessa dal famoso streamer americano IShowSpeed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il filmato mostra Orb\u00e1n mentre reagisce ai momenti chiave della partita, tra cui un gesto di frustrazione in cui alza le mani prima di tornare alla sua consueta posa da spettatore, in piedi con le braccia incrociate mentre segue l\u2019incontro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Anche alcuni membri della famiglia Orb\u00e1n sono stati avvistati sugli spalti<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un\u2019osservazione pi\u00f9 attenta del filmato ha rivelato la presenza di diversi membri della famiglia di Orb\u00e1n tra le persone sedute vicino a lui.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suo figlio G\u00e1sp\u00e1r Orb\u00e1n \u00e8 stato visto indossare un berretto rosso, mentre tra gli spettatori sono stati identificati anche sua figlia S\u00e1ra Orb\u00e1n e suo marito Tam\u00e1s Szokira. L\u2019uomo seduto accanto all\u2019ex primo ministro sarebbe J\u00e1nos Jakab, presidente onorario della squadra di calcio Budafok di Budapest.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il gruppo era seduto nelle file sotto la tribuna VIP, anzich\u00e9 nella tribuna VIP principale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel frattempo, S\u00e1ndor Cs\u00e1nyi, presidente della Federazione calcistica ungherese (MLSZ) e vicepresidente della FIFA, ha assistito alla partita dall\u2019area VIP, dove era seduto vicino al presidente della FIFA Gianni Infantino.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"irl stream France \ud83c\uddeb\ud83c\uddf7 Vs Spain \ud83c\uddea\ud83c\uddf8! Semifinals Full World Cup Match \u26bd\ufe0f\ud83c\udf0d\" width=\"1480\" height=\"833\" src=\"https:\/\/www.youtube.com\/embed\/pvpR2LBevPk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Orb\u00e1n ha tifato per la Francia, ma \u00e8 la Spagna ad aver superato il turno<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Orb\u00e1n aveva previsto che la Francia avrebbe vinto la semifinale, il che significa che il risultato non \u00e8 stato chiaramente quello che sperava.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la partita, le telecamere hanno ripreso la sua frustrazione mentre la Spagna dominava il gioco ed eliminava una delle favorite del torneo. A un certo punto, dopo che lo spagnolo Mikel Oyarzabal aveva trasformato un rigore, Orb\u00e1n si \u00e8 subito rimesso a sedere, mentre in altri momenti lo si vedeva scuotere la testa e gesticolare con aria delusa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019ex primo ministro non dovr\u00e0 tuttavia attendere a lungo per un\u2019altra partita. Proseguendo la sua tradizione di lunga data di partecipare ai principali eventi calcistici, Orb\u00e1n dovrebbe assistere anche all\u2019altra semifinale e alla finale dei Mondiali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il suo viaggio negli Stati Uniti \u00e8 iniziato proprio mentre il parlamento ungherese <a href=\"https:\/\/dailynewshungary.com\/it\/il-parlamento-ungherese-approva-ampie-modifiche-costituzionali-per-destituire-il-presidente\/\/\">votava il 17\u00b0 emendamento<\/a> alla Legge fondamentale. La mossa era stata pesantemente criticata dall\u2019opposizione, con il partito Fidesz che in precedenza aveva messo in guardia da una grave crisi costituzionale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019assenza di Orb\u00e1n durante la votazione ha attirato l\u2019attenzione, poich\u00e9 l\u2019ex primo ministro si \u00e8 recato negli Stati Uniti per assistere alle partite di calcio mentre in patria proseguiva il dibattito politico.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-black-color has-pale-ocean-gradient-background has-text-color has-background has-link-color wp-elements-b8e50b8d5d4af9b9e9b7a7249c0715dc wp-block-paragraph\"><strong>Se ve lo siete perso: <a href=\"https:\/\/dailynewshungary.com\/it\/viktor-orban-sotto-accusa-dopo-aver-dichiarato-la-morte-della-democrazia-ungherese-per-poi-volare-ai-mondiali\/\/\">Viktor Orb\u00e1n sotto accusa dopo aver dichiarato \u00abmorta\u00bb la democrazia ungherese \u2014 per poi volare ai Mondiali<\/a><\/strong><\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ex primo ministro ungherese Viktor Orb\u00e1n ha assistito alla vittoria della Spagna per 2-0 sulla Francia nella semifinale dei Mondiali dagli spalti dello stadio di Dallas, accompagnato da diversi membri della sua famiglia. Orb\u00e1n, noto appassionato di calcio, aveva gi\u00e0 annunciato in precedenza la sua intenzione di assistere alle fasi finali del torneo negli Stati [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":791882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_display_image":"","footnotes":""},"categories":[2443],"tags":[1085,2549,1111,1069,1124,1083],"class_list":["post-791881","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-life","tag-calcio","tag-categoria-sport","tag-stati-uniti","tag-ungheria","tag-video","tag-viktor-orban"],"blocksy_meta":[],"author_username":"hmercedesz","telegram_post":"","public_post_metadata":{"breaking_news":"yes","important":"no","csempe":"yes","center_tile":"no","disable_thumbnail":"no","target_lang":"","_featured_image_style":"","telegram_post":"","_xlat_group_id":""},"public_rank_math_data":{"title":"%title% %sep% %sitename%","description":"","focus_keyword":"orb\u00e1n","canonical_url":"","robots":"","primary_category":"2443","breadcrumb_title":"","facebook_title":"","facebook_description":"","facebook_image":"","facebook_image_id":"","twitter_title":"","twitter_description":"","twitter_image":"","twitter_image_id":"","twitter_card_type":"","twitter_use_facebook":"","advanced_robots":"","pillar_content":"","seo_score":"75","contentai_score":"","rich_snippet":""},"_links":{"self":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/791881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/comments?post=791881"}],"version-history":[{"count":0,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/posts\/791881\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media\/791882"}],"wp:attachment":[{"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/media?parent=791881"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/categories?post=791881"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dailynewshungary.com\/it\/wp-json\/wp\/v2\/tags?post=791881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}